{"id":100236,"date":"2020-03-06T10:46:00","date_gmt":"2020-03-06T14:46:00","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=100236"},"modified":"2020-03-06T10:46:00","modified_gmt":"2020-03-06T14:46:00","slug":"oms-llama-a-los-gobiernos-usar-todos-los-medios-para-frenar-el-coronavirus","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2020\/03\/06\/oms-llama-a-los-gobiernos-usar-todos-los-medios-para-frenar-el-coronavirus\/","title":{"rendered":"OMS llama a los gobiernos usar todos los medios para frenar el coronavirus"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-100237 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2020\/03\/06_03_2020-HOY_VIERNES_060320_-El-Mundo8-B-553x450.jpg\" alt=\"\" width=\"498\" height=\"405\" \/>El avance mundial del coronavirus provoc\u00f3 un en\u00e9rgico llamado ayer, jueves, por parte de la Organizaci\u00f3n Mundial de la Salud para que los gobiernos recurren a todos los medios posibles para frenar la epidemia, la cual ha obligado a cerrar sitios p\u00fablicos como la Iglesia de la Natividad en Bel\u00e9n y la cancelaci\u00f3n de las festividades por la primavera en la India.<\/p>\n<p>A medida que China, despu\u00e9s de muchas semanas arduas, parec\u00eda estar ganando una batalla \u00e9pica y costosa contra el nuevo virus, la lucha se aceleraba en otras partes del mundo, desencadenando acciones que est\u00e1n impactando profundamente a miles de millones de personas.<\/p>\n<p>\u201cLos pa\u00edses deben prepararse para contagio comunitario sostenido\u201d, dijo el jueves el jefe de la OMS, Tedros Adhanom Ghebreyesus, acerca de la epidemia declarada hace dos meses. \u201cNuestro mensaje a todos los pa\u00edses es: \u00e9sta no es una v\u00eda de sentido \u00fanico. Podemos obligar al virus a retroceder. Estas acciones determinar\u00e1n el curso del brote en cada pa\u00eds\u201d, agreg\u00f3 en su informe diario desde Ginebra.<\/p>\n<p>Se est\u00e1 abriendo una brecha alrededor del mundo. China, donde se origin\u00f3 el brote, informa diariamente sobre la dr\u00e1stica ca\u00edda de las cifras de contagio y la reapertura gradual de f\u00e1bricas mientras aumenta la sensaci\u00f3n de que la normalidad ya no es un hecho distante. Mientras tanto, otros pa\u00edses reportan cifras crecientes de contagio con cancelaciones, clausuras, prohibiciones de viajes y escasez de art\u00edculos. Hay 17 veces m\u00e1s infecciones fuera de China que dentro del pa\u00eds, dijo la OMS, la mayor\u00eda de ellas en Corea del Sur, Italia e Ir\u00e1n.<\/p>\n<p>\u201cEl virus no hace distinciones de raza, credo ni color. Ataca a todos por igual\u201d, dijo Ian MacKay, vir\u00f3logo de la Universidad de Queensland, Australia. \u201cLo que vemos en la pr\u00e1ctica es una pandemia\u201d. Desesperados por impedir la propagaci\u00f3n de la crisis dentro de sus fronteras, los pa\u00edses ajustan las restricciones de desplazamiento. Australia prohibi\u00f3 la entrada de personas de Corea del Sur.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El avance mundial del coronavirus provoc\u00f3 un en\u00e9rgico llamado ayer, jueves, por parte de la Organizaci\u00f3n Mundial de la Salud para que los gobiernos recurren a todos los medios posibles para frenar la epidemia, la cual ha obligado a cerrar sitios p\u00fablicos como la Iglesia de la Natividad en Bel\u00e9n y la cancelaci\u00f3n de las festividades por la primavera en la India. A medida que China, despu\u00e9s de muchas semanas arduas, parec\u00eda estar ganando una batalla \u00e9pica y costosa contra el nuevo virus, la lucha se aceleraba en otras partes del mundo, desencadenando acciones que est\u00e1n impactando profundamente a miles de millones de personas. \u201cLos pa\u00edses deben prepararse para contagio comunitario sostenido\u201d, dijo el jueves el jefe de la OMS, Tedros Adhanom Ghebreyesus, acerca de la epidemia declarada hace dos meses. \u201cNuestro mensaje a todos los pa\u00edses es: \u00e9sta no es una v\u00eda de sentido \u00fanico. Podemos obligar al virus a retroceder. Estas acciones determinar\u00e1n el curso del brote en cada pa\u00eds\u201d, agreg\u00f3 en su informe diario desde Ginebra. Se est\u00e1 abriendo una brecha alrededor del mundo. China, donde se origin\u00f3 el brote, informa diariamente sobre la dr\u00e1stica ca\u00edda de las cifras de contagio y la reapertura gradual de f\u00e1bricas mientras aumenta la sensaci\u00f3n de que la normalidad ya no es un hecho distante. Mientras tanto, otros pa\u00edses reportan cifras crecientes de contagio con cancelaciones, clausuras, prohibiciones de viajes y escasez de art\u00edculos. Hay 17 veces m\u00e1s infecciones fuera de China que dentro del pa\u00eds, dijo la OMS, la mayor\u00eda de ellas en Corea del Sur, Italia e Ir\u00e1n. \u201cEl virus no hace distinciones de raza, credo ni color. Ataca a todos por igual\u201d, dijo Ian MacKay, vir\u00f3logo de la Universidad de Queensland, Australia. \u201cLo que vemos en la pr\u00e1ctica es una pandemia\u201d. Desesperados por impedir la propagaci\u00f3n de la crisis dentro de sus fronteras, los pa\u00edses ajustan las restricciones de desplazamiento. Australia prohibi\u00f3 la entrada de personas de Corea del Sur.<\/p>\n","protected":false},"author":6,"featured_media":100237,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-100236","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/100236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=100236"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/100236\/revisions"}],"predecessor-version":[{"id":100238,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/100236\/revisions\/100238"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/100237"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=100236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=100236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=100236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}