{"id":100406,"date":"2020-03-13T10:41:07","date_gmt":"2020-03-13T14:41:07","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=100406"},"modified":"2020-03-13T10:41:07","modified_gmt":"2020-03-13T14:41:07","slug":"espana-declarara-manana-el-estado-de-alarma-ante-la-extension-del-coronavirus","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2020\/03\/13\/espana-declarara-manana-el-estado-de-alarma-ante-la-extension-del-coronavirus\/","title":{"rendered":"Espa\u00f1a declarar\u00e1 ma\u00f1ana el estado de alarma ante la extensi\u00f3n del coronavirus"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-100407 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2020\/03\/pedro-992x550-800x444.jpg\" alt=\"\" width=\"497\" height=\"276\" \/>MADRID.- El Gobierno espa\u00f1ol declarar\u00e1 ma\u00f1ana el estado de alarma ante la expansi\u00f3n del coronavirus, lo que permitir\u00e1 a las autoridades tomar medidas excepcionales para afrontar la situaci\u00f3n.<\/p>\n<p>\u201cLa emergencia social y sanitaria por el coronavirus crea circunstancias extraordinarias\u201d para dotar al Ejecutivo de \u201cpoderes extraordinarios\u201d, anunci\u00f3 el presidente del Gobierno, Pedro S\u00e1nchez, en una declaraci\u00f3n institucional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MADRID.- El Gobierno espa\u00f1ol declarar\u00e1 ma\u00f1ana el estado de alarma ante la expansi\u00f3n del coronavirus, lo que permitir\u00e1 a las autoridades tomar medidas excepcionales para afrontar la situaci\u00f3n. \u201cLa emergencia social y sanitaria por el coronavirus crea circunstancias extraordinarias\u201d para dotar al Ejecutivo de \u201cpoderes extraordinarios\u201d, anunci\u00f3 el presidente del Gobierno, Pedro S\u00e1nchez, en una declaraci\u00f3n institucional.<\/p>\n","protected":false},"author":6,"featured_media":100407,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-100406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/100406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=100406"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/100406\/revisions"}],"predecessor-version":[{"id":100408,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/100406\/revisions\/100408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/100407"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=100406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=100406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=100406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}