{"id":100755,"date":"2020-03-22T19:36:00","date_gmt":"2020-03-22T23:36:00","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=100755"},"modified":"2020-03-22T19:36:00","modified_gmt":"2020-03-22T23:36:00","slug":"coronavirus-quique-antun-propone-cierre-temporal-de-las-oficinas-publicas","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2020\/03\/22\/coronavirus-quique-antun-propone-cierre-temporal-de-las-oficinas-publicas\/","title":{"rendered":"Coronavirus: Quique Ant\u00fan propone cierre temporal de las oficinas p\u00fablicas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-100756 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2020\/03\/0-81-800x450-800x450.jpg\" alt=\"\" width=\"497\" height=\"280\" \/>SANTO DOMINGO.- El presidente del Partido Reformista Social Cristiano (PRSC) plante\u00f3 este domingo al Gobierno que ante la creciente propagaci\u00f3n del coronavirus en el pa\u00eds, que ya se han confirmado 202 casos de la enfermedad, se disponga el cierre temporal de las oficinas p\u00fablicas, con excepci\u00f3n de las indispensables.<\/p>\n<p>Quique Ant\u00fan explic\u00f3 que para evitar que contin\u00fae la propagaci\u00f3n del COVID-19, se tienen que endurecer las medidas que se han tomado hasta el momento, \u201cporque todos los d\u00edas surgen nuevos casos de la enfermedad y tenemos que seguir haciendo esfuerzos en proteger las vidas de nuestros ciudadanos\u201d.<\/p>\n<p>Entiende que no es suficiente la medida anunciada por el presidente de la Rep\u00fablica, Danilo Medina, de alternar al 50% de los servidores p\u00fablicos cada semana, cuando hay instituciones del Estado que tienen en su n\u00f3mina a cientos de empleados, \u201clo que significa que a pesar de que solo la mitad est\u00e1 asistiendo a su trabajo, se mantienen las aglomeraciones, lo que dispara el riesgo del contagio de la enfermedad\u201d.<\/p>\n<p>\u201cLas medidas tienen que ser m\u00e1s estrictas y el gobierno debe dar el ejemplo\u201d, expres\u00f3 el l\u00edder reformista.<\/p>\n<p>Quique Ant\u00fan dijo que hay instituciones del Estado, como ministerios, direcciones generales y descentralizadas que a esta altura con la cantidad de casos que se han registrado y las muertes de tres personas deber\u00edan estar cerradas \u201cpara evitar m\u00e1s contagios\u201d.<\/p>\n<p>Sostuvo que con esa pandemia, que tiene aterrorizada a la sociedad, \u201cpoca gente est\u00e1 saliendo a hacer diligencias en oficinas p\u00fablicas y privadas\u201d.<\/p>\n<p>Manifest\u00f3 que mientras menos personas est\u00e9n circulando en las calles, m\u00e1s se controla la propagaci\u00f3n del coronavirus.<\/p>\n<p>Insisti\u00f3 que hay que seguir endureciendo las medidas tomadas para proteger a la poblaci\u00f3n.<\/p>\n<p>Pero tambi\u00e9n \u2013agreg\u00f3- se mantenerse una campa\u00f1a permanente por radio, television, redes sociales y telefonos orientando a la poblaci\u00f3n de c\u00f3mo prevenir la propagacion de la enfermedad y como evitar el contagio.<\/p>\n<p>Explic\u00f3 que esa campa\u00f1a de orientaci\u00f3n, que dijo debe mantenerse mientras dure la situaci\u00f3n de la pandemia, tiene que tener mensajes como \u201cQu\u00e9date en casa\u201d, \u201cL\u00e1vate las manos\u201d, \u201cC\u00fabrete la boca y nariz\u201d, entre otros.<\/p>\n<p>\u201cNo hay nada m\u00e1s importante que la salud y la vida. Aquellos dominicanos que ponen en juego la salud de todos deben ser tratados como criminales\u201d, escribi\u00f3 este domingo Quique Ant\u00fan en su cuenta de Twitter.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- El presidente del Partido Reformista Social Cristiano (PRSC) plante\u00f3 este domingo al Gobierno que ante la creciente propagaci\u00f3n del coronavirus en el pa\u00eds, que ya se han confirmado 202 casos de la enfermedad, se disponga el cierre temporal de las oficinas p\u00fablicas, con excepci\u00f3n de las indispensables. Quique Ant\u00fan explic\u00f3 que para evitar que contin\u00fae la propagaci\u00f3n del COVID-19, se tienen que endurecer las medidas que se han tomado hasta el momento, \u201cporque todos los d\u00edas surgen nuevos casos de la enfermedad y tenemos que seguir haciendo esfuerzos en proteger las vidas de nuestros ciudadanos\u201d. Entiende que no es suficiente la medida anunciada por el presidente de la Rep\u00fablica, Danilo Medina, de alternar al 50% de los servidores p\u00fablicos cada semana, cuando hay instituciones del Estado que tienen en su n\u00f3mina a cientos de empleados, \u201clo que significa que a pesar de que solo la mitad est\u00e1 asistiendo a su trabajo, se mantienen las aglomeraciones, lo que dispara el riesgo del contagio de la enfermedad\u201d. \u201cLas medidas tienen que ser m\u00e1s estrictas y el gobierno debe dar el ejemplo\u201d, expres\u00f3 el l\u00edder reformista. Quique Ant\u00fan dijo que hay instituciones del Estado, como ministerios, direcciones generales y descentralizadas que a esta altura con la cantidad de casos que se han registrado y las muertes de tres personas deber\u00edan estar cerradas \u201cpara evitar m\u00e1s contagios\u201d. Sostuvo que con esa pandemia, que tiene aterrorizada a la sociedad, \u201cpoca gente est\u00e1 saliendo a hacer diligencias en oficinas p\u00fablicas y privadas\u201d. Manifest\u00f3 que mientras menos personas est\u00e9n circulando en las calles, m\u00e1s se controla la propagaci\u00f3n del coronavirus. Insisti\u00f3 que hay que seguir endureciendo las medidas tomadas para proteger a la poblaci\u00f3n. Pero tambi\u00e9n \u2013agreg\u00f3- se mantenerse una campa\u00f1a permanente por radio, television, redes sociales y telefonos orientando a la poblaci\u00f3n de c\u00f3mo prevenir la propagacion de la enfermedad y como evitar el contagio. Explic\u00f3 que esa campa\u00f1a de orientaci\u00f3n, que dijo debe mantenerse mientras dure la situaci\u00f3n de la pandemia, tiene que tener mensajes como \u201cQu\u00e9date en casa\u201d, \u201cL\u00e1vate las manos\u201d, \u201cC\u00fabrete la boca y nariz\u201d, entre otros. \u201cNo hay nada m\u00e1s importante que la salud y la vida. Aquellos dominicanos que ponen en juego la salud de todos deben ser tratados como criminales\u201d, escribi\u00f3 este domingo Quique Ant\u00fan en su cuenta de Twitter.<\/p>\n","protected":false},"author":6,"featured_media":100756,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-100755","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/100755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=100755"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/100755\/revisions"}],"predecessor-version":[{"id":100757,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/100755\/revisions\/100757"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/100756"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=100755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=100755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=100755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}