{"id":100906,"date":"2020-03-26T20:07:20","date_gmt":"2020-03-27T00:07:20","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=100906"},"modified":"2020-03-26T20:07:20","modified_gmt":"2020-03-27T00:07:20","slug":"unos-simpaticos-munecos-de-covid-19-la-original-idea-de-la-policia-boliviana","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2020\/03\/26\/unos-simpaticos-munecos-de-covid-19-la-original-idea-de-la-policia-boliviana\/","title":{"rendered":"Unos simp\u00e1ticos mu\u00f1ecos de COVID-19, la original idea de la Polic\u00eda Boliviana"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-100907 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2020\/03\/095b6f11-etzlvlcwkam-wpq-800x571.jpg\" alt=\"\" width=\"496\" height=\"354\" \/>LA PAZ.-\u00a0Uno es amarillo fosforescente y el otro morado, ambos tienen sonrisas mal\u00e9volas y, aunque representan al temible coronavirus que ha puesto al mundo en crisis, su misi\u00f3n es ayudar a la Polic\u00eda Boliviana en las calles creando consciencia sobre los cuidados que se deben tener para evitar la transmisi\u00f3n.<\/p>\n<p>\u201cHola, hola amigo, soy el coronavirus\u201d, anuncian animados estos virus de tama\u00f1o humano al acercarse a los transe\u00fantes en lugares que mantienen una alta concurrencia, como los mercados callejeros de La Paz, a pesar de las restricciones dispuestas por el Gobierno interino de Bolivia.<\/p>\n<p>Algunos se asustan, otros se r\u00eden y no faltan quienes se hacen selfies con estas alegres botargas, unos mu\u00f1ecos que son iniciativa de la Direcci\u00f3n Nacional de Tr\u00e1nsito de Bolivia para concienciar a la gente sobre los peligros del COVID-19 y las medidas preventivas, como el uso de mascarillas y guantes desechables.<\/p>\n<p>MU\u00d1ECOS SORPRESA EN MERCADOS PACE\u00d1OS<\/p>\n<p>El primer lugar visitado este jueves fue el populoso mercado Rodr\u00edguez, uno de los m\u00e1s grandes y tradicionales en el oeste de La Paz, donde de ma\u00f1ana la normalidad casi se impone, salvo por algunas personas que llevan mascarillas para vender o hacer las compras.<\/p>\n<p>\u201c\u00a1Soy el virus!\u201d, \u201cmantengan distancia\u201d, \u201cvayan a sus casas\u201d, arengan las botargas, arrancando sonrisas, elogios y alg\u00fan ocasional enojo a su paso por este mercado.<\/p>\n<p>\u201cQu\u00e9 buena onda\u201d, dice un comprador al verlos, mientras un polic\u00eda llama \u201cvirus\u201d a su compa\u00f1ero disfrazado para que se acerque a unas vendedoras.<\/p>\n<p>Tambi\u00e9n cuestionan jocosamente a quienes salieron de casa con sus ni\u00f1os o las parejas de enamorados que andan de la mano pese a las recomendaciones de mantener distancia.<\/p>\n<p>Con ellos va un agente que insta a la gente a recordar que solamente puede salir una persona por familia a hacer las compras y que a partir del mediod\u00eda todos deben estar de vuelta en sus casas<\/p>\n<p>El grupo se traslada luego a otro mercado que est\u00e1 unas calles m\u00e1s arriba, sobre la tambi\u00e9n populosa avenida Buenos Aires, donde se repite la historia.<\/p>\n<p>Los m\u00e1s j\u00f3venes no dudan en acercarse a estos virus para hacerse unas fotograf\u00edas juntos, mientras que otros transe\u00fantes los filman de pasada y algunos m\u00e1s aprovechan para despejar algunas dudas sobre la cuarentena con el agente que lleva el meg\u00e1fono.<\/p>\n<p>LA ORIGINAL IDEA DE LA POLIC\u00cdA BOLIVIANA<\/p>\n<p>\u201cLa Polic\u00eda Boliviana hace todos los esfuerzos para poder concienciar a la ciudadan\u00eda habida cuenta de que hay en alguno que otro sector personas que hacen caso omiso al decreto supremo\u201d que dict\u00f3 la cuarentena, explic\u00f3 este jueves a Efe el director nacional de Tr\u00e1nsito, el coronel Walter Miranda.<\/p>\n<p>Por ello decidieron hacer estos mu\u00f1ecos del COVID-19, con esa forma redonda con antenas con la que se asocia el virus, para que a diario vayan a mercados y calles concurridas, acompa\u00f1ados por un agente que, meg\u00e1fono en mano, lanza consignas explicando a la gente sobre las medidas para evitar la propagaci\u00f3n del virus, empezando por quedarse en casa.<\/p>\n<p>La iniciativa se realiza tambi\u00e9n en otras ciudades bolivianas, como Cochabamba, con el fin de \u201cconmover y concienciar a la gente\u201d, indic\u00f3 Miranda.<\/p>\n<p>\u201cEn algunos sectores s\u00ed ven que esta situaci\u00f3n que nos est\u00e1 afectando a nivel mundial es una preocupaci\u00f3n y nos felicitan y dicen que van a hacer consciencia (\u2026). Tenemos que hacer todo lo posible haciendo los esfuerzos para poder educar a la gente que no entiende\u201d, dijo el oficial.<\/p>\n<p>M\u00c1S INICIATIVAS CONTRA EL COVID-19<\/p>\n<p>La Polic\u00eda Boliviana trabaja con otras iniciativas para llegar a la ciudadan\u00eda, con spots en video y panfletos informativos para que aquellos \u201cmalos ciudadanos que no hacen caso a la disposici\u00f3n puedan comprender\u201d las restricciones vigentes, explic\u00f3 el coronel Miranda.<\/p>\n<p>El oficial remarc\u00f3 que los agentes tambi\u00e9n son seres humanos y, como todos, necesitan ponerse \u201ca buen recaudo\u201d.<\/p>\n<p>\u201cPor eso pedimos que todos se queden en casa y nuestras v\u00edas durante esta cuarentena est\u00e9n expeditas y vac\u00edas, as\u00ed nosotros vamos a disminuir el n\u00famero de efectivos que tenemos en la calle\u201d, concluy\u00f3.<\/p>\n<p>Bolivia, que reporta 42 casos confirmados de COVID-19 en cuatro de sus nueve regiones, est\u00e1 en estado de emergencia sanitaria desde este jueves, con medidas de cuarentena m\u00e1s severas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LA PAZ.-\u00a0Uno es amarillo fosforescente y el otro morado, ambos tienen sonrisas mal\u00e9volas y, aunque representan al temible coronavirus que ha puesto al mundo en crisis, su misi\u00f3n es ayudar a la Polic\u00eda Boliviana en las calles creando consciencia sobre los cuidados que se deben tener para evitar la transmisi\u00f3n. \u201cHola, hola amigo, soy el coronavirus\u201d, anuncian animados estos virus de tama\u00f1o humano al acercarse a los transe\u00fantes en lugares que mantienen una alta concurrencia, como los mercados callejeros de La Paz, a pesar de las restricciones dispuestas por el Gobierno interino de Bolivia. Algunos se asustan, otros se r\u00eden y no faltan quienes se hacen selfies con estas alegres botargas, unos mu\u00f1ecos que son iniciativa de la Direcci\u00f3n Nacional de Tr\u00e1nsito de Bolivia para concienciar a la gente sobre los peligros del COVID-19 y las medidas preventivas, como el uso de mascarillas y guantes desechables. MU\u00d1ECOS SORPRESA EN MERCADOS PACE\u00d1OS El primer lugar visitado este jueves fue el populoso mercado Rodr\u00edguez, uno de los m\u00e1s grandes y tradicionales en el oeste de La Paz, donde de ma\u00f1ana la normalidad casi se impone, salvo por algunas personas que llevan mascarillas para vender o hacer las compras. \u201c\u00a1Soy el virus!\u201d, \u201cmantengan distancia\u201d, \u201cvayan a sus casas\u201d, arengan las botargas, arrancando sonrisas, elogios y alg\u00fan ocasional enojo a su paso por este mercado. \u201cQu\u00e9 buena onda\u201d, dice un comprador al verlos, mientras un polic\u00eda llama \u201cvirus\u201d a su compa\u00f1ero disfrazado para que se acerque a unas vendedoras. Tambi\u00e9n cuestionan jocosamente a quienes salieron de casa con sus ni\u00f1os o las parejas de enamorados que andan de la mano pese a las recomendaciones de mantener distancia. Con ellos va un agente que insta a la gente a recordar que solamente puede salir una persona por familia a hacer las compras y que a partir del mediod\u00eda todos deben estar de vuelta en sus casas El grupo se traslada luego a otro mercado que est\u00e1 unas calles m\u00e1s arriba, sobre la tambi\u00e9n populosa avenida Buenos Aires, donde se repite la historia. Los m\u00e1s j\u00f3venes no dudan en acercarse a estos virus para hacerse unas fotograf\u00edas juntos, mientras que otros transe\u00fantes los filman de pasada y algunos m\u00e1s aprovechan para despejar algunas dudas sobre la cuarentena con el agente que lleva el meg\u00e1fono. LA ORIGINAL IDEA DE LA POLIC\u00cdA BOLIVIANA \u201cLa Polic\u00eda Boliviana hace todos los esfuerzos para poder concienciar a la ciudadan\u00eda habida cuenta de que hay en alguno que otro sector personas que hacen caso omiso al decreto supremo\u201d que dict\u00f3 la cuarentena, explic\u00f3 este jueves a Efe el director nacional de Tr\u00e1nsito, el coronel Walter Miranda. Por ello decidieron hacer estos mu\u00f1ecos del COVID-19, con esa forma redonda con antenas con la que se asocia el virus, para que a diario vayan a mercados y calles concurridas, acompa\u00f1ados por un agente que, meg\u00e1fono en mano, lanza consignas explicando a la gente sobre las medidas para evitar la propagaci\u00f3n del virus, empezando por quedarse en casa. La iniciativa se realiza tambi\u00e9n en otras ciudades bolivianas, como Cochabamba, con el fin de \u201cconmover y concienciar a la gente\u201d, indic\u00f3 Miranda. \u201cEn algunos sectores s\u00ed ven que esta situaci\u00f3n que nos est\u00e1 afectando a nivel mundial es una preocupaci\u00f3n y nos felicitan y dicen que van a hacer consciencia (\u2026). Tenemos que hacer todo lo posible haciendo los esfuerzos para poder educar a la gente que no entiende\u201d, dijo el oficial. M\u00c1S INICIATIVAS CONTRA EL COVID-19 La Polic\u00eda Boliviana trabaja con otras iniciativas para llegar a la ciudadan\u00eda, con spots en video y panfletos informativos para que aquellos \u201cmalos ciudadanos que no hacen caso a la disposici\u00f3n puedan comprender\u201d las restricciones vigentes, explic\u00f3 el coronel Miranda. El oficial remarc\u00f3 que los agentes tambi\u00e9n son seres humanos y, como todos, necesitan ponerse \u201ca buen recaudo\u201d. \u201cPor eso pedimos que todos se queden en casa y nuestras v\u00edas durante esta cuarentena est\u00e9n expeditas y vac\u00edas, as\u00ed nosotros vamos a disminuir el n\u00famero de efectivos que tenemos en la calle\u201d, concluy\u00f3. Bolivia, que reporta 42 casos confirmados de COVID-19 en cuatro de sus nueve regiones, est\u00e1 en estado de emergencia sanitaria desde este jueves, con medidas de cuarentena m\u00e1s severas.<\/p>\n","protected":false},"author":6,"featured_media":100907,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-100906","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/100906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=100906"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/100906\/revisions"}],"predecessor-version":[{"id":100908,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/100906\/revisions\/100908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/100907"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=100906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=100906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=100906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}