{"id":101155,"date":"2020-04-03T09:45:19","date_gmt":"2020-04-03T13:45:19","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=101155"},"modified":"2020-04-03T09:45:19","modified_gmt":"2020-04-03T13:45:19","slug":"minerd-e-inabie-completan-con-exito-segunda-etapa-entrega-kits-alimenticios","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2020\/04\/03\/minerd-e-inabie-completan-con-exito-segunda-etapa-entrega-kits-alimenticios\/","title":{"rendered":"MINERD e INABIE completan con \u00e9xito segunda etapa entrega kits alimenticios"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-101156 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2020\/04\/FOTO-SEGUNDA-ENTREGA-800x450-800x450.jpg\" alt=\"\" width=\"498\" height=\"280\" \/>SANTO DOMINGO.- El Ministerio de Educaci\u00f3n (MINERD), inform\u00f3 que el Instituto Nacional de Bienestar Estudiantil (INABIE), culmin\u00f3 este jueves con \u00e9xito la segunda etapa de entrega de kits alimenticios a los padres, madres y tutores de los estudiantes que est\u00e1n en la modalidad de Jornada Escolar Extendida (JEE).<\/p>\n<p>A trav\u00e9s de una nota de prensa, la instituci\u00f3n record\u00f3 que la modalidad de entrega de alimentos crudos en las escuelas de la modalidad de Jornada Escolar Extendida se implement\u00f3 para prevenir la propagaci\u00f3n del Covid-19.<\/p>\n<p>Inform\u00f3, adem\u00e1s, que desde el INABIE se adoptan las medidas de lugar para completar la distribuci\u00f3n en algunos centros educativos, donde los suplidores no pudieron cumplir la encomienda establecida debido a dificultades individuales.<\/p>\n<p>Explic\u00f3 que el reporte preliminar indica que la entrega de alimentos se materializ\u00f3 de manera efectiva en m\u00e1s de 3 mil 160 centros educativos, lo cual ha permitido garantizar alimentaci\u00f3n a la comunidad educativa que integra la JEE.<\/p>\n<p>El MINERD destac\u00f3 que el \u00e9xito en el proceso de entrega de alimentos que lleva ya dos semanas, ha estado sustentado en la disciplina y vocaci\u00f3n de servicio de directores de centros, docentes, personal administrativo, Polic\u00eda Escolar y voluntarios.<\/p>\n<p>Dijo que el proceso ha sido desarrollado conforme al calendario y la coordinaci\u00f3n realizada por el INABIE con los directores de centros, cumpliendo con todos los protocolos establecidos para entregar alimentos crudos a padres, madres y tutores de los estudiantes.<\/p>\n<p>En ese sentido, el director del INABIE, Ren\u00e9 J\u00e1quez Gil, resalt\u00f3 el orden, la organizaci\u00f3n y el civismo mostrado por todos los involucrados en la jornada. \u201cEn estos dos d\u00edas de la segunda etapa de entrega de kits de alimentos y en la primera etapa el proceso se desarroll\u00f3 de manera exitosa\u201d, afirm\u00f3 el funcionario.<\/p>\n<p>La instituci\u00f3n reiter\u00f3 que esta semana se ha entregado dos kits alimenticios a cada padre, madre o tutor que retiran los suministros en representaci\u00f3n de los estudiantes, con la finalidad de proporcionar comida para dos semanas y compensar las raciones cocidas que se entrega diariamente de forma ordinaria en los centros p\u00fablicos, como una medida de optimizar la seguridad alimentaria y nutricional de los educandos y as\u00ed evitar la exposici\u00f3n de las familias al salir de las casas.<\/p>\n<p>El Ministerio de Educaci\u00f3n indic\u00f3 que de esa manera se contribuye a disminuir los riesgos de contagio y propagaci\u00f3n del Coronavirus en los actores del sistema educativo.<\/p>\n<p>Desayuno y merienda<\/p>\n<p>El MINERD inform\u00f3, adem\u00e1s, que se ha entregado leche y jugos en los centros educativos donde tradicionalmente se sirve desayuno escolar y merienda a los estudiantes.<\/p>\n<p>Tal fue el caso del Centro de Educativo Celina Pellier, del sector Los Mameyes, Santo Domingo Este, donde se entreg\u00f3 a cada estudiante, a trav\u00e9s de sus padres, madres o tutores leche y jugo equivalentes a una semana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- El Ministerio de Educaci\u00f3n (MINERD), inform\u00f3 que el Instituto Nacional de Bienestar Estudiantil (INABIE), culmin\u00f3 este jueves con \u00e9xito la segunda etapa de entrega de kits alimenticios a los padres, madres y tutores de los estudiantes que est\u00e1n en la modalidad de Jornada Escolar Extendida (JEE). A trav\u00e9s de una nota de prensa, la instituci\u00f3n record\u00f3 que la modalidad de entrega de alimentos crudos en las escuelas de la modalidad de Jornada Escolar Extendida se implement\u00f3 para prevenir la propagaci\u00f3n del Covid-19. Inform\u00f3, adem\u00e1s, que desde el INABIE se adoptan las medidas de lugar para completar la distribuci\u00f3n en algunos centros educativos, donde los suplidores no pudieron cumplir la encomienda establecida debido a dificultades individuales. Explic\u00f3 que el reporte preliminar indica que la entrega de alimentos se materializ\u00f3 de manera efectiva en m\u00e1s de 3 mil 160 centros educativos, lo cual ha permitido garantizar alimentaci\u00f3n a la comunidad educativa que integra la JEE. El MINERD destac\u00f3 que el \u00e9xito en el proceso de entrega de alimentos que lleva ya dos semanas, ha estado sustentado en la disciplina y vocaci\u00f3n de servicio de directores de centros, docentes, personal administrativo, Polic\u00eda Escolar y voluntarios. Dijo que el proceso ha sido desarrollado conforme al calendario y la coordinaci\u00f3n realizada por el INABIE con los directores de centros, cumpliendo con todos los protocolos establecidos para entregar alimentos crudos a padres, madres y tutores de los estudiantes. En ese sentido, el director del INABIE, Ren\u00e9 J\u00e1quez Gil, resalt\u00f3 el orden, la organizaci\u00f3n y el civismo mostrado por todos los involucrados en la jornada. \u201cEn estos dos d\u00edas de la segunda etapa de entrega de kits de alimentos y en la primera etapa el proceso se desarroll\u00f3 de manera exitosa\u201d, afirm\u00f3 el funcionario. La instituci\u00f3n reiter\u00f3 que esta semana se ha entregado dos kits alimenticios a cada padre, madre o tutor que retiran los suministros en representaci\u00f3n de los estudiantes, con la finalidad de proporcionar comida para dos semanas y compensar las raciones cocidas que se entrega diariamente de forma ordinaria en los centros p\u00fablicos, como una medida de optimizar la seguridad alimentaria y nutricional de los educandos y as\u00ed evitar la exposici\u00f3n de las familias al salir de las casas. El Ministerio de Educaci\u00f3n indic\u00f3 que de esa manera se contribuye a disminuir los riesgos de contagio y propagaci\u00f3n del Coronavirus en los actores del sistema educativo. Desayuno y merienda El MINERD inform\u00f3, adem\u00e1s, que se ha entregado leche y jugos en los centros educativos donde tradicionalmente se sirve desayuno escolar y merienda a los estudiantes. Tal fue el caso del Centro de Educativo Celina Pellier, del sector Los Mameyes, Santo Domingo Este, donde se entreg\u00f3 a cada estudiante, a trav\u00e9s de sus padres, madres o tutores leche y jugo equivalentes a una semana.<\/p>\n","protected":false},"author":6,"featured_media":101156,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-101155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/101155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=101155"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/101155\/revisions"}],"predecessor-version":[{"id":101157,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/101155\/revisions\/101157"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/101156"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=101155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=101155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=101155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}