{"id":101273,"date":"2020-04-14T10:50:26","date_gmt":"2020-04-14T14:50:26","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=101273"},"modified":"2020-04-14T10:51:54","modified_gmt":"2020-04-14T14:51:54","slug":"covid-19-ee-uu-aprueba-test-de-saliva-para-diagnosticar-el-virus","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2020\/04\/14\/covid-19-ee-uu-aprueba-test-de-saliva-para-diagnosticar-el-virus\/","title":{"rendered":"COVID-19: EE. UU. aprueba test de saliva para diagnosticar el virus"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-101275 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2020\/04\/TEST-COVID-19-800x450-1-800x450.jpeg\" alt=\"\" width=\"492\" height=\"277\" \/>WASHINGTON.\u2014 Investigadores de la Universidad Rutgers recibieron luz verde del gobierno de Estados Unidos para los primeros test de saliva que ayuden a diagnosticar el COVID-19, la enfermedad causada por el coronavirus, un nuevo enfoque que podr\u00eda ayudar a ampliar las opciones de prueba y reducir el riesgo de infecci\u00f3n en los trabajadores de salud.<\/p>\n<p>La Administraci\u00f3n de Alimentos y Medicamentos autoriz\u00f3 el test bajo sus poderes de emergencia para aprobar r\u00e1pidamente nuevas pruebas y terapias para combatir el brote, dijo la universidad de Nueva Jersey el lunes. En un primer momento, el m\u00e9todo estar\u00e1 disponible en hospitales y cl\u00ednicas afiliadas a la escuela. El anuncio se produjo en un momento en el que muchas comunidades de todo el pa\u00eds siguen teniendo problemas para localizar y contener el coronavirus.<\/p>\n<p>El sistema actual para la detecci\u00f3n del COVID-19 requiere que el sanitario extraiga una muestra de la nariz o garganta del paciente. Para reducir el riesgo de infecci\u00f3n, muchos hospitales y cl\u00ednicas piden a su personal que tiren los guantes y mascarillas luego de estar cerca de un infectado o una persona que pueda haber contra\u00eddo el virus. Y muchas instituciones tienen escasez de suministros b\u00e1sicos como guantes, mascarillas e hisopos.<\/p>\n<p>Con la nueva prueba de saliva, los pacientes reciben un tubo de pl\u00e1stico en el que deben escupir varias veces. Despu\u00e9s devuelven el tubo al trabajador sanitario para su procesamiento en un laboratorio.<\/p>\n<p>\u201cEsto evita que los profesionales de la salud tengan que enfrentarse a alguien asintom\u00e1tico\u201d, se\u00f1al\u00f3 Andrew Brooks, director del\u00a0laboratorio de Rutgers\u00a0que desarroll\u00f3 el test.<\/p>\n<p>Un experto en enfermedades infecciosas que no particip\u00f3 en la nueva prueba, apunt\u00f3 que ayudar\u00eda a superar las molestias y dificultades que supone para el paciente el tomar una muestra con hisopos.<\/p>\n<p>Rutgers prob\u00f3 la precisi\u00f3n de su m\u00e9todo tomando muestras de saliva e hisopos a 60 pacientes. En el 100% de los casos, ambos resultados coincidieron.<\/p>\n<p>La Universidad desarroll\u00f3 el m\u00e9todo con kits de recolecci\u00f3n de saliva de\u00a0Spectrum Solutions, una empresa de Utah que proporciona dispositivos similares para pruebas de ascendencia basadas en ADN. El laboratorio de Rutgers puede procesar 10.000 muestras al d\u00eda, apunt\u00f3 Brooks.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>WASHINGTON.\u2014 Investigadores de la Universidad Rutgers recibieron luz verde del gobierno de Estados Unidos para los primeros test de saliva que ayuden a diagnosticar el COVID-19, la enfermedad causada por el coronavirus, un nuevo enfoque que podr\u00eda ayudar a ampliar las opciones de prueba y reducir el riesgo de infecci\u00f3n en los trabajadores de salud. La Administraci\u00f3n de Alimentos y Medicamentos autoriz\u00f3 el test bajo sus poderes de emergencia para aprobar r\u00e1pidamente nuevas pruebas y terapias para combatir el brote, dijo la universidad de Nueva Jersey el lunes. En un primer momento, el m\u00e9todo estar\u00e1 disponible en hospitales y cl\u00ednicas afiliadas a la escuela. El anuncio se produjo en un momento en el que muchas comunidades de todo el pa\u00eds siguen teniendo problemas para localizar y contener el coronavirus. El sistema actual para la detecci\u00f3n del COVID-19 requiere que el sanitario extraiga una muestra de la nariz o garganta del paciente. Para reducir el riesgo de infecci\u00f3n, muchos hospitales y cl\u00ednicas piden a su personal que tiren los guantes y mascarillas luego de estar cerca de un infectado o una persona que pueda haber contra\u00eddo el virus. Y muchas instituciones tienen escasez de suministros b\u00e1sicos como guantes, mascarillas e hisopos. Con la nueva prueba de saliva, los pacientes reciben un tubo de pl\u00e1stico en el que deben escupir varias veces. Despu\u00e9s devuelven el tubo al trabajador sanitario para su procesamiento en un laboratorio. \u201cEsto evita que los profesionales de la salud tengan que enfrentarse a alguien asintom\u00e1tico\u201d, se\u00f1al\u00f3 Andrew Brooks, director del\u00a0laboratorio de Rutgers\u00a0que desarroll\u00f3 el test. Un experto en enfermedades infecciosas que no particip\u00f3 en la nueva prueba, apunt\u00f3 que ayudar\u00eda a superar las molestias y dificultades que supone para el paciente el tomar una muestra con hisopos. Rutgers prob\u00f3 la precisi\u00f3n de su m\u00e9todo tomando muestras de saliva e hisopos a 60 pacientes. En el 100% de los casos, ambos resultados coincidieron. La Universidad desarroll\u00f3 el m\u00e9todo con kits de recolecci\u00f3n de saliva de\u00a0Spectrum Solutions, una empresa de Utah que proporciona dispositivos similares para pruebas de ascendencia basadas en ADN. El laboratorio de Rutgers puede procesar 10.000 muestras al d\u00eda, apunt\u00f3 Brooks.<\/p>\n","protected":false},"author":6,"featured_media":101274,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-101273","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/101273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=101273"}],"version-history":[{"count":2,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/101273\/revisions"}],"predecessor-version":[{"id":101277,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/101273\/revisions\/101277"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/101274"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=101273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=101273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=101273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}