{"id":102607,"date":"2020-06-30T19:06:25","date_gmt":"2020-06-30T23:06:25","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=102607"},"modified":"2020-06-30T19:06:25","modified_gmt":"2020-06-30T23:06:25","slug":"intrant-extiende-vigencia-licencias-de-conducir-y-carnes-de-aprendizaje-hasta-el-primero-de-agosto","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2020\/06\/30\/intrant-extiende-vigencia-licencias-de-conducir-y-carnes-de-aprendizaje-hasta-el-primero-de-agosto\/","title":{"rendered":"INTRANT extiende vigencia \u00a0licencias de conducir y carn\u00e9s de aprendizaje hasta el primero \u00a0de agosto"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-102608 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2020\/06\/thumbnail_937A7262-800x533.jpg\" alt=\"\" width=\"171\" height=\"113\" \/>Santo Domingo, 30 junio 2020.-El Instituto Nacional de Tr\u00e1nsito y Transporte Terrestre (INTRANT), inform\u00f3 este martes sobre la \u00a0extensi\u00f3n de vigencia de las \u00a0licencias de conducir y carn\u00e9s de aprendizaje hasta el primero \u00a0de agosto del a\u00f1o en curso.<\/p>\n<p>La medida beneficia a las personas cuya fecha de vencimiento est\u00e9 comprendida entre el 19 de marzo y el 1ro. de agosto del presente a\u00f1o, por lo que, se trabaja en la coordinaci\u00f3n de estas acciones con la Direcci\u00f3n General de Seguridad de Tr\u00e1nsito y Transporte Terrestre (DIGESETT).<\/p>\n<p>La Direcci\u00f3n de Comunicaciones del organismo, explic\u00f3 mediante nota de prensa que todos los servicios de la Direcci\u00f3n de Licencias de Conducir se encuentran reanudados exclusivamente con cita previa a trav\u00e9s del portal institucional\u00a0www.intrant.gob.do, para de esa manera contribuir con las reglas de distanciamiento social y medidas de prevenci\u00f3n adoptadas por el Gobierno dominicano frente al Covid-19.<\/p>\n<p>En ese sentido, INTRANT certifica del mismo modo la extensi\u00f3n de vigencia de las Licencias de Conducir de los dominicanos residentes en el extranjero conforme a los plazos establecidos en el art\u00edculo segundo de la resoluci\u00f3n 004-2020, por consiguiente, las disposiciones de este art\u00edculo certifican la extensi\u00f3n de vigencia de dichas licencias. Ok<\/p>\n<p>Servicios en l\u00ednea<\/p>\n<p>En su comunicado el INTRANT explic\u00f3 que se mantienen los servicios no presenciales a trav\u00e9s de su chat en l\u00ednea disponible en la p\u00e1gina web\u00a0intrant.gob.do\u00a0para responder dudas, recibir denuncias y\/o sugerencias sobre los servicios que ofrece, de lunes a viernes en horario de 8:00 a.m. a 4:00 p.m.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo, 30 junio 2020.-El Instituto Nacional de Tr\u00e1nsito y Transporte Terrestre (INTRANT), inform\u00f3 este martes sobre la \u00a0extensi\u00f3n de vigencia de las \u00a0licencias de conducir y carn\u00e9s de aprendizaje hasta el primero \u00a0de agosto del a\u00f1o en curso. La medida beneficia a las personas cuya fecha de vencimiento est\u00e9 comprendida entre el 19 de marzo y el 1ro. de agosto del presente a\u00f1o, por lo que, se trabaja en la coordinaci\u00f3n de estas acciones con la Direcci\u00f3n General de Seguridad de Tr\u00e1nsito y Transporte Terrestre (DIGESETT). La Direcci\u00f3n de Comunicaciones del organismo, explic\u00f3 mediante nota de prensa que todos los servicios de la Direcci\u00f3n de Licencias de Conducir se encuentran reanudados exclusivamente con cita previa a trav\u00e9s del portal institucional\u00a0www.intrant.gob.do, para de esa manera contribuir con las reglas de distanciamiento social y medidas de prevenci\u00f3n adoptadas por el Gobierno dominicano frente al Covid-19. En ese sentido, INTRANT certifica del mismo modo la extensi\u00f3n de vigencia de las Licencias de Conducir de los dominicanos residentes en el extranjero conforme a los plazos establecidos en el art\u00edculo segundo de la resoluci\u00f3n 004-2020, por consiguiente, las disposiciones de este art\u00edculo certifican la extensi\u00f3n de vigencia de dichas licencias. Ok Servicios en l\u00ednea En su comunicado el INTRANT explic\u00f3 que se mantienen los servicios no presenciales a trav\u00e9s de su chat en l\u00ednea disponible en la p\u00e1gina web\u00a0intrant.gob.do\u00a0para responder dudas, recibir denuncias y\/o sugerencias sobre los servicios que ofrece, de lunes a viernes en horario de 8:00 a.m. a 4:00 p.m. &nbsp;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-102607","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/102607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=102607"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/102607\/revisions"}],"predecessor-version":[{"id":102609,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/102607\/revisions\/102609"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=102607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=102607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=102607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}