{"id":103650,"date":"2020-07-23T19:04:07","date_gmt":"2020-07-23T23:04:07","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=103650"},"modified":"2020-07-23T19:04:07","modified_gmt":"2020-07-23T23:04:07","slug":"comite-de-mitigacion-en-sdo-debate-medidas-para-enfrentar-tormenta-gonzalo","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2020\/07\/23\/comite-de-mitigacion-en-sdo-debate-medidas-para-enfrentar-tormenta-gonzalo\/","title":{"rendered":"Comit\u00e9 de Mitigaci\u00f3n en SDO debate medidas para enfrentar tormenta Gonzalo"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-103651 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2020\/07\/6bfe28d0-whatsapp-image-2020-07-23-at-13.19.29-800x580.jpg\" alt=\"\" width=\"160\" height=\"116\" \/>REP\u00daBLICA DOMINICANA.- El Comit\u00e9 Municipal de Prevenci\u00f3n, Mitigaci\u00f3n y Respuesta de Santo Domingo Oeste sostuvo hoy una reuni\u00f3n de emergencia para tratar los efectos de la pandemia del covid-19 en el municipio y la amenaza de la tormenta Gonzalo.<\/p>\n<p>El director municipal de la Defensa Civil, Ariel Cuevas, detall\u00f3 las medidas de seguridad que est\u00e1n tomando las autoridades en el municipio de Santo Domingo Oeste para prevenir incidentes con la llegada de la tormenta Gonzalo que en horas de la tarde se convertir\u00eda en hurac\u00e1n.<\/p>\n<p>\u201cLo que queremos es prevenir y por eso nos reunimos antes de que llegue el mal, estamos a tiempo, y en conjunto con todas las autoridades presentes vamos a estudiar las propuestas para luego orientas a los mun\u00edcipes\u201d, indic\u00f3 Cuevas.<\/p>\n<p>El Comit\u00e9 Municipal de Prevenci\u00f3n, Mitigaci\u00f3n y Respuesta de Santo Domingo\u00a0\u00a0 Oeste tambi\u00e9n abord\u00f3 los efectos del coronavirus en esa demarcaci\u00f3n y coordinaron los pasos que dar\u00e1n en los pr\u00f3ximos d\u00edas para combatir el virus.<\/p>\n<p>El director del hospital Marcelino V\u00e9lez Santana, Frank Soto, resalt\u00f3 que en el centro de salud se atender\u00e1n pacientes exclusivamente de covid-19, y para las emergencias se colocar\u00e1n caspas en el parqueo para evitar los contagios de la enfermedad.<\/p>\n<p>\u201cEn el hospital estamos tratando de prevenir los contagios y no es prudente atender en el mismo hospital personas contagiadas con las enfermedad con aquellos que no lo est\u00e1n, por esto los referimos a otros centros\u201d, dijo Soto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REP\u00daBLICA DOMINICANA.- El Comit\u00e9 Municipal de Prevenci\u00f3n, Mitigaci\u00f3n y Respuesta de Santo Domingo Oeste sostuvo hoy una reuni\u00f3n de emergencia para tratar los efectos de la pandemia del covid-19 en el municipio y la amenaza de la tormenta Gonzalo. El director municipal de la Defensa Civil, Ariel Cuevas, detall\u00f3 las medidas de seguridad que est\u00e1n tomando las autoridades en el municipio de Santo Domingo Oeste para prevenir incidentes con la llegada de la tormenta Gonzalo que en horas de la tarde se convertir\u00eda en hurac\u00e1n. \u201cLo que queremos es prevenir y por eso nos reunimos antes de que llegue el mal, estamos a tiempo, y en conjunto con todas las autoridades presentes vamos a estudiar las propuestas para luego orientas a los mun\u00edcipes\u201d, indic\u00f3 Cuevas. El Comit\u00e9 Municipal de Prevenci\u00f3n, Mitigaci\u00f3n y Respuesta de Santo Domingo\u00a0\u00a0 Oeste tambi\u00e9n abord\u00f3 los efectos del coronavirus en esa demarcaci\u00f3n y coordinaron los pasos que dar\u00e1n en los pr\u00f3ximos d\u00edas para combatir el virus. El director del hospital Marcelino V\u00e9lez Santana, Frank Soto, resalt\u00f3 que en el centro de salud se atender\u00e1n pacientes exclusivamente de covid-19, y para las emergencias se colocar\u00e1n caspas en el parqueo para evitar los contagios de la enfermedad. \u201cEn el hospital estamos tratando de prevenir los contagios y no es prudente atender en el mismo hospital personas contagiadas con las enfermedad con aquellos que no lo est\u00e1n, por esto los referimos a otros centros\u201d, dijo Soto.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-103650","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/103650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=103650"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/103650\/revisions"}],"predecessor-version":[{"id":103652,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/103650\/revisions\/103652"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=103650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=103650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=103650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}