{"id":106014,"date":"2020-08-18T11:34:13","date_gmt":"2020-08-18T15:34:13","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=106014"},"modified":"2020-08-18T11:34:13","modified_gmt":"2020-08-18T15:34:13","slug":"juan-rosa-asume-en-direccion-general-de-jubilaciones-y-pensiones-a-cargo-del-estado","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2020\/08\/18\/juan-rosa-asume-en-direccion-general-de-jubilaciones-y-pensiones-a-cargo-del-estado\/","title":{"rendered":"Juan Rosa asume en Direcci\u00f3n General de Jubilaciones y Pensiones a Cargo del Estado."},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-106015 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2020\/08\/Juan-Rosa-1024x550-800x430.jpeg\" alt=\"\" width=\"491\" height=\"264\" \/>SANTO DOMINGO.- El nuevo Director General de Jubilaciones y Pensiones a Cargo del Estado (DGJP), Lic. Juan Rosa, tom\u00f3 posesi\u00f3n del cargo este martes en una ceremonia realizada en el sal\u00f3n de reuniones de la instituci\u00f3n.<\/p>\n<p>Juan Rosa fue designado como director general de la DGJP mediante el art\u00edculo 31 del decreto 339-20 emitido por el presidente Luis Abinader Corona.<\/p>\n<p>Al ser posicionado, Rosa declar\u00f3 que llega a la instituci\u00f3n \u201ccon un compromiso que espera desarrollarlo con eficiencia, con compromiso social y con transparencia, tal y como se lo prometimos al presidente Luis Abinader en la noche de la juramentaci\u00f3n\u201d.<\/p>\n<p>El nuevo funcionario insisti\u00f3 en que su mayor compromiso es con el pa\u00eds, con la transparencia y con la calidad en el servicio.<\/p>\n<p>De su lado, el ministro de Hacienda, Jos\u00e9 Manuel Vicente, declar\u00f3 que est\u00e1 convencido que Rosa har\u00e1 una trabajo excelente y apegado a los m\u00e1s altos principios \u00e9ticos.<\/p>\n<p>Tras asumir el cargo, Rosa recibi\u00f3 la oferta de colaboraci\u00f3n del anterior director de la instituci\u00f3n, German Nova, quien le dese\u00f3 \u00e9xitos en sus nuevas responsabilidades.<\/p>\n<p>La ceremonia de traspaso de mando cont\u00f3 con la asistencia de los encargados de \u00e1reas de la DGJP quienes le dieron la bienvenida al nuevo incumbente.<\/p>\n<p>Adem\u00e1s, asistieron a la ceremonia diferentes invitados especiales de parte de nuevo director.<\/p>\n<p>Juan Rosa es un abogado de los tribunales de la Rep\u00fablica con experiencia en la administraci\u00f3n p\u00fablica donde ha ocupado varios puestos tanto a nivel del gobierno central como en el \u00e1mbito municipal.<\/p>\n<p>El nuevo director de la DGJP fue Asesor de Planificaci\u00f3n del Ayuntamiento de Santo Domingo Norte y tambi\u00e9n se hab\u00eda desempe\u00f1ado como Intendente de Seguros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- El nuevo Director General de Jubilaciones y Pensiones a Cargo del Estado (DGJP), Lic. Juan Rosa, tom\u00f3 posesi\u00f3n del cargo este martes en una ceremonia realizada en el sal\u00f3n de reuniones de la instituci\u00f3n. Juan Rosa fue designado como director general de la DGJP mediante el art\u00edculo 31 del decreto 339-20 emitido por el presidente Luis Abinader Corona. Al ser posicionado, Rosa declar\u00f3 que llega a la instituci\u00f3n \u201ccon un compromiso que espera desarrollarlo con eficiencia, con compromiso social y con transparencia, tal y como se lo prometimos al presidente Luis Abinader en la noche de la juramentaci\u00f3n\u201d. El nuevo funcionario insisti\u00f3 en que su mayor compromiso es con el pa\u00eds, con la transparencia y con la calidad en el servicio. De su lado, el ministro de Hacienda, Jos\u00e9 Manuel Vicente, declar\u00f3 que est\u00e1 convencido que Rosa har\u00e1 una trabajo excelente y apegado a los m\u00e1s altos principios \u00e9ticos. Tras asumir el cargo, Rosa recibi\u00f3 la oferta de colaboraci\u00f3n del anterior director de la instituci\u00f3n, German Nova, quien le dese\u00f3 \u00e9xitos en sus nuevas responsabilidades. La ceremonia de traspaso de mando cont\u00f3 con la asistencia de los encargados de \u00e1reas de la DGJP quienes le dieron la bienvenida al nuevo incumbente. Adem\u00e1s, asistieron a la ceremonia diferentes invitados especiales de parte de nuevo director. Juan Rosa es un abogado de los tribunales de la Rep\u00fablica con experiencia en la administraci\u00f3n p\u00fablica donde ha ocupado varios puestos tanto a nivel del gobierno central como en el \u00e1mbito municipal. El nuevo director de la DGJP fue Asesor de Planificaci\u00f3n del Ayuntamiento de Santo Domingo Norte y tambi\u00e9n se hab\u00eda desempe\u00f1ado como Intendente de Seguros.<\/p>\n","protected":false},"author":6,"featured_media":106015,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-106014","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/106014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=106014"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/106014\/revisions"}],"predecessor-version":[{"id":106016,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/106014\/revisions\/106016"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/106015"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=106014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=106014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=106014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}