{"id":106282,"date":"2020-08-19T21:37:38","date_gmt":"2020-08-20T01:37:38","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=106282"},"modified":"2020-08-19T21:37:38","modified_gmt":"2020-08-20T01:37:38","slug":"muertos-por-coronavirus-ya-pasan-de-1500-en-republica-dominicana","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2020\/08\/19\/muertos-por-coronavirus-ya-pasan-de-1500-en-republica-dominicana\/","title":{"rendered":"Muertos por coronavirus ya pasan de 1,500 en Rep\u00fablica Dominicana"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-106283 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2020\/08\/526d22d8-salud-foto-1-800x398.jpg\" alt=\"\" width=\"205\" height=\"102\" \/>SANTO DOMINGO.\u2013 El Ministerio de Salud\u00a0 P\u00fablica inform\u00f3 hoy que los decesos por coronavirus en Rep\u00fablica Dominicana alcanzaron los 1,501, de los cuales 12 fueron reportados en las \u00faltimas 24 horas.<\/p>\n<p>Indica que los casos confirmados aumentaron a 88,127 (1,004 son nuevos).<\/p>\n<p>El bolet\u00edn n\u00famero 153 emitido hoy por Salud P\u00fablica, explica que los recuperados del virus subieron a 56,760 y los casos activos se mantienen 29,866.<\/p>\n<p>Manifiesta que de los casos, 6,960 se encuentran en aislamiento hospitalario y 22,906 en aislamiento<\/p>\n<p>domiciliario. Los pacientes de Covid-19 en cuidados intensivos suman 288; 44.44% en centros del Gran Santo Domingo, 27.78% en Santiago y 12.50% en Duarte.<\/p>\n<p>El total de muestras procesadas es de 331,160, de las cuales 4,516 corresponden a este bolet\u00edn. 243,033 casos sospechosos del virus han sido descartados por pruebas de laboratorio.<\/p>\n<p>La tasa de letalidad se sit\u00faa en 1.70% y la positividad en las muestras procesadas en las \u00faltimas cuatro semanas es de 30.87%.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.\u2013 El Ministerio de Salud\u00a0 P\u00fablica inform\u00f3 hoy que los decesos por coronavirus en Rep\u00fablica Dominicana alcanzaron los 1,501, de los cuales 12 fueron reportados en las \u00faltimas 24 horas. Indica que los casos confirmados aumentaron a 88,127 (1,004 son nuevos). El bolet\u00edn n\u00famero 153 emitido hoy por Salud P\u00fablica, explica que los recuperados del virus subieron a 56,760 y los casos activos se mantienen 29,866. Manifiesta que de los casos, 6,960 se encuentran en aislamiento hospitalario y 22,906 en aislamiento domiciliario. Los pacientes de Covid-19 en cuidados intensivos suman 288; 44.44% en centros del Gran Santo Domingo, 27.78% en Santiago y 12.50% en Duarte. El total de muestras procesadas es de 331,160, de las cuales 4,516 corresponden a este bolet\u00edn. 243,033 casos sospechosos del virus han sido descartados por pruebas de laboratorio. La tasa de letalidad se sit\u00faa en 1.70% y la positividad en las muestras procesadas en las \u00faltimas cuatro semanas es de 30.87%.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-106282","post","type-post","status-publish","format-standard","hentry","category-nature"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/106282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=106282"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/106282\/revisions"}],"predecessor-version":[{"id":106284,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/106282\/revisions\/106284"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=106282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=106282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=106282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}