{"id":107081,"date":"2020-08-28T19:54:01","date_gmt":"2020-08-28T23:54:01","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=107081"},"modified":"2020-08-28T19:54:01","modified_gmt":"2020-08-28T23:54:01","slug":"srsm-juramenta-directora-hospital-santo-socorro","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2020\/08\/28\/srsm-juramenta-directora-hospital-santo-socorro\/","title":{"rendered":"SRSM juramenta directora Hospital Santo Socorro"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-107082 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2020\/08\/thumbnail_Dr.-Feliz-Feliz-800x533.jpg\" alt=\"\" width=\"157\" height=\"104\" \/>El director del Servicio Regional de Salud Metropolitano (SRSM), doctor Edisson F\u00e9liz F\u00e9liz, por instrucci\u00f3n del director del Servicio Nacional de Salud (SNS), doctor Mario Lama, posesion\u00f3 a la doctora Mabel Jones como directora del Hospital Materno Infantil Santo Socorro.<\/p>\n<p>En el acto de juramentaci\u00f3n, el doctor F\u00e9liz F\u00e9liz resalt\u00f3 la alta demanda de servicios que recibe ese centro de salud y tambi\u00e9n el excelente trabajo realizado por el director saliente, doctor Darling del Orbe, el cual se evidencia en el orden, limpieza y disciplina que exhibe el hospital.<\/p>\n<p>En tal sentido, el doctor del Orbe dijo sentirse satisfecho con la labor realizada y manifest\u00f3 su apoyo a la doctora Jones para que desarrolle una buena gesti\u00f3n.<\/p>\n<p>Por su parte, la doctora Jones dijo estar consciente del reto que significa dirigir un hospital tan c\u00e9ntrico e importante para los residentes del Distrito Nacional, por lo que su principal objetivo ser\u00e1 ofrecer atenci\u00f3n de primera y con humanizaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El director del Servicio Regional de Salud Metropolitano (SRSM), doctor Edisson F\u00e9liz F\u00e9liz, por instrucci\u00f3n del director del Servicio Nacional de Salud (SNS), doctor Mario Lama, posesion\u00f3 a la doctora Mabel Jones como directora del Hospital Materno Infantil Santo Socorro. En el acto de juramentaci\u00f3n, el doctor F\u00e9liz F\u00e9liz resalt\u00f3 la alta demanda de servicios que recibe ese centro de salud y tambi\u00e9n el excelente trabajo realizado por el director saliente, doctor Darling del Orbe, el cual se evidencia en el orden, limpieza y disciplina que exhibe el hospital. En tal sentido, el doctor del Orbe dijo sentirse satisfecho con la labor realizada y manifest\u00f3 su apoyo a la doctora Jones para que desarrolle una buena gesti\u00f3n. Por su parte, la doctora Jones dijo estar consciente del reto que significa dirigir un hospital tan c\u00e9ntrico e importante para los residentes del Distrito Nacional, por lo que su principal objetivo ser\u00e1 ofrecer atenci\u00f3n de primera y con humanizaci\u00f3n.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-107081","post","type-post","status-publish","format-standard","hentry","category-nature"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/107081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=107081"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/107081\/revisions"}],"predecessor-version":[{"id":107083,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/107081\/revisions\/107083"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=107081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=107081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=107081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}