{"id":107685,"date":"2020-09-02T21:00:39","date_gmt":"2020-09-03T01:00:39","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=107685"},"modified":"2020-09-02T21:00:39","modified_gmt":"2020-09-03T01:00:39","slug":"dncd-decomisa-350-paquetes-que-presumen-es-cocaina-en-interior-de-camion-en-la-romana","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2020\/09\/02\/dncd-decomisa-350-paquetes-que-presumen-es-cocaina-en-interior-de-camion-en-la-romana\/","title":{"rendered":"DNCD decomisa 350 paquetes que presumen es coca\u00edna en interior de cami\u00f3n en La Romana"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-107686 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2020\/09\/f8b141c4-dncd-1024x550-800x430.jpg\" alt=\"\" width=\"154\" height=\"83\" \/>La Direcci\u00f3n Nacional de Control de Drogas, decomiso 350 paquetes de un polvo presumiblemente Coca\u00edna en un operativo realizado en la ciudad de La Romana, en la regi\u00f3n Este del pa\u00eds.<\/p>\n<p>En este cami\u00f3n cerrado, era trasladada la droga, camuflada en la parte trasera de los asientos, en 14 pacas colocadas en sacos de 100 libras.<\/p>\n<p>En rueda de prensa en la sede de la DNCD, el vocero de la entidad antinarc\u00f3ticos, Carlos Devers, explic\u00f3 que en el operativo participaron, los Ministerios P\u00fablico y el de Defensa, as\u00ed como miembros de los organismos de inteligencia.<\/p>\n<p>Dijo que por el hecho hay 6 personas de nacionalidad dominicana detenidas.<\/p>\n<p>El vocero de la DNCD, informo que el cami\u00f3n fue interceptado en el vertedero principal de la Romana, pr\u00f3ximo al Batey Gato, donde le fueron ocupados, adem\u00e1s un fusil, una pistola, dos veh\u00edculos y varias celulares y diversos documentos personales de los detenidos.<\/p>\n<p>La droga y las dem\u00e1s evidencias fueron enviadas al Instituto Nacional de Patolog\u00eda Forense para los fines correspondiente, informo en vocero de la DNCD.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Direcci\u00f3n Nacional de Control de Drogas, decomiso 350 paquetes de un polvo presumiblemente Coca\u00edna en un operativo realizado en la ciudad de La Romana, en la regi\u00f3n Este del pa\u00eds. En este cami\u00f3n cerrado, era trasladada la droga, camuflada en la parte trasera de los asientos, en 14 pacas colocadas en sacos de 100 libras. En rueda de prensa en la sede de la DNCD, el vocero de la entidad antinarc\u00f3ticos, Carlos Devers, explic\u00f3 que en el operativo participaron, los Ministerios P\u00fablico y el de Defensa, as\u00ed como miembros de los organismos de inteligencia. Dijo que por el hecho hay 6 personas de nacionalidad dominicana detenidas. El vocero de la DNCD, informo que el cami\u00f3n fue interceptado en el vertedero principal de la Romana, pr\u00f3ximo al Batey Gato, donde le fueron ocupados, adem\u00e1s un fusil, una pistola, dos veh\u00edculos y varias celulares y diversos documentos personales de los detenidos. La droga y las dem\u00e1s evidencias fueron enviadas al Instituto Nacional de Patolog\u00eda Forense para los fines correspondiente, informo en vocero de la DNCD.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-107685","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/107685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=107685"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/107685\/revisions"}],"predecessor-version":[{"id":107687,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/107685\/revisions\/107687"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=107685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=107685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=107685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}