{"id":108454,"date":"2020-09-12T05:51:21","date_gmt":"2020-09-12T09:51:21","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=108454"},"modified":"2020-09-12T05:51:21","modified_gmt":"2020-09-12T09:51:21","slug":"mescyt-anuncia-v-congreso-estudiantil-de-investigacion-cientifica-del-15-al-18-de-este-mes","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2020\/09\/12\/mescyt-anuncia-v-congreso-estudiantil-de-investigacion-cientifica-del-15-al-18-de-este-mes\/","title":{"rendered":"MESCYT anuncia V Congreso Estudiantil de Investigaci\u00f3n Cient\u00edfica del 15 al 18 de este mes"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-108455 aligncenter\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2020\/09\/thumbnail_FRANKLIN-1024x550-800x430.jpg\" alt=\"\" width=\"800\" height=\"430\" \/>El ministro de Educaci\u00f3n Superior, Ciencia y Tecnolog\u00eda (MESCYT), doctor Franklin Garc\u00eda Ferm\u00edn, anunci\u00f3 el V Congreso Estudiantil de Investigaci\u00f3n Cient\u00edfica y Tecnol\u00f3gica (VCEICYT), con la participaci\u00f3n de diecinueve universidades del pa\u00eds e invitados internacionales, a celebrarse de manera virtual los d\u00edas 15, 16, 17 y 18 de este mes.<\/p>\n<p>El evento es organizado por el MESCYT de forma conjunta con la Universidad Aut\u00f3noma de Santo Domingo (UASD), la Universidad Abierta para Adultos (UAPA), APEC (UNAPEC), la Universidad Nacional Pedro Henr\u00edquez Ure\u00f1a (UNPHU), Instituto Tecnol\u00f3gico de Santo Domingo (INTEC), la Universidad del Caribe (UNICARIBE), la Universidad Federico Henr\u00edquez y Carvajal (UFHEC) y la Universidad Cat\u00f3lica Madre y Maestra (PUCMM). Adem\u00e1s de la Red de Investigaci\u00f3n de la Asociaci\u00f3n Dominicana de Rectores de Universidades (RIADRU).<\/p>\n<p>El CEICYT es un espacio para dar a conocer iniciativas de investigaci\u00f3n de estudiantes universitarios del nivel de grado, en las \u00e1reas cient\u00edficas y tecnol\u00f3gicas en el que se busca contribuir al fomento de la cultura de estudios e innovaci\u00f3n en la naci\u00f3n, con miras a insertarla en la sociedad del conocimiento.<\/p>\n<p>En este a\u00f1o el congreso estudiantil contar\u00e1 con la participaci\u00f3n de estudiantes de diecinueve universidades y de invitados de Cuba, Brasil y Chile, entre otros.<\/p>\n<p>Entre las \u00e1reas o campos disciplinarios para la presentaci\u00f3n de trabajos de investigaci\u00f3n se encuentran las de ciencias b\u00e1sicas, como la biolog\u00eda, qu\u00edmica, f\u00edsica, matem\u00e1ticas, aplicaciones, fronteras y campos emergentes; neurociencia, econof\u00edsica.<\/p>\n<p>Asimismo, las de ciencias agropecuarias y recursos naturales; ciencias agroalimentarias y forestales, medio Ambiente, biotecnolog\u00eda y veterinaria. De<\/p>\n<p>igual forma, en los campos de ingenier\u00eda y tecnolog\u00eda, se encuentran ingenier\u00edas, arquitectura, tecnolog\u00edas de la informaci\u00f3n y comunicaci\u00f3n (TIC), desarrollo de software y aplicaciones, microprocesadores y microcontroladores, mecatr\u00f3nica y rob\u00f3tica, bioingenier\u00eda, energ\u00eda renovable, procesos industriales y manufactura.<\/p>\n<p>Adem\u00e1s, en ciencias de la salud abarca medicina interna, quir\u00fargica, experimental, molecular, biomedicina, nutrici\u00f3n, enfermer\u00eda, farmacia y odontolog\u00eda.<\/p>\n<p>En la rama de la educaci\u00f3n cient\u00edfica y educaci\u00f3n matem\u00e1tica, hace \u00e9nfasis en el uso de las TICs (plataformas digitales en general) para promover aprendizaje.<\/p>\n<p>Los participantes en el congreso son los estudiantes universitarios de grado o egresados con seis meses o menos de graduado, siempre y cuando los trabajos a presentar hayan sido realizados durante sus estudios de grado.<\/p>\n<p>En ese tenor, deben ser de las \u00e1reas de ciencias b\u00e1sicas y aplicadas los que pueden participar como expositores de trabajos cient\u00edficos o en representaci\u00f3n de sus universidades.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ministro de Educaci\u00f3n Superior, Ciencia y Tecnolog\u00eda (MESCYT), doctor Franklin Garc\u00eda Ferm\u00edn, anunci\u00f3 el V Congreso Estudiantil de Investigaci\u00f3n Cient\u00edfica y Tecnol\u00f3gica (VCEICYT), con la participaci\u00f3n de diecinueve universidades del pa\u00eds e invitados internacionales, a celebrarse de manera virtual los d\u00edas 15, 16, 17 y 18 de este mes. El evento es organizado por el MESCYT de forma conjunta con la Universidad Aut\u00f3noma de Santo Domingo (UASD), la Universidad Abierta para Adultos (UAPA), APEC (UNAPEC), la Universidad Nacional Pedro Henr\u00edquez Ure\u00f1a (UNPHU), Instituto Tecnol\u00f3gico de Santo Domingo (INTEC), la Universidad del Caribe (UNICARIBE), la Universidad Federico Henr\u00edquez y Carvajal (UFHEC) y la Universidad Cat\u00f3lica Madre y Maestra (PUCMM). Adem\u00e1s de la Red de Investigaci\u00f3n de la Asociaci\u00f3n Dominicana de Rectores de Universidades (RIADRU). El CEICYT es un espacio para dar a conocer iniciativas de investigaci\u00f3n de estudiantes universitarios del nivel de grado, en las \u00e1reas cient\u00edficas y tecnol\u00f3gicas en el que se busca contribuir al fomento de la cultura de estudios e innovaci\u00f3n en la naci\u00f3n, con miras a insertarla en la sociedad del conocimiento. En este a\u00f1o el congreso estudiantil contar\u00e1 con la participaci\u00f3n de estudiantes de diecinueve universidades y de invitados de Cuba, Brasil y Chile, entre otros. Entre las \u00e1reas o campos disciplinarios para la presentaci\u00f3n de trabajos de investigaci\u00f3n se encuentran las de ciencias b\u00e1sicas, como la biolog\u00eda, qu\u00edmica, f\u00edsica, matem\u00e1ticas, aplicaciones, fronteras y campos emergentes; neurociencia, econof\u00edsica. Asimismo, las de ciencias agropecuarias y recursos naturales; ciencias agroalimentarias y forestales, medio Ambiente, biotecnolog\u00eda y veterinaria. De igual forma, en los campos de ingenier\u00eda y tecnolog\u00eda, se encuentran ingenier\u00edas, arquitectura, tecnolog\u00edas de la informaci\u00f3n y comunicaci\u00f3n (TIC), desarrollo de software y aplicaciones, microprocesadores y microcontroladores, mecatr\u00f3nica y rob\u00f3tica, bioingenier\u00eda, energ\u00eda renovable, procesos industriales y manufactura. Adem\u00e1s, en ciencias de la salud abarca medicina interna, quir\u00fargica, experimental, molecular, biomedicina, nutrici\u00f3n, enfermer\u00eda, farmacia y odontolog\u00eda. En la rama de la educaci\u00f3n cient\u00edfica y educaci\u00f3n matem\u00e1tica, hace \u00e9nfasis en el uso de las TICs (plataformas digitales en general) para promover aprendizaje. Los participantes en el congreso son los estudiantes universitarios de grado o egresados con seis meses o menos de graduado, siempre y cuando los trabajos a presentar hayan sido realizados durante sus estudios de grado. En ese tenor, deben ser de las \u00e1reas de ciencias b\u00e1sicas y aplicadas los que pueden participar como expositores de trabajos cient\u00edficos o en representaci\u00f3n de sus universidades. &nbsp; &nbsp; &nbsp;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-108454","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/108454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=108454"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/108454\/revisions"}],"predecessor-version":[{"id":108456,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/108454\/revisions\/108456"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=108454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=108454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=108454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}