{"id":109073,"date":"2020-09-18T22:11:25","date_gmt":"2020-09-19T02:11:25","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=109073"},"modified":"2020-09-18T22:11:25","modified_gmt":"2020-09-19T02:11:25","slug":"optic-y-prosoli-trabajaran-en-conjunto-para-eficientizar-servicios-de-los-programas-sociales","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2020\/09\/18\/optic-y-prosoli-trabajaran-en-conjunto-para-eficientizar-servicios-de-los-programas-sociales\/","title":{"rendered":"OPTIC y\u00a0PROSOLI\u00a0trabajar\u00e1n en conjunto para eficientizar servicios de los programas sociales"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-109074 aligncenter\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2020\/09\/thumbnail_748D4CD3-BCDC-4F50-9071-73D7D929EED5-800x558.jpg\" alt=\"\" width=\"800\" height=\"558\" \/>Santo Domingo. \u2013\u00a0El director general de la Oficina Presidencial de Tecnolog\u00eda de la Informaci\u00f3n y Comunicaci\u00f3n (OPTIC), Pedro Quezada, realiz\u00f3 un recorrido junto a la directora general de Progresando con Solidaridad (PROSOLI), Gloria Reyes, con la finalidad de mostrarle la infraestructura y servicios del Datacenter del Estado dominicano.<\/p>\n<p>Quezada y Reyes acordaron trabajar en conjunto en la creaci\u00f3n de estrategias tecnol\u00f3gicas que procuren eficientizar los servicios de los programas sociales que realiza el gobierno a trav\u00e9s de PROSOLI.<\/p>\n<p>Los funcionarios indicaron que desde la OPTIC se prestar\u00e1 colaboraci\u00f3n en la ampliaci\u00f3n de las capacidades de almacenamiento en sus equipos, lo cual ayudar\u00e1 incrementar la calidad en los servicios que se le ofrece a los beneficiaros de los diferentes planes de asistencia social.<\/p>\n<p>Quezada expres\u00f3 que desde el Datacenter se provee un servicio de calidad a todas las instituciones del Estado que ha requerido alojar sus datos en la m\u00e1s moderna plataforma tecnol\u00f3gica del pa\u00eds.<\/p>\n<p>\u201cLas instalaciones de este Datacenter, adem\u00e1s de modernas, son muy confiables y seguras, con est\u00e1ndares que nos colocan a la altura de cualquier Datacenter a nivel internacional\u201d, explic\u00f3 Quezada.<\/p>\n<p>De su lado Gloria Reyes mostr\u00f3 confianza por la seguridad con que cuenta el centro, por lo que consider\u00f3\u00a0establecer all\u00ed el almacenamiento de datos\u00a0\u00a0\u00a0de\u00a0PROSOLI en el menor tiempo posible.<\/p>\n<p>Reyes manifest\u00f3 inter\u00e9s de que el centro de datos alternos de la instituci\u00f3n que dirige est\u00e9 alojado en el Datacenter del Estado por las garant\u00edas que ofrece la estructura ante cualquier evento natural que suceda en el pa\u00eds.<\/p>\n<p>Durante el recorrido, los funcionarios estuvieron acompa\u00f1ados de Kanking Choi, director del Datacenter; Guevert Bocio, encargado de Operaciones e Infraestructuras del Datacenter; Tomas Kelly, director de Relaciones Interinstitucional de la OPTIC y Ronny Lebr\u00f3n, director de Tecnolog\u00eda de PROSOSLI, entre otros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo. \u2013\u00a0El director general de la Oficina Presidencial de Tecnolog\u00eda de la Informaci\u00f3n y Comunicaci\u00f3n (OPTIC), Pedro Quezada, realiz\u00f3 un recorrido junto a la directora general de Progresando con Solidaridad (PROSOLI), Gloria Reyes, con la finalidad de mostrarle la infraestructura y servicios del Datacenter del Estado dominicano. Quezada y Reyes acordaron trabajar en conjunto en la creaci\u00f3n de estrategias tecnol\u00f3gicas que procuren eficientizar los servicios de los programas sociales que realiza el gobierno a trav\u00e9s de PROSOLI. Los funcionarios indicaron que desde la OPTIC se prestar\u00e1 colaboraci\u00f3n en la ampliaci\u00f3n de las capacidades de almacenamiento en sus equipos, lo cual ayudar\u00e1 incrementar la calidad en los servicios que se le ofrece a los beneficiaros de los diferentes planes de asistencia social. Quezada expres\u00f3 que desde el Datacenter se provee un servicio de calidad a todas las instituciones del Estado que ha requerido alojar sus datos en la m\u00e1s moderna plataforma tecnol\u00f3gica del pa\u00eds. \u201cLas instalaciones de este Datacenter, adem\u00e1s de modernas, son muy confiables y seguras, con est\u00e1ndares que nos colocan a la altura de cualquier Datacenter a nivel internacional\u201d, explic\u00f3 Quezada. De su lado Gloria Reyes mostr\u00f3 confianza por la seguridad con que cuenta el centro, por lo que consider\u00f3\u00a0establecer all\u00ed el almacenamiento de datos\u00a0\u00a0\u00a0de\u00a0PROSOLI en el menor tiempo posible. Reyes manifest\u00f3 inter\u00e9s de que el centro de datos alternos de la instituci\u00f3n que dirige est\u00e9 alojado en el Datacenter del Estado por las garant\u00edas que ofrece la estructura ante cualquier evento natural que suceda en el pa\u00eds. Durante el recorrido, los funcionarios estuvieron acompa\u00f1ados de Kanking Choi, director del Datacenter; Guevert Bocio, encargado de Operaciones e Infraestructuras del Datacenter; Tomas Kelly, director de Relaciones Interinstitucional de la OPTIC y Ronny Lebr\u00f3n, director de Tecnolog\u00eda de PROSOSLI, entre otros.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-109073","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/109073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=109073"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/109073\/revisions"}],"predecessor-version":[{"id":109075,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/109073\/revisions\/109075"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=109073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=109073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=109073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}