{"id":109196,"date":"2020-09-20T17:53:31","date_gmt":"2020-09-20T21:53:31","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=109196"},"modified":"2020-09-20T17:53:31","modified_gmt":"2020-09-20T21:53:31","slug":"jose-sanchez-rector-itsc-visita-director-general-de-escuelas-vocacionales-coronel-juan-jose-otano-jimenez-erd","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2020\/09\/20\/jose-sanchez-rector-itsc-visita-director-general-de-escuelas-vocacionales-coronel-juan-jose-otano-jimenez-erd\/","title":{"rendered":"Jos\u00e9 S\u00e1nchez, rector ITSC, visita director general de Escuelas Vocacionales, coronel Juan Jos\u00e9 Ota\u00f1o Jim\u00e9nez (ERD)."},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-109197 aligncenter\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2020\/09\/thumbnail_RECTOR-JOS\u00c9-S\u00c1NCHEZ-VISITA-A-DIRECTOR-DIGEV-800x533.jpg\" alt=\"\" width=\"800\" height=\"533\" \/>Santo Domingo. RD. El abogado y acad\u00e9mico Jos\u00e9 S\u00e1nchez, rector del Instituto T\u00e9cnico Superior Comunitario (ITSC), realiz\u00f3 una visita al coronel Juan Jos\u00e9 Ota\u00f1o Jim\u00e9nez (ERD), director general de\u00a0las Escuelas Vocacionales de las Fuerzas Armadas y Polic\u00eda Nacional\u00a0(DIGEV),\u00a0con el objetivo de realizar futuros convenios que favorezcan a los j\u00f3venes y adultos dominicanos que viven en condiciones de vulnerabilidad.<\/p>\n<p>El nuevo rector del ITSC detall\u00f3 que con dicho convenio se lograr\u00eda que \u201clos estudiantes que asistan a nuestra instituci\u00f3n y no cumplan con el perfil que requerimos, puedan ser referidos a las\u00a0Escuelas Vocacionales de las Fuerzas Armadas y Polic\u00eda Nacional\u00a0(DIGEV),\u00a0asegur\u00e1ndoles\u00a0 un cupo en cualquiera de las 140 acciones formativas impartidas en dicha instituci\u00f3n\u201d.<\/p>\n<p>En ese mismo tenor, S\u00e1nchez explic\u00f3 que con tal acci\u00f3n se \u201catraer\u00eda a toda la poblaci\u00f3n a realizar un curso t\u00e9cnico y as\u00ed a recibir los beneficios de la educaci\u00f3n, lo cual traer\u00eda frutos positivos a toda la sociedad,\u00a0inculcando en los estudiantes una cultura de emprendurismo y fortaleciendo, de este modo, el desarrollo social y econ\u00f3mico del pa\u00eds\u201d.<\/p>\n<p>El acad\u00e9mico insisti\u00f3 en que es conocida en toda la sociedad dominicana, \u201cel excelente trabajo que realizan dichas escuelas, las cuales cuentan con una amplia variedad de cursos, completamente gratis, entre\u00a0los cuales algunos no requieren un nivel acad\u00e9mico tan alto, logrando graduar, a nivel\u00a0\u00a0t\u00e9cnico-profesional, a muchos j\u00f3venes de escasos recursos econ\u00f3micos, pudiendo \u00e9stos \u00a0incorporarse al mercado laboral productivo\u201d.<\/p>\n<p>El rector Jos\u00e9 S\u00e1nchez, tambi\u00e9n estuvo acompa\u00f1ado por Ram\u00f3n Jim\u00e9nez, regidor de la Alcald\u00eda de Santo Domingo Este, la Dra. Alba Iris Contreras Jim\u00e9nez, consultora jur\u00eddica del ITSC y otros directivos de la alta casa de estudios.<\/p>\n<p>PIE DE FOTO.<\/p>\n<p>El abogado y acad\u00e9mico Jos\u00e9 S\u00e1nchez, rector del Instituto T\u00e9cnico Superior Comunitario (ITSC) y el coronel Juan Jos\u00e9 Ota\u00f1o Jim\u00e9nez (ERD), director general de\u00a0las Escuelas Vocacionales de las Fuerzas Armadas y Polic\u00eda Nacional\u00a0(DIGEV).<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo. RD. El abogado y acad\u00e9mico Jos\u00e9 S\u00e1nchez, rector del Instituto T\u00e9cnico Superior Comunitario (ITSC), realiz\u00f3 una visita al coronel Juan Jos\u00e9 Ota\u00f1o Jim\u00e9nez (ERD), director general de\u00a0las Escuelas Vocacionales de las Fuerzas Armadas y Polic\u00eda Nacional\u00a0(DIGEV),\u00a0con el objetivo de realizar futuros convenios que favorezcan a los j\u00f3venes y adultos dominicanos que viven en condiciones de vulnerabilidad. El nuevo rector del ITSC detall\u00f3 que con dicho convenio se lograr\u00eda que \u201clos estudiantes que asistan a nuestra instituci\u00f3n y no cumplan con el perfil que requerimos, puedan ser referidos a las\u00a0Escuelas Vocacionales de las Fuerzas Armadas y Polic\u00eda Nacional\u00a0(DIGEV),\u00a0asegur\u00e1ndoles\u00a0 un cupo en cualquiera de las 140 acciones formativas impartidas en dicha instituci\u00f3n\u201d. En ese mismo tenor, S\u00e1nchez explic\u00f3 que con tal acci\u00f3n se \u201catraer\u00eda a toda la poblaci\u00f3n a realizar un curso t\u00e9cnico y as\u00ed a recibir los beneficios de la educaci\u00f3n, lo cual traer\u00eda frutos positivos a toda la sociedad,\u00a0inculcando en los estudiantes una cultura de emprendurismo y fortaleciendo, de este modo, el desarrollo social y econ\u00f3mico del pa\u00eds\u201d. El acad\u00e9mico insisti\u00f3 en que es conocida en toda la sociedad dominicana, \u201cel excelente trabajo que realizan dichas escuelas, las cuales cuentan con una amplia variedad de cursos, completamente gratis, entre\u00a0los cuales algunos no requieren un nivel acad\u00e9mico tan alto, logrando graduar, a nivel\u00a0\u00a0t\u00e9cnico-profesional, a muchos j\u00f3venes de escasos recursos econ\u00f3micos, pudiendo \u00e9stos \u00a0incorporarse al mercado laboral productivo\u201d. El rector Jos\u00e9 S\u00e1nchez, tambi\u00e9n estuvo acompa\u00f1ado por Ram\u00f3n Jim\u00e9nez, regidor de la Alcald\u00eda de Santo Domingo Este, la Dra. Alba Iris Contreras Jim\u00e9nez, consultora jur\u00eddica del ITSC y otros directivos de la alta casa de estudios. PIE DE FOTO. El abogado y acad\u00e9mico Jos\u00e9 S\u00e1nchez, rector del Instituto T\u00e9cnico Superior Comunitario (ITSC) y el coronel Juan Jos\u00e9 Ota\u00f1o Jim\u00e9nez (ERD), director general de\u00a0las Escuelas Vocacionales de las Fuerzas Armadas y Polic\u00eda Nacional\u00a0(DIGEV). &nbsp;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-109196","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/109196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=109196"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/109196\/revisions"}],"predecessor-version":[{"id":109198,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/109196\/revisions\/109198"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=109196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=109196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=109196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}