{"id":109316,"date":"2020-09-22T19:48:15","date_gmt":"2020-09-22T23:48:15","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=109316"},"modified":"2020-09-22T19:48:15","modified_gmt":"2020-09-22T23:48:15","slug":"con-peatonalizacion-de-calles-intrant-inicia-tercera-semana-de-la-movilidad-sostenible","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2020\/09\/22\/con-peatonalizacion-de-calles-intrant-inicia-tercera-semana-de-la-movilidad-sostenible\/","title":{"rendered":"Con peatonalizaci\u00f3n de calles INTRANT inicia tercera Semana de la Movilidad Sostenible"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-109317 aligncenter\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2020\/09\/thumbnail_Recorrido-por-la-Duarte-Peatonal-800x533.jpg\" alt=\"\" width=\"800\" height=\"533\" \/>Junto a las alcald\u00edas, organismos internacionales e instituciones p\u00fablicas y privadas, fomenta la movilidad el\u00e9ctrica y otras formas de desplazamiento amigables con el medio ambiente.<\/strong><\/p>\n<p>Santo Domingo, 22 septiembre 2020.-\u00a0Con el prop\u00f3sito de\u00a0sensibilizar a los ciudadanos sobre c\u00f3mo mejorar su calidad de vida, cambiando la forma en que se movilizan,\u00a0el Instituto Nacional de Tr\u00e1nsito y Transporte Terrestre (INTRANT), celebra la tercera Semana Nacional de la Movilidad Sostenible del 22 al 29 de septiembre.<\/p>\n<p>Las actividades iniciaron con la celebraci\u00f3n del D\u00eda Mundial Sin Auto y la peatonalizaci\u00f3n de algunas v\u00edas, como la avenida Duarte del Distrito Nacional, acto en el que participaron el director ejecutivo del INTRANT, Rafael Arias, la alcaldesa por el Distrito Nacional, Carolina Mej\u00eda y representantes del sector comercial de la citada avenida.<\/p>\n<p>Asimismo, se implementan proyectos piloto de ciclov\u00edas en el DN, SDE, SDN y Los Alcarrizos, as\u00ed como habilitaci\u00f3n\u00a0parqueos para bicicletas en diferentes espacios de la ciudad.<\/p>\n<p>A prop\u00f3sito, el director ejecutivo del INTRANT, Rafael Arias dijo que la celebraci\u00f3n busca promover los beneficios del uso de transportes m\u00e1s sostenibles y amigables con el medio ambiente, como el transporte colectivo, la bicicleta y los viajes a pie o transporte no motorizado, e incentivar al uso del Sistema Integrado de Transporte P\u00fablico, como parte de\u00a0las ejecutorias del Plan de Movilidad Urbana Sostenible del Gran Santo Domingo (PMUS).<\/p>\n<p>De su lado Carolina Mej\u00eda expres\u00f3 que \u201cestamos trabajando en favor de todos los dominicanos que disfrutan diariamente de la capital, promoviendo la movilidad sostenible y creando espacios donde los mun\u00edcipes puedan disfrutar su ciudad, caminar sus calles y redescubrir Santo Domingo\u201d.<\/p>\n<p>Las acciones de la Semana de Movilidad ser\u00e1n ejecutadas por el INTRANT junto a las distintas alcald\u00edas del Gran Santo Domingo y del interior del pa\u00eds, y cuenta con el apoyo de instituciones p\u00fablicas y privadas,\u00a0 universidades, autoridades del sector transporte, la Agencia Francesa de Desarrollo (AFD), la Uni\u00f3n Europea (UE), el banco Interamericano de Desarrollo (BID) la Embajada de los Pa\u00edses Bajos, el Ministerio de Obras P\u00fablicas y Comunicaciones (MOPC), OPRET, OMSA, la Polic\u00eda Nacional, la DIGESETT, COMIPOL, entre otros.<\/p>\n<p>La celebraci\u00f3n de Movilidad Sostenible surge en\u00a0Europa, y ha sido acogida en pa\u00edses de Latinoam\u00e9rica como Colombia, Brasil, M\u00e9xico, Argentina, Per\u00fa, Chile y la Rep\u00fablica Dominicana es parte de esa iniciativa. Esta jornada se hace promoviendo los modos sostenibles que evitan la propagaci\u00f3n del COVID-19 y cumplimiento de las medidas de distanciamiento f\u00edsico e higiene en los desplazamientos necesarios.<\/p>\n<p>Se destacar\u00e1n acciones a favor de la movilidad el\u00e9ctrica y la movilidad activa como la ubicaci\u00f3n de cargadores el\u00e9ctricos y el desarrollo de dos seminarios web (Webinar), para educar respecto al tema con el apoyo del Instituto Tecnol\u00f3gico de Santo Domingo INTEC.<\/p>\n<p>Durante la celebraci\u00f3n, se realizar\u00e1 un piloto de alquiler de patinetas el\u00e9ctricas y bicicletas que faciliten a los usuarios conectar con estaciones del Metro de Santo Domingo; y en ese mismo orden se realizar\u00e1 una Bici-feria en la que se escoger\u00e1n mediante concurso los proyectos m\u00e1s innovadores que utilicen la bicicleta como base de la creatividad.<\/p>\n<p>En la SNMS los usuarios podr\u00e1n abordar el Metro y Telef\u00e9rico con su bici y para educar a la ciudadan\u00eda se realizar\u00e1n actividades de urbanismo t\u00e1ctico en las paradas del transporte p\u00fablico de OMSA, para colocar la se\u00f1alizaci\u00f3n del distanciamiento f\u00edsico.<\/p>\n<p>En esa misma semana, tambi\u00e9n se realizar\u00e1 el moviclaje, actividad que consiste en motivar la cultura de reciclaje mediante el intercambio de botellas pl\u00e1sticas por pasajes de transporte con la tarjeta \u00abSDGo\u00bb.<\/p>\n<p>A prop\u00f3sito de la situaci\u00f3n sanitaria por la pandemia COVID-19, el INTRANT reconocer\u00e1 las empresas de transporte p\u00fablico que est\u00e9n implementado las medidas correctas de higiene y distanciamiento para ofrecer el servicio. Sin dejar de considerar el contexto de la educaci\u00f3n virtual, se hace un rally para que los diferentes centros educativos motiven a los j\u00f3venes a participar respondiendo preguntas para aportar a su experiencia educativa desde la virtualidad.<\/p>\n<p>Habr\u00e1 un reto que consiste en que las empresas motiven a sus empleados a trasladarse, durante esa semana, a su lugar de trabajo en bicicleta, a pie o utilizando un transporte colectivo facilitado por la empresa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Junto a las alcald\u00edas, organismos internacionales e instituciones p\u00fablicas y privadas, fomenta la movilidad el\u00e9ctrica y otras formas de desplazamiento amigables con el medio ambiente. Santo Domingo, 22 septiembre 2020.-\u00a0Con el prop\u00f3sito de\u00a0sensibilizar a los ciudadanos sobre c\u00f3mo mejorar su calidad de vida, cambiando la forma en que se movilizan,\u00a0el Instituto Nacional de Tr\u00e1nsito y Transporte Terrestre (INTRANT), celebra la tercera Semana Nacional de la Movilidad Sostenible del 22 al 29 de septiembre. Las actividades iniciaron con la celebraci\u00f3n del D\u00eda Mundial Sin Auto y la peatonalizaci\u00f3n de algunas v\u00edas, como la avenida Duarte del Distrito Nacional, acto en el que participaron el director ejecutivo del INTRANT, Rafael Arias, la alcaldesa por el Distrito Nacional, Carolina Mej\u00eda y representantes del sector comercial de la citada avenida. Asimismo, se implementan proyectos piloto de ciclov\u00edas en el DN, SDE, SDN y Los Alcarrizos, as\u00ed como habilitaci\u00f3n\u00a0parqueos para bicicletas en diferentes espacios de la ciudad. A prop\u00f3sito, el director ejecutivo del INTRANT, Rafael Arias dijo que la celebraci\u00f3n busca promover los beneficios del uso de transportes m\u00e1s sostenibles y amigables con el medio ambiente, como el transporte colectivo, la bicicleta y los viajes a pie o transporte no motorizado, e incentivar al uso del Sistema Integrado de Transporte P\u00fablico, como parte de\u00a0las ejecutorias del Plan de Movilidad Urbana Sostenible del Gran Santo Domingo (PMUS). De su lado Carolina Mej\u00eda expres\u00f3 que \u201cestamos trabajando en favor de todos los dominicanos que disfrutan diariamente de la capital, promoviendo la movilidad sostenible y creando espacios donde los mun\u00edcipes puedan disfrutar su ciudad, caminar sus calles y redescubrir Santo Domingo\u201d. Las acciones de la Semana de Movilidad ser\u00e1n ejecutadas por el INTRANT junto a las distintas alcald\u00edas del Gran Santo Domingo y del interior del pa\u00eds, y cuenta con el apoyo de instituciones p\u00fablicas y privadas,\u00a0 universidades, autoridades del sector transporte, la Agencia Francesa de Desarrollo (AFD), la Uni\u00f3n Europea (UE), el banco Interamericano de Desarrollo (BID) la Embajada de los Pa\u00edses Bajos, el Ministerio de Obras P\u00fablicas y Comunicaciones (MOPC), OPRET, OMSA, la Polic\u00eda Nacional, la DIGESETT, COMIPOL, entre otros. La celebraci\u00f3n de Movilidad Sostenible surge en\u00a0Europa, y ha sido acogida en pa\u00edses de Latinoam\u00e9rica como Colombia, Brasil, M\u00e9xico, Argentina, Per\u00fa, Chile y la Rep\u00fablica Dominicana es parte de esa iniciativa. Esta jornada se hace promoviendo los modos sostenibles que evitan la propagaci\u00f3n del COVID-19 y cumplimiento de las medidas de distanciamiento f\u00edsico e higiene en los desplazamientos necesarios. Se destacar\u00e1n acciones a favor de la movilidad el\u00e9ctrica y la movilidad activa como la ubicaci\u00f3n de cargadores el\u00e9ctricos y el desarrollo de dos seminarios web (Webinar), para educar respecto al tema con el apoyo del Instituto Tecnol\u00f3gico de Santo Domingo INTEC. Durante la celebraci\u00f3n, se realizar\u00e1 un piloto de alquiler de patinetas el\u00e9ctricas y bicicletas que faciliten a los usuarios conectar con estaciones del Metro de Santo Domingo; y en ese mismo orden se realizar\u00e1 una Bici-feria en la que se escoger\u00e1n mediante concurso los proyectos m\u00e1s innovadores que utilicen la bicicleta como base de la creatividad. En la SNMS los usuarios podr\u00e1n abordar el Metro y Telef\u00e9rico con su bici y para educar a la ciudadan\u00eda se realizar\u00e1n actividades de urbanismo t\u00e1ctico en las paradas del transporte p\u00fablico de OMSA, para colocar la se\u00f1alizaci\u00f3n del distanciamiento f\u00edsico. En esa misma semana, tambi\u00e9n se realizar\u00e1 el moviclaje, actividad que consiste en motivar la cultura de reciclaje mediante el intercambio de botellas pl\u00e1sticas por pasajes de transporte con la tarjeta \u00abSDGo\u00bb. A prop\u00f3sito de la situaci\u00f3n sanitaria por la pandemia COVID-19, el INTRANT reconocer\u00e1 las empresas de transporte p\u00fablico que est\u00e9n implementado las medidas correctas de higiene y distanciamiento para ofrecer el servicio. Sin dejar de considerar el contexto de la educaci\u00f3n virtual, se hace un rally para que los diferentes centros educativos motiven a los j\u00f3venes a participar respondiendo preguntas para aportar a su experiencia educativa desde la virtualidad. Habr\u00e1 un reto que consiste en que las empresas motiven a sus empleados a trasladarse, durante esa semana, a su lugar de trabajo en bicicleta, a pie o utilizando un transporte colectivo facilitado por la empresa.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-109316","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/109316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=109316"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/109316\/revisions"}],"predecessor-version":[{"id":109318,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/109316\/revisions\/109318"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=109316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=109316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=109316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}