{"id":109492,"date":"2020-09-24T13:54:19","date_gmt":"2020-09-24T17:54:19","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=109492"},"modified":"2020-09-24T13:54:52","modified_gmt":"2020-09-24T17:54:52","slug":"dgcp-emite-nuevas-disposiciones-para-garantizar-transparencia-y-control-en-contrataciones-publicas","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2020\/09\/24\/dgcp-emite-nuevas-disposiciones-para-garantizar-transparencia-y-control-en-contrataciones-publicas\/","title":{"rendered":"DGCP emite nuevas disposiciones para garantizar transparencia y control en\u00a0contrataciones p\u00fablicas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-109494 aligncenter\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2020\/09\/thumbnail_Sr.-Pimentel-1-800x533.jpg\" alt=\"\" width=\"800\" height=\"533\" \/>La Direcci\u00f3n General de Contrataciones P\u00fablicas (DGCP) emiti\u00f3 una normativa que establece las pautas generales para la elaboraci\u00f3n de pliegos de condiciones, fichas t\u00e9cnicas y t\u00e9rminos de referencia en los procedimientos de contrataci\u00f3n p\u00fablica.<\/p>\n<p>Se trata de la resoluci\u00f3n\u00a0PNP-06-2020, la cual busca aumentar la eficiencia y objetividad en los procedimientos convocados por las instituciones sujetas al \u00e1mbito de aplicaci\u00f3n de la Ley 340-06, sobre Compras y Contrataciones P\u00fablicas.<\/p>\n<p>Seg\u00fan la DGCP la ejecuci\u00f3n exitosa de estos procedimientos depende de la calidad de las bases de la contrataci\u00f3n, las cuales, de conformidad con el art\u00edculo 20 de la Ley 340-06 de Compras y Contrataciones P\u00fablicas, deben establecer toda la informaci\u00f3n necesaria, de manera precisa y detallada, a los fines de que los interesados en participar cuenten con los datos requeridos para presentar sus propuestas y autoevaluarse, lo que har\u00eda la adjudicaci\u00f3n m\u00e1s objetiva, justa y eficiente.<\/p>\n<p>Estas pautas surgen como resultado de la consolidaci\u00f3n de las principales inobservancias detectadas a trav\u00e9s de los recursos administrativos, as\u00ed como de los monitoreos aleatorios preventivos que se realizan a los procedimientos gestionados en el Portal Transaccional.<\/p>\n<p>Dicha normativa va de la mano de la resoluci\u00f3n PNP-07-2020 que ordena a los comit\u00e9s de compras y contrataciones de las instituciones p\u00fablicas y los ayuntamientos, a designar peritos que intervendr\u00e1n en las fases de dise\u00f1o y evaluaci\u00f3n de los procedimientos de contrataci\u00f3n p\u00fablica.<\/p>\n<p>Seg\u00fan esta disposici\u00f3n emitida por el \u00f3rgano rector del sistema, las instituciones deber\u00e1n designar, al menos, tres peritos en cada procedimiento, con un perfil de especialistas legales, financieros y t\u00e9cnicos, seg\u00fan la complejidad y el objeto de la contrataci\u00f3n, para evaluar y emitir un informe t\u00e9cnico de las ofertas presentadas, de conformidad a los requerimientos establecidos en la base de contrataci\u00f3n.<\/p>\n<p>Entre otras cosas, el documento\u00a0plantea que las bases de la contrataci\u00f3n y el borrador de contrato establezcan de forma clara las condiciones y el tiempo de pago, as\u00ed como los tipos de garant\u00edas requeridas a los oferentes.<\/p>\n<p>Asimismo, insta a las instituciones a realizar consultas al mercado y llamados a manifestaci\u00f3n de inter\u00e9s, durante la fase de planificaci\u00f3n para determinar la forma m\u00e1s eficiente de satisfacer la necesidad de la entidad contratante, las caracter\u00edsticas del bien, servicio u obra a ser adquirido y obtener informacion acerca de las diferentes opciones o innovaciones en el mercado.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Direcci\u00f3n General de Contrataciones P\u00fablicas (DGCP) emiti\u00f3 una normativa que establece las pautas generales para la elaboraci\u00f3n de pliegos de condiciones, fichas t\u00e9cnicas y t\u00e9rminos de referencia en los procedimientos de contrataci\u00f3n p\u00fablica. Se trata de la resoluci\u00f3n\u00a0PNP-06-2020, la cual busca aumentar la eficiencia y objetividad en los procedimientos convocados por las instituciones sujetas al \u00e1mbito de aplicaci\u00f3n de la Ley 340-06, sobre Compras y Contrataciones P\u00fablicas. Seg\u00fan la DGCP la ejecuci\u00f3n exitosa de estos procedimientos depende de la calidad de las bases de la contrataci\u00f3n, las cuales, de conformidad con el art\u00edculo 20 de la Ley 340-06 de Compras y Contrataciones P\u00fablicas, deben establecer toda la informaci\u00f3n necesaria, de manera precisa y detallada, a los fines de que los interesados en participar cuenten con los datos requeridos para presentar sus propuestas y autoevaluarse, lo que har\u00eda la adjudicaci\u00f3n m\u00e1s objetiva, justa y eficiente. Estas pautas surgen como resultado de la consolidaci\u00f3n de las principales inobservancias detectadas a trav\u00e9s de los recursos administrativos, as\u00ed como de los monitoreos aleatorios preventivos que se realizan a los procedimientos gestionados en el Portal Transaccional. Dicha normativa va de la mano de la resoluci\u00f3n PNP-07-2020 que ordena a los comit\u00e9s de compras y contrataciones de las instituciones p\u00fablicas y los ayuntamientos, a designar peritos que intervendr\u00e1n en las fases de dise\u00f1o y evaluaci\u00f3n de los procedimientos de contrataci\u00f3n p\u00fablica. Seg\u00fan esta disposici\u00f3n emitida por el \u00f3rgano rector del sistema, las instituciones deber\u00e1n designar, al menos, tres peritos en cada procedimiento, con un perfil de especialistas legales, financieros y t\u00e9cnicos, seg\u00fan la complejidad y el objeto de la contrataci\u00f3n, para evaluar y emitir un informe t\u00e9cnico de las ofertas presentadas, de conformidad a los requerimientos establecidos en la base de contrataci\u00f3n. Entre otras cosas, el documento\u00a0plantea que las bases de la contrataci\u00f3n y el borrador de contrato establezcan de forma clara las condiciones y el tiempo de pago, as\u00ed como los tipos de garant\u00edas requeridas a los oferentes. Asimismo, insta a las instituciones a realizar consultas al mercado y llamados a manifestaci\u00f3n de inter\u00e9s, durante la fase de planificaci\u00f3n para determinar la forma m\u00e1s eficiente de satisfacer la necesidad de la entidad contratante, las caracter\u00edsticas del bien, servicio u obra a ser adquirido y obtener informacion acerca de las diferentes opciones o innovaciones en el mercado. &nbsp; &nbsp;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-109492","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/109492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=109492"}],"version-history":[{"count":2,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/109492\/revisions"}],"predecessor-version":[{"id":109495,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/109492\/revisions\/109495"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=109492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=109492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=109492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}