{"id":109716,"date":"2020-09-27T18:37:40","date_gmt":"2020-09-27T22:37:40","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=109716"},"modified":"2020-09-27T18:37:40","modified_gmt":"2020-09-27T22:37:40","slug":"trump-consigue-un-poder-judicial-a-su-medida-con-mayoria-conservadora","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2020\/09\/27\/trump-consigue-un-poder-judicial-a-su-medida-con-mayoria-conservadora\/","title":{"rendered":"Trump consigue un poder judicial a su medida con mayor\u00eda conservadora"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-109717 aligncenter\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2020\/09\/374e3f28-tribunal-supremo.jpg\" alt=\"\" width=\"620\" height=\"349\" \/>Donald Trump se dispone a ultimar el que ser\u00e1 sin duda el legado m\u00e1s duradero de su presidencia: una Corte Suprema a su medida.<\/p>\n<p>Cuando el presidente acabe su primer mandato, en enero, permanezca o no en la Casa Blanca, habr\u00e1 renovado un tercio de la m\u00e1xima instancia judicial de Estados Unidos con jueces conservadores, que ya conforman una clara mayor\u00eda de seis esca\u00f1os frente a tres.<\/p>\n<p>En tiempo r\u00e9cord, con el apoyo casi un\u00e1nime del Partido Republicano, el presidente se ha apresurado a nombrar una sustituta a Ruth Bader Ginsburg, fallecida hace apenas una semana, icono feminista de la izquierda estadounidense.<\/p>\n<p>La sustituta por la que se ha decantado Trump es Amy Coney Barrett, a la que \u00e9l mismo nombr\u00f3 jueza federal en 2017, una magistrada firmemente conservadora que ser\u00e1 la quinta mujer en ingresar en la bancada en toda su historia.<\/p>\n<p>Tras una semana de deliberaciones, el presidente anunci\u00f3 ayer su elecci\u00f3n en una ceremonia solemne en el rosal de la Casa Blanca, y pidi\u00f3 a los dem\u00f3cratas \u00abque le brinden a la jueza Barrett las vistas respetuosas y dignas que se merece y, francamente, que nuestro pa\u00eds se merece\u00bb.<\/p>\n<p>\u00abPido a los legisladores y los medios de comunicaci\u00f3n que se abstengan de ataques personales o partidistas. Los riesgos para nuestro pa\u00eds de ello son incre\u00edblemente altos\u00bb, a\u00f1adi\u00f3 el presidente.<\/p>\n<p>\u00abLa otra vez ya parec\u00eda f\u00e1cil\u00bb, brome\u00f3, en referencia al proceso de confirmaci\u00f3n, en 2018, del juez Brett Kavanaugh, que fue acusado de violaci\u00f3n y recibi\u00f3 el voto en contra de los dem\u00f3cratas .<\/p>\n<p>A Trump le acompa\u00f1\u00f3 la propia candidata, que vol\u00f3 a Washington desde Indiana con su familia.<\/p>\n<p>La jueza Barrett proclam\u00f3 su amor por su pa\u00eds y la Constituci\u00f3n y comenz\u00f3 su breve discurso rindiendo homenaje a la fallecida juez Ginsburg: \u00abNo s\u00f3lo rompi\u00f3 los techos de cristal, los pulveriz\u00f3\u00bb.<\/p>\n<p>Despu\u00e9s, prometi\u00f3 hacer justicia, si es confirmada para el Supremo, por encima de ideolog\u00edas y afinidades partidistas o personales.<\/p>\n<p>Fue una llamada a la concordia en toda regla: \u00abLas desavenencias sobre asuntos de gran enjundia no deben influir sobre el respeto mutuo\u00bb, dijo, antes de ponerse a disposici\u00f3n de los senadores para el proceso de confirmaci\u00f3n que ahora empieza en el Capitolio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Donald Trump se dispone a ultimar el que ser\u00e1 sin duda el legado m\u00e1s duradero de su presidencia: una Corte Suprema a su medida. Cuando el presidente acabe su primer mandato, en enero, permanezca o no en la Casa Blanca, habr\u00e1 renovado un tercio de la m\u00e1xima instancia judicial de Estados Unidos con jueces conservadores, que ya conforman una clara mayor\u00eda de seis esca\u00f1os frente a tres. En tiempo r\u00e9cord, con el apoyo casi un\u00e1nime del Partido Republicano, el presidente se ha apresurado a nombrar una sustituta a Ruth Bader Ginsburg, fallecida hace apenas una semana, icono feminista de la izquierda estadounidense. La sustituta por la que se ha decantado Trump es Amy Coney Barrett, a la que \u00e9l mismo nombr\u00f3 jueza federal en 2017, una magistrada firmemente conservadora que ser\u00e1 la quinta mujer en ingresar en la bancada en toda su historia. Tras una semana de deliberaciones, el presidente anunci\u00f3 ayer su elecci\u00f3n en una ceremonia solemne en el rosal de la Casa Blanca, y pidi\u00f3 a los dem\u00f3cratas \u00abque le brinden a la jueza Barrett las vistas respetuosas y dignas que se merece y, francamente, que nuestro pa\u00eds se merece\u00bb. \u00abPido a los legisladores y los medios de comunicaci\u00f3n que se abstengan de ataques personales o partidistas. Los riesgos para nuestro pa\u00eds de ello son incre\u00edblemente altos\u00bb, a\u00f1adi\u00f3 el presidente. \u00abLa otra vez ya parec\u00eda f\u00e1cil\u00bb, brome\u00f3, en referencia al proceso de confirmaci\u00f3n, en 2018, del juez Brett Kavanaugh, que fue acusado de violaci\u00f3n y recibi\u00f3 el voto en contra de los dem\u00f3cratas . A Trump le acompa\u00f1\u00f3 la propia candidata, que vol\u00f3 a Washington desde Indiana con su familia. La jueza Barrett proclam\u00f3 su amor por su pa\u00eds y la Constituci\u00f3n y comenz\u00f3 su breve discurso rindiendo homenaje a la fallecida juez Ginsburg: \u00abNo s\u00f3lo rompi\u00f3 los techos de cristal, los pulveriz\u00f3\u00bb. Despu\u00e9s, prometi\u00f3 hacer justicia, si es confirmada para el Supremo, por encima de ideolog\u00edas y afinidades partidistas o personales. Fue una llamada a la concordia en toda regla: \u00abLas desavenencias sobre asuntos de gran enjundia no deben influir sobre el respeto mutuo\u00bb, dijo, antes de ponerse a disposici\u00f3n de los senadores para el proceso de confirmaci\u00f3n que ahora empieza en el Capitolio.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-109716","post","type-post","status-publish","format-standard","hentry","category-culture"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/109716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=109716"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/109716\/revisions"}],"predecessor-version":[{"id":109718,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/109716\/revisions\/109718"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=109716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=109716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=109716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}