{"id":111018,"date":"2020-10-17T09:20:23","date_gmt":"2020-10-17T13:20:23","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=111018"},"modified":"2020-10-17T09:20:23","modified_gmt":"2020-10-17T13:20:23","slug":"mopc-remueve-escombros-de-vivienda-colapso-en-los-mameyes","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2020\/10\/17\/mopc-remueve-escombros-de-vivienda-colapso-en-los-mameyes\/","title":{"rendered":"MOPC remueve escombros de vivienda colaps\u00f3 en Los Mameyes"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-111019 aligncenter\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2020\/10\/196b3625-a47e-4240-891a-d0ccac13a993-800x600.jpg\" alt=\"\" width=\"800\" height=\"600\" \/>Eval\u00faa los da\u00f1os producidos por el derrumbe.<\/strong><br \/>\nAtendiendo a instrucciones del ministro Deligne Ascenci\u00f3n, una brigada de la Direcci\u00f3n de Equipos y Transporte del Ministerio de Obras P\u00fablicas dispuso este jueves la remoci\u00f3n de los escombros producidos por el derrumbe una edificaci\u00f3n que dej\u00f3 a la intemperie a varias familias y al menos ocho heridos en el sector Los Mameyes, municipio Santo Domingo Este.<br \/>\nLos residentes en las cuatro viviendas que resultaron destruidas por el derrumbe hab\u00edan solicitado a las autoridades acudir en su auxilio para la demolici\u00f3n de parte de la estructura, debido a que representaba un peligro para los residentes en el sector.<br \/>\nPersonal y equipos del MOPC respondieron al llamado que hicieran los afectados, acudieron en su auxilio, removiendo escombros de la edificaci\u00f3n que colaps\u00f3.<br \/>\nLa vivienda, de dos niveles, estaba ubicada en la calle Respaldo Gregorio Luper\u00f3n, de Los Mameyes.<br \/>\nEntre los heridos se encuentran dos menores de 5 y 9 a\u00f1os de edad, quienes fueron trasladados al hospital infantil Robert Reid Cabral, mientras que cuatro hombres y dos mujeres fueron trasladados a los hospitales Dar\u00edo Contreras y el Ney Arias Lora, todos con traumas m\u00faltiples.<br \/>\nEl MOPC inform\u00f3 que una comisi\u00f3n t\u00e9cnica de la instituci\u00f3n eval\u00faa los da\u00f1os producidos por el derrumbe, y que posteriormente rendir\u00e1 un informe para determinar el tipo de ayuda que ofrecer\u00e1 a las familias afectadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eval\u00faa los da\u00f1os producidos por el derrumbe. Atendiendo a instrucciones del ministro Deligne Ascenci\u00f3n, una brigada de la Direcci\u00f3n de Equipos y Transporte del Ministerio de Obras P\u00fablicas dispuso este jueves la remoci\u00f3n de los escombros producidos por el derrumbe una edificaci\u00f3n que dej\u00f3 a la intemperie a varias familias y al menos ocho heridos en el sector Los Mameyes, municipio Santo Domingo Este. Los residentes en las cuatro viviendas que resultaron destruidas por el derrumbe hab\u00edan solicitado a las autoridades acudir en su auxilio para la demolici\u00f3n de parte de la estructura, debido a que representaba un peligro para los residentes en el sector. Personal y equipos del MOPC respondieron al llamado que hicieran los afectados, acudieron en su auxilio, removiendo escombros de la edificaci\u00f3n que colaps\u00f3. La vivienda, de dos niveles, estaba ubicada en la calle Respaldo Gregorio Luper\u00f3n, de Los Mameyes. Entre los heridos se encuentran dos menores de 5 y 9 a\u00f1os de edad, quienes fueron trasladados al hospital infantil Robert Reid Cabral, mientras que cuatro hombres y dos mujeres fueron trasladados a los hospitales Dar\u00edo Contreras y el Ney Arias Lora, todos con traumas m\u00faltiples. El MOPC inform\u00f3 que una comisi\u00f3n t\u00e9cnica de la instituci\u00f3n eval\u00faa los da\u00f1os producidos por el derrumbe, y que posteriormente rendir\u00e1 un informe para determinar el tipo de ayuda que ofrecer\u00e1 a las familias afectadas.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-111018","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/111018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=111018"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/111018\/revisions"}],"predecessor-version":[{"id":111020,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/111018\/revisions\/111020"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=111018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=111018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=111018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}