{"id":111036,"date":"2020-10-18T09:55:43","date_gmt":"2020-10-18T13:55:43","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=111036"},"modified":"2020-10-18T09:55:43","modified_gmt":"2020-10-18T13:55:43","slug":"adn-continua-programa-de-reforestacion-en-las-tres-circunscripciones-de-la-capital","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2020\/10\/18\/adn-continua-programa-de-reforestacion-en-las-tres-circunscripciones-de-la-capital\/","title":{"rendered":"ADN contin\u00faa programa de reforestaci\u00f3n en las tres circunscripciones de la Capital"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-111037 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2020\/10\/WhatsApp-Image-2020-10-17-at-3.26.09-PM-2-600x800.jpg\" alt=\"\" width=\"293\" height=\"391\" \/>Se han sembrado especies nativas y eliminado vertederos improvisados\u00a0\u00a0<\/strong><\/p>\n<p>Santo Domingo, D.N.- La Alcald\u00eda del Distrito Nacional, a trav\u00e9s de la Direcci\u00f3n de Gesti\u00f3n Ambiental continu\u00f3 con el programa de reforestaci\u00f3n, con la siembra de 100 \u00e1rboles en distintos puntos de la ciudad.<\/p>\n<p>La Direcci\u00f3n de Foresta Urbana identific\u00f3 los puntos para eliminar islas de calor con la siembra de especies nativas y end\u00e9micas como el Alm\u00e1cigo, Penda y avellano criollo, adem\u00e1s ofrecen frutos aumentando la biodiversidad urbana.<\/p>\n<p>De acuerdo a los t\u00e9cnicos del ADN, con la siembra de esas especies se puede reducir un grado a la temperatura en este punto de la ciudad, como es en la ave M\u00e1ximo G\u00f3mez en el tramo de la 27 de Febrero hasta las John F Kennedy.<\/p>\n<p>Mientras, que en la avenida Privada esquina Enriquillo se sustituy\u00f3 un \u00e1rbol seco de acacia amarilla, especie introducida, por un \u00e1rbol end\u00e9mico de Almacigo.<\/p>\n<p>Asimismo, en la calle Manuela Diez, del sector Mar\u00eda Auxiliadora se plantaron \u00e1rboles de Almacigo y se procedi\u00f3 a eliminar un vertedero improvisado para dejar un espacio limpio, digno y arborizado.<\/p>\n<p>El ADN impulsar\u00e1 una jornada de reforestaci\u00f3n en forma simult\u00e1nea en las tres circunscripciones de la ciudad, hasta lograr el esplendor que requiere para mantener el equilibrio ambiental.<\/p>\n<p>Con esta jornada tambi\u00e9n se procura la sensibilizaci\u00f3n y movilizaci\u00f3n de la gente a favor del rescate de la biodiversidad, de cara a un centro urbano que a diario es bombardeado con di\u00f3xido de carbono fruto del parque vehicular, las industrias, y otros sectores.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se han sembrado especies nativas y eliminado vertederos improvisados\u00a0\u00a0 Santo Domingo, D.N.- La Alcald\u00eda del Distrito Nacional, a trav\u00e9s de la Direcci\u00f3n de Gesti\u00f3n Ambiental continu\u00f3 con el programa de reforestaci\u00f3n, con la siembra de 100 \u00e1rboles en distintos puntos de la ciudad. La Direcci\u00f3n de Foresta Urbana identific\u00f3 los puntos para eliminar islas de calor con la siembra de especies nativas y end\u00e9micas como el Alm\u00e1cigo, Penda y avellano criollo, adem\u00e1s ofrecen frutos aumentando la biodiversidad urbana. De acuerdo a los t\u00e9cnicos del ADN, con la siembra de esas especies se puede reducir un grado a la temperatura en este punto de la ciudad, como es en la ave M\u00e1ximo G\u00f3mez en el tramo de la 27 de Febrero hasta las John F Kennedy. Mientras, que en la avenida Privada esquina Enriquillo se sustituy\u00f3 un \u00e1rbol seco de acacia amarilla, especie introducida, por un \u00e1rbol end\u00e9mico de Almacigo. Asimismo, en la calle Manuela Diez, del sector Mar\u00eda Auxiliadora se plantaron \u00e1rboles de Almacigo y se procedi\u00f3 a eliminar un vertedero improvisado para dejar un espacio limpio, digno y arborizado. El ADN impulsar\u00e1 una jornada de reforestaci\u00f3n en forma simult\u00e1nea en las tres circunscripciones de la ciudad, hasta lograr el esplendor que requiere para mantener el equilibrio ambiental. Con esta jornada tambi\u00e9n se procura la sensibilizaci\u00f3n y movilizaci\u00f3n de la gente a favor del rescate de la biodiversidad, de cara a un centro urbano que a diario es bombardeado con di\u00f3xido de carbono fruto del parque vehicular, las industrias, y otros sectores. &nbsp;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-111036","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/111036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=111036"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/111036\/revisions"}],"predecessor-version":[{"id":111038,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/111036\/revisions\/111038"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=111036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=111036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=111036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}