{"id":112592,"date":"2020-11-19T18:43:51","date_gmt":"2020-11-19T22:43:51","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=112592"},"modified":"2020-11-19T18:43:51","modified_gmt":"2020-11-19T22:43:51","slug":"gobierno-pone-en-operacion-servicio-9-1-1-en-valverde-para-atencion-de-salud-y-seguridad-a-173000-habitantes","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2020\/11\/19\/gobierno-pone-en-operacion-servicio-9-1-1-en-valverde-para-atencion-de-salud-y-seguridad-a-173000-habitantes\/","title":{"rendered":"Gobierno pone en operaci\u00f3n servicio 9- 1- 1 en Valverde para atenci\u00f3n de salud y seguridad a 173,000 habitantes"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-112593 aligncenter\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2020\/11\/eea7f2f9-6d67-4255-93fd-9bbd61ed0deb-800x533.jpg\" alt=\"\" width=\"800\" height=\"533\" \/>El presidente Abinader resalta objetivo de servir y proteger la gente<\/strong><\/p>\n<p>Mao, Valverde.- El presidente Luis Abinader dej\u00f3 en operaciones este jueves el Sistema Nacional de Atenci\u00f3n a Emergencias y Seguridad 9- 1- 1 en esta provincia, que ofrecer\u00e1 servicios sanitarios, de seguridad, en incidentes en carretera o incendios a unos 173 mil habitantes.<\/p>\n<p>El gobernante anunci\u00f3 la movilizaci\u00f3n de m\u00e1s de 500 profesionales para garantizar un servicio a la altura de las necesidades.<\/p>\n<p>Para tales fines, inform\u00f3 que el Servicio Nacional de Salud (SNS) incorporar\u00e1 a 29 m\u00e9dicos, 29 enfermeras, 80 param\u00e9dicos y 115 t\u00e9cnicos en transporte sanitario, para conducir 15 ambulancias, as\u00ed como a 15 motocicletas ambulancias.<\/p>\n<p>En el \u00e1mbito de la seguridad, dijo que refuerzan y ampl\u00edan las posibilidades, con la suma de 120 agentes de la Polic\u00eda Nacional que contar\u00e1n la tecnolog\u00eda y el liderazgo del sistema 911.<\/p>\n<p>Agreg\u00f3 que esto mejorar\u00e1 los incidentes relacionados con el tr\u00e1nsito, porque se suman 28 agentes m\u00e1s de la Direcci\u00f3n General de Seguridad de Tr\u00e1nsito y Transporte Terrestre.<\/p>\n<p>Resalt\u00f3 que el Ministerio de Obras P\u00fablicas y Comunicaciones incorpora a la provincia 37 colaboradores, 6 unidades patrulleras, 1 ambulancia, una gr\u00faa y un taller m\u00f3vil.<\/p>\n<p>\u201cA partir de ahora, los habitantes Valverde y sus municipios van a contar con un servicio de atenci\u00f3n que garantiza su vida y seguridad\u201d, manifest\u00f3 Abinader.<\/p>\n<p>Afirm\u00f3 que desde el gobierno no descansar\u00e1n hasta que el 9-1-1 llegue cada vez a m\u00e1s dominicanos y dominicanas, por el marco inter\u00e9s de servir a la gente.<\/p>\n<p>Record\u00f3 que a la fecha, el servicio alcanza el 89.4% de la poblaci\u00f3n nacional.<\/p>\n<p>Destac\u00f3 el trabajo altamente profesional que realizan integrantes del 9-1-1, los que con los medios materiales que tienen a disposici\u00f3n garantizar una atenci\u00f3n r\u00e1pida, profesional y eficiente a una situaci\u00f3n de riesgo que se presente a cualquier ciudadano.<\/p>\n<p>En tanto Vicente Mota Molina, director del 911, resalt\u00f3 la importancia de que este servicio llegue a municipios Mao, Esperanza y Laguna Salada.<\/p>\n<p>En el acto participaron los ministros de la Presidencia, Lisandro Macarrulla Salud P\u00fablica, Plutarco Arias y Defensa, teniente general Carlos Luciano D\u00edaz Morfa.<\/p>\n<p>Adem\u00e1s, los directores de la Polic\u00eda Nacional, mayor general Edward S\u00e1nchez Gonz\u00e1lez; del Servicio Nacional de Salud, doctor Mario Lama, as\u00ed como la gobernadora de Valverde,<br \/>\nDaysi Aquino Mesa.<\/p>\n<p>Tambi\u00e9n asistieron los senadores de Valverde, Eddy Nolasco; de Monte Cristi, Ram\u00f3n Antonio Pimentel G\u00f3mez (Moreno Arias), y de Santiago Rodr\u00edguez, Antonio Marte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Abinader resalta objetivo de servir y proteger la gente Mao, Valverde.- El presidente Luis Abinader dej\u00f3 en operaciones este jueves el Sistema Nacional de Atenci\u00f3n a Emergencias y Seguridad 9- 1- 1 en esta provincia, que ofrecer\u00e1 servicios sanitarios, de seguridad, en incidentes en carretera o incendios a unos 173 mil habitantes. El gobernante anunci\u00f3 la movilizaci\u00f3n de m\u00e1s de 500 profesionales para garantizar un servicio a la altura de las necesidades. Para tales fines, inform\u00f3 que el Servicio Nacional de Salud (SNS) incorporar\u00e1 a 29 m\u00e9dicos, 29 enfermeras, 80 param\u00e9dicos y 115 t\u00e9cnicos en transporte sanitario, para conducir 15 ambulancias, as\u00ed como a 15 motocicletas ambulancias. En el \u00e1mbito de la seguridad, dijo que refuerzan y ampl\u00edan las posibilidades, con la suma de 120 agentes de la Polic\u00eda Nacional que contar\u00e1n la tecnolog\u00eda y el liderazgo del sistema 911. Agreg\u00f3 que esto mejorar\u00e1 los incidentes relacionados con el tr\u00e1nsito, porque se suman 28 agentes m\u00e1s de la Direcci\u00f3n General de Seguridad de Tr\u00e1nsito y Transporte Terrestre. Resalt\u00f3 que el Ministerio de Obras P\u00fablicas y Comunicaciones incorpora a la provincia 37 colaboradores, 6 unidades patrulleras, 1 ambulancia, una gr\u00faa y un taller m\u00f3vil. \u201cA partir de ahora, los habitantes Valverde y sus municipios van a contar con un servicio de atenci\u00f3n que garantiza su vida y seguridad\u201d, manifest\u00f3 Abinader. Afirm\u00f3 que desde el gobierno no descansar\u00e1n hasta que el 9-1-1 llegue cada vez a m\u00e1s dominicanos y dominicanas, por el marco inter\u00e9s de servir a la gente. Record\u00f3 que a la fecha, el servicio alcanza el 89.4% de la poblaci\u00f3n nacional. Destac\u00f3 el trabajo altamente profesional que realizan integrantes del 9-1-1, los que con los medios materiales que tienen a disposici\u00f3n garantizar una atenci\u00f3n r\u00e1pida, profesional y eficiente a una situaci\u00f3n de riesgo que se presente a cualquier ciudadano. En tanto Vicente Mota Molina, director del 911, resalt\u00f3 la importancia de que este servicio llegue a municipios Mao, Esperanza y Laguna Salada. En el acto participaron los ministros de la Presidencia, Lisandro Macarrulla Salud P\u00fablica, Plutarco Arias y Defensa, teniente general Carlos Luciano D\u00edaz Morfa. Adem\u00e1s, los directores de la Polic\u00eda Nacional, mayor general Edward S\u00e1nchez Gonz\u00e1lez; del Servicio Nacional de Salud, doctor Mario Lama, as\u00ed como la gobernadora de Valverde, Daysi Aquino Mesa. Tambi\u00e9n asistieron los senadores de Valverde, Eddy Nolasco; de Monte Cristi, Ram\u00f3n Antonio Pimentel G\u00f3mez (Moreno Arias), y de Santiago Rodr\u00edguez, Antonio Marte.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-112592","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/112592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=112592"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/112592\/revisions"}],"predecessor-version":[{"id":112594,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/112592\/revisions\/112594"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=112592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=112592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=112592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}