{"id":114389,"date":"2020-12-29T20:58:15","date_gmt":"2020-12-30T00:58:15","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=114389"},"modified":"2020-12-29T20:58:15","modified_gmt":"2020-12-30T00:58:15","slug":"hospital-ney-arias-preparado-para-brindar-asistencia-durante-segunda-fase-de-operativo-navideno","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2020\/12\/29\/hospital-ney-arias-preparado-para-brindar-asistencia-durante-segunda-fase-de-operativo-navideno\/","title":{"rendered":"Hospital Ney Arias preparado para brindar asistencia durante segunda fase de Operativo Navide\u00f1o"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-114390 aligncenter\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2020\/12\/thumbnail_Fachada-800x575.jpg\" alt=\"\" width=\"800\" height=\"575\" \/>SANTO DOMINGO.-\u00a0El director del Hospital Traumatol\u00f3gico Doctor Ney Arias Lora, Doctor Julio Landr\u00f3n,\u00a0 asegur\u00f3 que el centro de salud est\u00e1 preparado para brindar asistencia r\u00e1pida y oportuna ante cualquier eventualidad que se presente durante esta segunda fase del operativo navide\u00f1o.<\/p>\n<p>Landr\u00f3n,\u00a0 revel\u00f3 que durante la primera fase del operativo el centro mantuvo total control de sus operaciones, debido a esto se encuentran disponibles unas 36 camas y con los operativos quir\u00fargicos que se estar\u00e1n realizando en los d\u00edas previos a las festividades de a\u00f1o nuevo se tiene estimado que se habiliten unas 60 camas para enfrentar cualquier eventualidad.<\/p>\n<p>\u201cLa disponibilidad en el centro se da debido al reforzamiento en las diferentes \u00e1reas, sum\u00e1ndole a esto que no nos detuvimos de operar a los pacientes a pesar de que son d\u00edas de recogimiento, adem\u00e1s de que estamos operando entre hoy y ma\u00f1ana a los pacientes que llegaron con alg\u00fan trauma durante las festividades pasadas\u201d agreg\u00f3 el doctor Landr\u00f3n, quien tambi\u00e9n es el presidente de la Sociedad Dominicana de Ortopedia.<\/p>\n<p>El especialista record\u00f3 que se mantienen reforzados los servicios de emergencia, cirug\u00edas y cuidados intensivos, as\u00ed como el total abastecimiento del centro para poder asistir ante cualquier situaci\u00f3n.<\/p>\n<p>\u201cNos acabamos de abastecer a mediado de diciembre, estos insumos son para los siguientes tres meses como nos especifica el Servicio Nacional de Salud, lo que quiere decir que tenemos una capacidad completa en nuestros almacenes para dar respuesta a los pacientes tengan o no seguro m\u00e9dico\u201d puntualiz\u00f3 el especialista<\/p>\n<p>Landr\u00f3n,\u00a0 puntualiz\u00f3 que aunque el centro no es un hospital de COVID se les est\u00e1 realizando las pruebas a todos los pacientes que llegan traumatizados y que ser\u00e1n ingresados al centro, adem\u00e1s de mantener todos los protocolos de seguridad establecidos por las autoridades de salud.<\/p>\n<p>El director del establecimiento de salud,\u00a0 exhort\u00f3 a la poblaci\u00f3n a ser comedidos, a tratar de proteger a las familias y asumir la responsabilidad a la hora de salir a transitar en un veh\u00edculo de motor, llam\u00f3 adem\u00e1s a respetar las leyes de tr\u00e1nsito, a no tomar mientras se conduce, a usar el casco protector y evitar accidentes para poder pasar las festividades en armon\u00eda y paz.<\/p>\n<p>Landr\u00f3n de la Rosa,\u00a0 agradeci\u00f3 los esfuerzos del presidente Luis Abinader, por mejorar la calidad y el acceso a la salud del pueblo dominicano y por el compromiso que ha adoptado desde que asumi\u00f3 la presidencia.<\/p>\n<p>De igual forma al director del Servicio Nacional de Salud, doctor Mario Lama y al director del Servicio Regional de Salud Metropolitano (SRSM), doctor Edisson Feliz por la confianza y el apoyo dado para mejorar y los servicios ofrecidos en el centro<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.-\u00a0El director del Hospital Traumatol\u00f3gico Doctor Ney Arias Lora, Doctor Julio Landr\u00f3n,\u00a0 asegur\u00f3 que el centro de salud est\u00e1 preparado para brindar asistencia r\u00e1pida y oportuna ante cualquier eventualidad que se presente durante esta segunda fase del operativo navide\u00f1o. Landr\u00f3n,\u00a0 revel\u00f3 que durante la primera fase del operativo el centro mantuvo total control de sus operaciones, debido a esto se encuentran disponibles unas 36 camas y con los operativos quir\u00fargicos que se estar\u00e1n realizando en los d\u00edas previos a las festividades de a\u00f1o nuevo se tiene estimado que se habiliten unas 60 camas para enfrentar cualquier eventualidad. \u201cLa disponibilidad en el centro se da debido al reforzamiento en las diferentes \u00e1reas, sum\u00e1ndole a esto que no nos detuvimos de operar a los pacientes a pesar de que son d\u00edas de recogimiento, adem\u00e1s de que estamos operando entre hoy y ma\u00f1ana a los pacientes que llegaron con alg\u00fan trauma durante las festividades pasadas\u201d agreg\u00f3 el doctor Landr\u00f3n, quien tambi\u00e9n es el presidente de la Sociedad Dominicana de Ortopedia. El especialista record\u00f3 que se mantienen reforzados los servicios de emergencia, cirug\u00edas y cuidados intensivos, as\u00ed como el total abastecimiento del centro para poder asistir ante cualquier situaci\u00f3n. \u201cNos acabamos de abastecer a mediado de diciembre, estos insumos son para los siguientes tres meses como nos especifica el Servicio Nacional de Salud, lo que quiere decir que tenemos una capacidad completa en nuestros almacenes para dar respuesta a los pacientes tengan o no seguro m\u00e9dico\u201d puntualiz\u00f3 el especialista Landr\u00f3n,\u00a0 puntualiz\u00f3 que aunque el centro no es un hospital de COVID se les est\u00e1 realizando las pruebas a todos los pacientes que llegan traumatizados y que ser\u00e1n ingresados al centro, adem\u00e1s de mantener todos los protocolos de seguridad establecidos por las autoridades de salud. El director del establecimiento de salud,\u00a0 exhort\u00f3 a la poblaci\u00f3n a ser comedidos, a tratar de proteger a las familias y asumir la responsabilidad a la hora de salir a transitar en un veh\u00edculo de motor, llam\u00f3 adem\u00e1s a respetar las leyes de tr\u00e1nsito, a no tomar mientras se conduce, a usar el casco protector y evitar accidentes para poder pasar las festividades en armon\u00eda y paz. Landr\u00f3n de la Rosa,\u00a0 agradeci\u00f3 los esfuerzos del presidente Luis Abinader, por mejorar la calidad y el acceso a la salud del pueblo dominicano y por el compromiso que ha adoptado desde que asumi\u00f3 la presidencia. De igual forma al director del Servicio Nacional de Salud, doctor Mario Lama y al director del Servicio Regional de Salud Metropolitano (SRSM), doctor Edisson Feliz por la confianza y el apoyo dado para mejorar y los servicios ofrecidos en el centro<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-114389","post","type-post","status-publish","format-standard","hentry","category-nature"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/114389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=114389"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/114389\/revisions"}],"predecessor-version":[{"id":114391,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/114389\/revisions\/114391"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=114389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=114389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=114389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}