{"id":115081,"date":"2021-01-27T00:39:42","date_gmt":"2021-01-27T04:39:42","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=115081"},"modified":"2021-01-27T00:39:42","modified_gmt":"2021-01-27T04:39:42","slug":"ministerio-de-educacion-dona-200-libros-infantiles-a-dos-fundaciones-como-parte-de-la-iniciativa-punto-de-lectura-2","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2021\/01\/27\/ministerio-de-educacion-dona-200-libros-infantiles-a-dos-fundaciones-como-parte-de-la-iniciativa-punto-de-lectura-2\/","title":{"rendered":"Ministerio de Educaci\u00f3n dona 200 libros infantiles a dos fundaciones como parte de la iniciativa Punto de Lectura"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-115082 aligncenter\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2021\/01\/thumbnail__DSC9487-800x635.jpg\" alt=\"\" width=\"800\" height=\"635\" \/>Santo Domingo.\u00a0El Ministerio de Educaci\u00f3n, a trav\u00e9s de la Direcci\u00f3n General de Cultura, entreg\u00f3 200 libros de literatura infantil y juvenil a las fundaciones Acci\u00f3n Solidaria para la Provincia Bahoruco (ASOPROBA) y Lucas Fern\u00e1ndez Inc., con el objetivo de continuar fomentando el inter\u00e9s por la lectura en el sistema educativo y en las instituciones que trabajan con la cultura y la educaci\u00f3n.<\/p>\n<p>Durante la donaci\u00f3n, que se realiz\u00f3 en el Punto de Lectura, ubicado en el lobby de la sede central de MINERD, Luis R. Santos, director general de Cultura, dijo que \u201cAdem\u00e1s de fomentar la lectura, esta entrega de libros es parte de las\u00a0iniciativas que conlleva la creaci\u00f3n de los Puntos de Lectura. Nos adentramos ya en la formaci\u00f3n de mediadores de lectura, clubes de lectura, talleres literarios, charlas, conferencias, seminarios para poner el libro m\u00e1s cerca\u201d.<\/p>\n<p>Santos expres\u00f3 que leer promueve el cambio y es un eje transversal en materia educativa, de ah\u00ed el gran esfuerzo que est\u00e1 haciendo el ministro Roberto Fulcar para impulsar la lectura en todos los \u00e1mbitos de la sociedad. Explic\u00f3 que las entregas se realizan atendiendo al orden de las solicitudes que se reciben y la disponibilidad de textos.<\/p>\n<p>Exhort\u00f3 a las fundaciones beneficiarias a continuar trabajando para contribuir con el desarrollo y aprendizaje de sus comunidades.<\/p>\n<p>Al recibir la donaci\u00f3n, Carlos Ferm\u00edn Tejeda, presidente de la fundaci\u00f3n ASOPROBA, agradeci\u00f3 el aporte y dijo que \u201ccontribuir\u00e1 a incentivar el amor por los libros y la lectura en la ni\u00f1ez de la provincia Bahoruco\u201d.<\/p>\n<p>Para Rosa Fern\u00e1ndez, representante de la Fundaci\u00f3n Lucas Fern\u00e1ndez Inc., ubicada en el sector Los Invasores de Invivienda en Santo Domingo Este, y que trabaja con ni\u00f1os, ni\u00f1as y adolescentes \u201cesta donaci\u00f3n contribuye a llenar de manera positiva el tiempo de ocio en estos momentos de pandemia fomentando el amor por la lectura en esa poblaci\u00f3n\u201d.<\/p>\n<p>El Ministerio de Educaci\u00f3n desde el a\u00f1o pasado puso en funcionamiento el primer Punto de Lectura en las instalaciones del MINERD, una peque\u00f1a biblioteca con t\u00edtulos y g\u00e9neros diversos al alcance, en esta primera fase, del personal de la sede, en procura de que el libro sea un producto de f\u00e1cil acceso para la mayor\u00eda de la poblaci\u00f3n, tanto en la modalidad impresa como digital.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.\u00a0El Ministerio de Educaci\u00f3n, a trav\u00e9s de la Direcci\u00f3n General de Cultura, entreg\u00f3 200 libros de literatura infantil y juvenil a las fundaciones Acci\u00f3n Solidaria para la Provincia Bahoruco (ASOPROBA) y Lucas Fern\u00e1ndez Inc., con el objetivo de continuar fomentando el inter\u00e9s por la lectura en el sistema educativo y en las instituciones que trabajan con la cultura y la educaci\u00f3n. Durante la donaci\u00f3n, que se realiz\u00f3 en el Punto de Lectura, ubicado en el lobby de la sede central de MINERD, Luis R. Santos, director general de Cultura, dijo que \u201cAdem\u00e1s de fomentar la lectura, esta entrega de libros es parte de las\u00a0iniciativas que conlleva la creaci\u00f3n de los Puntos de Lectura. Nos adentramos ya en la formaci\u00f3n de mediadores de lectura, clubes de lectura, talleres literarios, charlas, conferencias, seminarios para poner el libro m\u00e1s cerca\u201d. Santos expres\u00f3 que leer promueve el cambio y es un eje transversal en materia educativa, de ah\u00ed el gran esfuerzo que est\u00e1 haciendo el ministro Roberto Fulcar para impulsar la lectura en todos los \u00e1mbitos de la sociedad. Explic\u00f3 que las entregas se realizan atendiendo al orden de las solicitudes que se reciben y la disponibilidad de textos. Exhort\u00f3 a las fundaciones beneficiarias a continuar trabajando para contribuir con el desarrollo y aprendizaje de sus comunidades. Al recibir la donaci\u00f3n, Carlos Ferm\u00edn Tejeda, presidente de la fundaci\u00f3n ASOPROBA, agradeci\u00f3 el aporte y dijo que \u201ccontribuir\u00e1 a incentivar el amor por los libros y la lectura en la ni\u00f1ez de la provincia Bahoruco\u201d. Para Rosa Fern\u00e1ndez, representante de la Fundaci\u00f3n Lucas Fern\u00e1ndez Inc., ubicada en el sector Los Invasores de Invivienda en Santo Domingo Este, y que trabaja con ni\u00f1os, ni\u00f1as y adolescentes \u201cesta donaci\u00f3n contribuye a llenar de manera positiva el tiempo de ocio en estos momentos de pandemia fomentando el amor por la lectura en esa poblaci\u00f3n\u201d. El Ministerio de Educaci\u00f3n desde el a\u00f1o pasado puso en funcionamiento el primer Punto de Lectura en las instalaciones del MINERD, una peque\u00f1a biblioteca con t\u00edtulos y g\u00e9neros diversos al alcance, en esta primera fase, del personal de la sede, en procura de que el libro sea un producto de f\u00e1cil acceso para la mayor\u00eda de la poblaci\u00f3n, tanto en la modalidad impresa como digital. &nbsp;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-115081","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/115081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=115081"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/115081\/revisions"}],"predecessor-version":[{"id":115083,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/115081\/revisions\/115083"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=115081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=115081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=115081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}