{"id":117115,"date":"2021-03-30T16:53:42","date_gmt":"2021-03-30T20:53:42","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=117115"},"modified":"2021-03-30T16:53:42","modified_gmt":"2021-03-30T20:53:42","slug":"obras-publicas-garantiza-continuidad-y-mejoria-del-programa-de-asistencia-vial","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2021\/03\/30\/obras-publicas-garantiza-continuidad-y-mejoria-del-programa-de-asistencia-vial\/","title":{"rendered":"Obras P\u00fablicas garantiza continuidad y mejor\u00eda del programa de Asistencia Vial."},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-117116 aligncenter\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2021\/03\/e8b97529-637f-4e38-91e8-ae05618a4c6a.jpg\" alt=\"\" width=\"545\" height=\"370\" \/>Anuncia apoyo al operativo del COE \u00bb Compromiso por la vida, Semana Santa 2021&#8243;.<\/strong><\/p>\n<p>SANTO DOMINGO. El Ministerio de Obras P\u00fablicas y Comunicaciones garantiz\u00f3 los servicios que brinda a los conductores que se desplazan por las carreteras y autopistas del pa\u00eds a trav\u00e9s del Programa de Asistencia Vial y garantiz\u00f3 su ampliaci\u00f3n y mejor\u00eda.<br \/>\nEn un documento de prensa dado a conocer este martes, el ministro, ingeniero Deligne Ascenci\u00f3n expres\u00f3 que: \u201cestamos comprometidos en ofrecer un servicio, cada vez de mejor calidad a los conductores, brind\u00e1ndoles la protecci\u00f3n que como seres humanos tienen derechos, en cualquier inconveniente que presenten en las distintas v\u00edas por donde transiten.<br \/>\n\u201cNuestra meta es reducir los accidentes y proteger la vida de quienes transiten por las v\u00edas\u201d. Expresa el ministro.<br \/>\nResalta que: \u201ca trav\u00e9s del programa de Asistencia Vial, el Ministerio de Obras P\u00fablicas y Comunicaciones, continuar\u00e1 ofreciendo ayuda a los conductores que con todo su derecho requieran nuestros servicios en las carreteras, a los cuales est\u00e1n comprometidos en mejorar su calidad\u201d.<br \/>\nEstablecen que una de las metas de este gobierno que encabeza el presidente Luis Abinader, es incrementar la cantidad y calidad de los servicios que est\u00e1n dentro del Programa de Asistencia Vial, consciente de la importancia de la seguridad que ameritan los usuarios de las autopistas y carreteras del pa\u00eds.<br \/>\nLos servicios que brindan estas unidades patrulleras son: extracci\u00f3n vehicular, talleres y gomeros m\u00f3viles, suministro de combustible en caso de que el conductor lo necesite, gr\u00faas, ambulancias, servicios m\u00e9dicos y pre hospitalarios, entre otros.<br \/>\nEn ese sentido, el ingeniero Deligne Ascenci\u00f3n dijo que con motivo de los d\u00edas de asueto de la Semana Santa y en apoyo al Centro de Operaciones de Emergencia (COE), el Ministerio de Obras P\u00fablicas y Comunicaciones dispondr\u00e1 de 1,150 hombres bien entrenados y capacitados y 398 veh\u00edculos, que estar\u00e1n disponibles para auxiliar a los conductores que lo necesiten.<br \/>\nAgreg\u00f3 que un total de 336 camionetas patrulleras estar\u00e1n en las carreteras y autopistas, as\u00ed como 36 ambulancias, 36 gr\u00faas, cinco unidades de extracci\u00f3n, 18 talleres m\u00f3viles y gomeros, 67 motocicletas, lo hace un total de 398 veh\u00edculos.<br \/>\n\u201cLa tarea inmediata es optimizar los servicios que brinda el Programa de Asistencia Vial y ayudar a evitar accidentes de tr\u00e1nsito en las carreteras, dijo Ascenci\u00f3n.<br \/>\n\u201cSeguiremos cumpliendo con nuestro rol de brindar asistencia a quienes lo necesiten en las carreteras y autopistas del pa\u00eds, vamos a optimizar el servicio y reiterar que todos los conductores que confronten problemas, solo tienen que llamar a nuestro call center: 829-688-1000, para recibir asistencia de nuestras unidades\u201d, puntualiz\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anuncia apoyo al operativo del COE \u00bb Compromiso por la vida, Semana Santa 2021&#8243;. SANTO DOMINGO. El Ministerio de Obras P\u00fablicas y Comunicaciones garantiz\u00f3 los servicios que brinda a los conductores que se desplazan por las carreteras y autopistas del pa\u00eds a trav\u00e9s del Programa de Asistencia Vial y garantiz\u00f3 su ampliaci\u00f3n y mejor\u00eda. En un documento de prensa dado a conocer este martes, el ministro, ingeniero Deligne Ascenci\u00f3n expres\u00f3 que: \u201cestamos comprometidos en ofrecer un servicio, cada vez de mejor calidad a los conductores, brind\u00e1ndoles la protecci\u00f3n que como seres humanos tienen derechos, en cualquier inconveniente que presenten en las distintas v\u00edas por donde transiten. \u201cNuestra meta es reducir los accidentes y proteger la vida de quienes transiten por las v\u00edas\u201d. Expresa el ministro. Resalta que: \u201ca trav\u00e9s del programa de Asistencia Vial, el Ministerio de Obras P\u00fablicas y Comunicaciones, continuar\u00e1 ofreciendo ayuda a los conductores que con todo su derecho requieran nuestros servicios en las carreteras, a los cuales est\u00e1n comprometidos en mejorar su calidad\u201d. Establecen que una de las metas de este gobierno que encabeza el presidente Luis Abinader, es incrementar la cantidad y calidad de los servicios que est\u00e1n dentro del Programa de Asistencia Vial, consciente de la importancia de la seguridad que ameritan los usuarios de las autopistas y carreteras del pa\u00eds. Los servicios que brindan estas unidades patrulleras son: extracci\u00f3n vehicular, talleres y gomeros m\u00f3viles, suministro de combustible en caso de que el conductor lo necesite, gr\u00faas, ambulancias, servicios m\u00e9dicos y pre hospitalarios, entre otros. En ese sentido, el ingeniero Deligne Ascenci\u00f3n dijo que con motivo de los d\u00edas de asueto de la Semana Santa y en apoyo al Centro de Operaciones de Emergencia (COE), el Ministerio de Obras P\u00fablicas y Comunicaciones dispondr\u00e1 de 1,150 hombres bien entrenados y capacitados y 398 veh\u00edculos, que estar\u00e1n disponibles para auxiliar a los conductores que lo necesiten. Agreg\u00f3 que un total de 336 camionetas patrulleras estar\u00e1n en las carreteras y autopistas, as\u00ed como 36 ambulancias, 36 gr\u00faas, cinco unidades de extracci\u00f3n, 18 talleres m\u00f3viles y gomeros, 67 motocicletas, lo hace un total de 398 veh\u00edculos. \u201cLa tarea inmediata es optimizar los servicios que brinda el Programa de Asistencia Vial y ayudar a evitar accidentes de tr\u00e1nsito en las carreteras, dijo Ascenci\u00f3n. \u201cSeguiremos cumpliendo con nuestro rol de brindar asistencia a quienes lo necesiten en las carreteras y autopistas del pa\u00eds, vamos a optimizar el servicio y reiterar que todos los conductores que confronten problemas, solo tienen que llamar a nuestro call center: 829-688-1000, para recibir asistencia de nuestras unidades\u201d, puntualiz\u00f3.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-117115","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/117115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=117115"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/117115\/revisions"}],"predecessor-version":[{"id":117117,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/117115\/revisions\/117117"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=117115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=117115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=117115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}