{"id":121239,"date":"2021-11-03T14:41:21","date_gmt":"2021-11-03T18:41:21","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=121239"},"modified":"2021-11-03T14:41:21","modified_gmt":"2021-11-03T18:41:21","slug":"alcaldesa-carolina-mejia-llega-a-madrid-para-participar-en-reunion-de-alcaldes-iberoamericanos","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2021\/11\/03\/alcaldesa-carolina-mejia-llega-a-madrid-para-participar-en-reunion-de-alcaldes-iberoamericanos\/","title":{"rendered":"Alcaldesa Carolina Mej\u00eda llega a Madrid para participar en reuni\u00f3n de alcaldes iberoamericanos\u00a0"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-121240 aligncenter\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2021\/11\/thumbnail_WhatsApp-Image-2021-11-02-at-12.10.31-PM-800x533.jpg\" alt=\"\" width=\"800\" height=\"533\" \/>Santo Domingo.- La alcaldesa del Distrito Nacional, Carolina Mej\u00eda, lleg\u00f3 este martes a Madrid, Espa\u00f1a, donde participar\u00e1 de la XIX Asamblea General de la Uni\u00f3n de Ciudades Capitales Iberoamericanas en la que los l\u00edderes y lideresas realizar\u00e1n una serie de di\u00e1logos en torno a diversos temas sobre el futuro de la regi\u00f3n.<\/p>\n<p>El encuentro, organizado por la Uni\u00f3n de Ciudades Capitales Iberoamericanas (UCCI), se llevar\u00e1 a cabo bajo el lema, \u201cCiudades por Iberoam\u00e9rica: El futuro que nos une\u201d, y en este debatir\u00e1n sobre c\u00f3mo encarar el futuro de las capitales iberoamericanas y las necesidades derivadas del nuevo contexto mundial generado por la pandemia.<\/p>\n<p>Entre los temas a abordar por los l\u00edderes y lideresas de las 29 ciudades que conforman la UCCI se destacan la recuperaci\u00f3n econ\u00f3mica y social de las ciudades iberoamericanas, debatir\u00e1n acerca del plan estrat\u00e9gico que definir\u00e1 las l\u00edneas de trabajo hasta el 2023, tambi\u00e9n, ser\u00e1n elegidas las nuevas autoridades que presidir\u00e1n la UCCI.<\/p>\n<p>De igual forma se conocer\u00e1 la iniciativa propuesta por la alcaldesa Mej\u00eda, la cual present\u00f3 por primera ocasi\u00f3n en septiembre pasado en la asamblea de UCCI celebrada en San Juan, Puerto Rico. La misma se denomina \u201cIniciativa por las aceras de las capitales de Centroam\u00e9rica, M\u00e9xico y el Caribe como garantes de derechos constitucionales, calidad de vida y desarrollo econ\u00f3mico urbano\u201d, y busca crear las condiciones para devolver la ciudad a la gente, promoviendo la caminabilidad en las ciudades, la calidad de vida y el desarrollo urbano.<\/p>\n<p>\u201cEn septiembre present\u00e9 en la Asamblea Regional de la Uni\u00f3n de Ciudades Capitales Iberoam\u00e9ricanas (UCCI) todo lo que en este dif\u00edcil tiempo hemos aprendido gracias a la participaci\u00f3n ciudadana y las consultas a expertos, y propuse una iniciativa regional para que las dem\u00e1s ciudades capitales se unan en una nueva visi\u00f3n de nuestras ciudades; una en la que las personas tengan, entre otras cosas, una experiencia peatonal grata y segura, priorizando las poblaciones m\u00e1s necesitadas y los centros urbanos\u201d, destac\u00f3 la funcionaria.\u00a0Esta asamblea, la cual estar\u00e1 presidida por el alcalde de Madrid, Jos\u00e9 Luis Mart\u00ednez-Almeida, busca continuar fortaleciendo los gobiernos locales a trav\u00e9s de la innovaci\u00f3n y la cooperaci\u00f3n, favoreciendo al crecimiento econ\u00f3mico y social de las ciudades y sus habitantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.- La alcaldesa del Distrito Nacional, Carolina Mej\u00eda, lleg\u00f3 este martes a Madrid, Espa\u00f1a, donde participar\u00e1 de la XIX Asamblea General de la Uni\u00f3n de Ciudades Capitales Iberoamericanas en la que los l\u00edderes y lideresas realizar\u00e1n una serie de di\u00e1logos en torno a diversos temas sobre el futuro de la regi\u00f3n. El encuentro, organizado por la Uni\u00f3n de Ciudades Capitales Iberoamericanas (UCCI), se llevar\u00e1 a cabo bajo el lema, \u201cCiudades por Iberoam\u00e9rica: El futuro que nos une\u201d, y en este debatir\u00e1n sobre c\u00f3mo encarar el futuro de las capitales iberoamericanas y las necesidades derivadas del nuevo contexto mundial generado por la pandemia. Entre los temas a abordar por los l\u00edderes y lideresas de las 29 ciudades que conforman la UCCI se destacan la recuperaci\u00f3n econ\u00f3mica y social de las ciudades iberoamericanas, debatir\u00e1n acerca del plan estrat\u00e9gico que definir\u00e1 las l\u00edneas de trabajo hasta el 2023, tambi\u00e9n, ser\u00e1n elegidas las nuevas autoridades que presidir\u00e1n la UCCI. De igual forma se conocer\u00e1 la iniciativa propuesta por la alcaldesa Mej\u00eda, la cual present\u00f3 por primera ocasi\u00f3n en septiembre pasado en la asamblea de UCCI celebrada en San Juan, Puerto Rico. La misma se denomina \u201cIniciativa por las aceras de las capitales de Centroam\u00e9rica, M\u00e9xico y el Caribe como garantes de derechos constitucionales, calidad de vida y desarrollo econ\u00f3mico urbano\u201d, y busca crear las condiciones para devolver la ciudad a la gente, promoviendo la caminabilidad en las ciudades, la calidad de vida y el desarrollo urbano. \u201cEn septiembre present\u00e9 en la Asamblea Regional de la Uni\u00f3n de Ciudades Capitales Iberoam\u00e9ricanas (UCCI) todo lo que en este dif\u00edcil tiempo hemos aprendido gracias a la participaci\u00f3n ciudadana y las consultas a expertos, y propuse una iniciativa regional para que las dem\u00e1s ciudades capitales se unan en una nueva visi\u00f3n de nuestras ciudades; una en la que las personas tengan, entre otras cosas, una experiencia peatonal grata y segura, priorizando las poblaciones m\u00e1s necesitadas y los centros urbanos\u201d, destac\u00f3 la funcionaria.\u00a0Esta asamblea, la cual estar\u00e1 presidida por el alcalde de Madrid, Jos\u00e9 Luis Mart\u00ednez-Almeida, busca continuar fortaleciendo los gobiernos locales a trav\u00e9s de la innovaci\u00f3n y la cooperaci\u00f3n, favoreciendo al crecimiento econ\u00f3mico y social de las ciudades y sus habitantes.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-121239","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/121239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=121239"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/121239\/revisions"}],"predecessor-version":[{"id":121241,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/121239\/revisions\/121241"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=121239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=121239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=121239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}