{"id":123511,"date":"2022-08-18T20:15:33","date_gmt":"2022-08-19T00:15:33","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=123511"},"modified":"2022-08-18T20:15:33","modified_gmt":"2022-08-19T00:15:33","slug":"lenguaje-sexista-caos-catastrofista-i","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2022\/08\/18\/lenguaje-sexista-caos-catastrofista-i\/","title":{"rendered":"LENGUAJE SEXISTA, CAOS CATASTROFISTA (I)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-123512 aligncenter\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2022\/08\/th.jpg\" alt=\"\" width=\"474\" height=\"408\" \/>Oscar L\u00f3pez Reyes<br \/>\nPalabras, vocales, morfemas, graf\u00edas y dobletes supuestamente feministas est\u00e1n siendo utilizados en la cotidianidad, como una intromisi\u00f3n indeseable, que alteran inmisericordemente el idioma espa\u00f1ol. Ex profeso, se busca desconocer el milenario uso del masculino gen\u00e9rico (singular y plural), que identifica a todas las especies (humanas, animales y algunas plantas), y que no establece diferencia entre sexos.<br \/>\nLa gramaticalidad estatuye el binarismo (binario o dual) no discriminatorio, porque -como lo especifica la Nueva Gram\u00e1tica de la Lengua Espa\u00f1ola- \u201cel masculino es en espa\u00f1ol el g\u00e9nero no marcado\u201d, o sea, el integral y neutral que designa a todos los individuos sin distinci\u00f3n carnal, \u201cy el femenino el marcado\u201d (1), es decir, que \u2013\u201cigual que en otros idiomas\u201d- se etiqueta como unisexo, porque opera para los dos.<\/p>\n<p>Para comprender esta exposici\u00f3n, tenemos que separar GENERO y SEXO, porque en la lengua hay g\u00e9nero, pero no sexo. El \u201cDiccionario panhisp\u00e1nico de dudas\u201d precisa que \u201cpara designar la condici\u00f3n org\u00e1nica, biol\u00f3gica, por la cual los seres vivos son masculinos o femeninos, debe emplearse el t\u00e9rmino sexo. Por lo tanto, las palabras tienen g\u00e9nero (y no sexo), mientras que los seres vivos tienen sexo (y no g\u00e9nero\u201d (2).<br \/>\nEn esa andana debemos deslindar, razonablemente, ambos significados. \u00bfQu\u00e9 g\u00e9nero tienen las palabras mano y pu\u00f1o? Las dos terminan en vocal O. Mano posee g\u00e9nero femenino, y pu\u00f1o abraza el masculino. \u00bfSabemos por qu\u00e9? No. Veamos ahora: la mano y el pu\u00f1o.<br \/>\nEl g\u00e9nero gramatical se determina por el empleo de los art\u00edculos (la mano y el pu\u00f1o); los sustantivos, entre ellos los epicenos -que nombran lo masculino y femenino, como el beb\u00e9-; los adjetivos, algunos pronombres, la terminaci\u00f3n y el contexto socio-cultural.<br \/>\nSexualizar el g\u00e9nero (sexo biol\u00f3gico) fundamentado en los par\u00e1metros de la ideolog\u00eda feminista del lenguaje rompe el rigor cient\u00edfico, con lesiones profundas en los esquemas morfol\u00f3gicos y sem\u00e1nticos, en virtud de que \u201cel g\u00e9nero de los sustantivos es una propiedad gramatical inherente, sin conexi\u00f3n con el sexo\u201d (3). Y no guarda relaci\u00f3n, en lo absoluto, con la ineludible equidad de derecho, ni oculta a ese ser prodigioso -el \u00fanico capaz de dar vida humana- llamado mujer.<br \/>\nEl espa\u00f1ol, que comenz\u00f3 en el a\u00f1o 1200 y que tonifica como la lengua m\u00e1s hablada (489 millones de personas), y otras romances o evoluci\u00f3n desde los tiempos de Roma (portugu\u00e9s, franc\u00e9s, italiano, rumano y una veintena m\u00e1s), est\u00e1 siendo degradado encarnizadamente por un ortodoxo y desafiante movimiento feminista, el bloque LGBTIQ+ (lesbianas, gays, bisexuales, transg\u00e9nero, intersexo, queer y m\u00e1s) y defensores de derechos humanos, que pretende llevarse por delante hasta la estructura morfol\u00f3gica y de sintaxis de la lengua espa\u00f1ola. Objetivo: ignorar el masculino como abarcador de todas las condiciones anat\u00f3micas, fisiol\u00f3gicas y psicol\u00f3gicas, para visibilizar a la mujer.<br \/>\nPor lo antes dicho, la conjunci\u00f3n de nuevas jergas detr\u00e1s de una inclusi\u00f3n que ya existe, \u201cquiebra la esencia\u201d del \u201cl\u00e9xico, gram\u00e1tica y ortograf\u00eda\u201d (4) de los emisores castellanohablantes, y lanza un reto a la Real Academia Espa\u00f1ola, que \u201ctiene como misi\u00f3n principal velar porque los cambios que experimente la Lengua Espa\u00f1ola en su constante adaptaci\u00f3n a las necesidades de sus hablantes\u201d, \u201cconserve el genio propio de la lengua\u201d y \u201cno quiebren la esencial unidad que mantiene en todo el \u00e1mbito hisp\u00e1nico\u201d.<br \/>\nEjemplifiquemos el compuesto de distorsiones del denominado lenguaje de la sexualidad:<br \/>\n1.- \u201cLos\/las\u201d. El uso de esta barra para juntar dos art\u00edculos pisotea reglas gramaticales, en un superfluo desdoblamiento l\u00e9xico o duplicaci\u00f3n de g\u00e9neros.<br \/>\n2.- \u201cDominicanos y dominicanas respetuosos y respetuosas\u201d. Este doblete deviene en tautolog\u00eda o redundancia. Despliega como un dislate.<br \/>\n3.- Buenos d\u00edas \u201ca todos y a todas\u201d. Se trata de un hip\u00f3nimo o repetici\u00f3n, en virtud de que \u201cTodos\u201d engloba a hombres y mujeres.<br \/>\n4.- \u201cLa miembra\u201d y \u201cLa estudianta\u201d. Adem\u00e1s de la impropiedad, sustituir los morfemas \u201co\u201d y \u201ce\u201d por la vocal \u201ca\u201d resulta malsonante y extravagante. Como contraparte, en vez de periodista tendr\u00edamos que escribir o pronunciar periodisto; en lugar de artista dir\u00edamos artisto, policio o no polic\u00eda, cliento y no cliente, la hembro y no la hembra, la criaturo y no la criatura, la persono y no la persona, y la victimo y no la v\u00edctima.<br \/>\n5.- \u201cLa dirigente\/ta\u201d. Una cursiler\u00eda an\u00f3mala e improcedente.<br \/>\n6.-\u201c@\u201d (chic@). Agramatical, porque el recurso grafema de la arroba, que une la \u201ca\u201d y la \u201co\u201d como representaci\u00f3n del masculino y el femenino, es un injerto rid\u00edculo sin valor ling\u00fc\u00edstico. En ning\u00fan idioma ha sido admitida la colocaci\u00f3n de una s\u00edlaba con la @, debido a que no es una vocal.<br \/>\n7.- \u201cAmigues\u201d, en vez de amigos: un invento ins\u00f3lito, que se escurre como un eufemismo.<br \/>\n8.-\u201cLes ni\u00f1es\u201d, otra premisa de la subjetividad terminol\u00f3gica.<br \/>\n9.- \u201cTodes\u201d y \u201cTodxs\u201d, en reemplazo de todos. El espa\u00f1ol tampoco acepta una s\u00edlaba con la \u201cx\u201d, ya que no es una vocal.<br \/>\n10.- \u201cChicxs\u201d y \u201cchiques\u201d: dos locuciones improvisadas, que ni siquiera pueden pronunciarse, por las trabas fon\u00e9ticas.<br \/>\n11.- \u201cHen\u201d y \u201chon\u201d (ella o tercera persona sin g\u00e9nero), en un canje por \u201chan\u201d (\u00e9l), en otra forzada y confusa ligadura en la variaci\u00f3n de la genitalidad.<br \/>\n12.- \u201cQuerides alumnes\u201d, por queridos alumnos y queridas alumnas. \u00a1Qu\u00e9 chabacaner\u00eda! .<br \/>\nEn su informe de 2020, la Real Academia Espa\u00f1ola, m\u00e1xima autoridad rectora del habla materna que cuida la propiedad, la unidad y la comprensi\u00f3n del idioma en el \u00e1mbito hisp\u00e1nico, sostiene que \u201cel uso de la \u201c@\u201d o de las letras \u201ce\u201d y \u201cx\u201d como supuestas marcas de g\u00e9nero inclusivo es ajeno a la morfolog\u00eda del espa\u00f1ol, adem\u00e1s de innecesario, pues el masculino gramatical ya cumple esa funci\u00f3n como t\u00e9rmino no marcado de la oposici\u00f3n de g\u00e9nero\u201d (5).<br \/>\nPlasmemos, como ilustraci\u00f3n, un texto que, por su exagerado sexismo, rueda con tautolog\u00eda o repetici\u00f3n recargada:<br \/>\n\u201cSe\u00f1oras y se\u00f1ores: Gracias por asistir a esta importante reuni\u00f3n. Todos y todas fueron convocados y convocadas para analizar qu\u00e9 podemos hacer en beneficio de los y las moradores y moradoras de esta comunidad que hoy forman parte de la gran masa de damnificados y damnificadas, v\u00edctimas de las recientes inundaciones. En condiciones bastante infrahumanas, esos y esas damnificados y damnificadas yacen alojados y alojadas en diferentes lugares o refugios en espera de la ayuda humanitaria que podamos ofrecerles todos y todas los y las que nos consideramos ser verdaderos y verdaderas cristianos y cristianas o totalmente identificados e identificadas con el dolor ajeno\u201d (6).<br \/>\n\u00bfQu\u00e9 le parece al presidente de la Rep\u00fablica leyendo la anterior pieza oratoria?<br \/>\n\u00bfHan visto ustedes semejante fragmento en un libro publicado por una reconocida editora, un diario prestigioso o una revista cient\u00edfica?<br \/>\nEl discurso precedente boya en la redundancia estil\u00edstica, contrario a la econom\u00eda ling\u00fc\u00edstica, la sencillez y la claridad; en la incoherencia y se torna asaz aburrido en la complejidad sint\u00e1ctica\/sem\u00e1ntica.<br \/>\nEl idioma espa\u00f1ol est\u00e1 cargado de tanta riqueza y amplitud que permite la feminizaci\u00f3n del lenguaje o la inclusi\u00f3n, admitida por la Real Academia de la Lengua. Adem\u00e1s de los epicenos, en la perspectiva de la morfolog\u00eda \u201cse recomienda generalizar el femenino con a en los nombres de profesiones, cargos y t\u00edtulos que en masculino terminan con o cuando \u00e9stos son desempe\u00f1ados por mujeres: la abogada, la catedr\u00e1tica, la m\u00e9dica, la ministra, la diputada\u201d.<br \/>\nIgualmente, lo facilita \u201cen los nombres de profesiones, cargos o t\u00edtulos terminados en consonante, se recomienda tratarlos como comunes en cuanto al g\u00e9nero: el juez-la juez, el fiscal-la fiscal, el concejal-la concejal, el edil-la edil, el bedel-la bedel, aunque en algunos casos, como el de juez, el Diccionario de la Real Academia ya recoge jueza\u201d (7).<br \/>\nObviando el antisexismo ling\u00fc\u00edstico, y para diferenciar el catalizador er\u00f3tico (hombre\/mujer) y el g\u00e9nero (masculino\/femenino), el \u201cLibro de estilo\u201d del diario espa\u00f1ol El Pa\u00eds (8) y otros textos sugieren variar \u201cigualdad de g\u00e9nero\u201d, por \u201cpol\u00edtica de igualdad\u201d, y \u201cviolencia de g\u00e9nero\u201d, por \u201cviolencia machista\u201d, \u201cviolencia sexista\u201d o \u201cviolencia contra las mujeres\u201d.<br \/>\nAislando los criterios extraling\u00fc\u00edsticos y admitiendo que son escasos los seres humanos que se oponen a la paridad de derechos entre hombres y mujeres, y que el lenguaje no pari\u00f3 ese fen\u00f3meno, tenemos que reconocer que las nuevas expresiones idiom\u00e1ticas atentan contra la tradici\u00f3n ling\u00fc\u00edstica y cultural, as\u00ed como contra la compactaci\u00f3n, la virginidad , la pertenencia y el buen uso de la lengua castellana.<br \/>\nY, como medida preventiva a las denominadas \u201clacras del lenguaje\u201d, maestros, fil\u00f3logos y especialistas en socioling\u00fc\u00edstica y psicoling\u00fc\u00edstica observan: 1) que dificultar\u00e1n a\u00fan m\u00e1s la incomprensi\u00f3n de la deficitaria lecto-escritura en ni\u00f1os y adolescentes, y 2) que los cambios se asientan meticulosamente durante cientos o miles de a\u00f1os, y que la imposici\u00f3n con una rapidez forzosa promueve la teor\u00eda del caos y empuja hacia la pendiente catastrofista.<br \/>\n\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026..<br \/>\nCitas bibliogr\u00e1ficas:<br \/>\n1.- Nueva Gram\u00e1tica de la Lengua Espa\u00f1ola, Asociaci\u00f3n de Academias de la Lengua, Decimotercera tirada, Editorial Planeta, Barcelona, Espa\u00f1a, 2021, p\u00e1g. 20.<br \/>\n2.- \u201cDiccionario panhisp\u00e1nico de dudas\u201d, Real Academia Espa\u00f1ola y Asociaci\u00f3n de Academias de la Lengua Espa\u00f1ola, Santillana Ediciones Generales, Bogot\u00e1, Colombia, 2005, p\u00e1g. 310.<br \/>\n3.- Nueva Gram\u00e1tica B\u00e1sica de la Lengua Espa\u00f1ola, Real Academia de la Lengua, Asociaci\u00f3n de Academias de la Lengua Espa\u00f1ola, Editorial Planeta, s\u00e9ptima tirada, Barcelona, Espa\u00f1a, 2021, p\u00e1g. 24.<br \/>\n4.- https:\/\/www.rae.es\/la-instituci%C3%B3n\/iiicentenario<br \/>\n5.- \u201cInforme de la Real Academia de la Lengua sobre el lenguaje inclusivo y cuestiones conexas\u201d, Madrid, Espa\u00f1a, 16 de enero de 2020.<br \/>\n6.- \u201cSexismo ling\u00fc\u00edstico y doble g\u00e9nero. La plaga del lenguaje contempor\u00e1neo\u201d, Academia Dominicana de la Lengua, Editora Corripio, Santo Domingo, Rep. Dom., 2012, p\u00e1g. 51.<br \/>\n7.- \u201cManual de espa\u00f1ol urgente\u201d, agencia espa\u00f1ola EFE, Ediciones C\u00e1tedra (Grupo Anaya), 2001, p\u00e1g. 60.<br \/>\n8.- \u201cLibro de estilo\u201d del diario espa\u00f1ol El Pa\u00eds, Penguin Random House Grupo Editorial, Barcelona, Espa\u00f1a, 2021, p\u00e1gs. 382 y 383.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oscar L\u00f3pez Reyes Palabras, vocales, morfemas, graf\u00edas y dobletes supuestamente feministas est\u00e1n siendo utilizados en la cotidianidad, como una intromisi\u00f3n indeseable, que alteran inmisericordemente el idioma espa\u00f1ol. Ex profeso, se busca desconocer el milenario uso del masculino gen\u00e9rico (singular y plural), que identifica a todas las especies (humanas, animales y algunas plantas), y que no establece diferencia entre sexos. La gramaticalidad estatuye el binarismo (binario o dual) no discriminatorio, porque -como lo especifica la Nueva Gram\u00e1tica de la Lengua Espa\u00f1ola- \u201cel masculino es en espa\u00f1ol el g\u00e9nero no marcado\u201d, o sea, el integral y neutral que designa a todos los individuos sin distinci\u00f3n carnal, \u201cy el femenino el marcado\u201d (1), es decir, que \u2013\u201cigual que en otros idiomas\u201d- se etiqueta como unisexo, porque opera para los dos. Para comprender esta exposici\u00f3n, tenemos que separar GENERO y SEXO, porque en la lengua hay g\u00e9nero, pero no sexo. El \u201cDiccionario panhisp\u00e1nico de dudas\u201d precisa que \u201cpara designar la condici\u00f3n org\u00e1nica, biol\u00f3gica, por la cual los seres vivos son masculinos o femeninos, debe emplearse el t\u00e9rmino sexo. Por lo tanto, las palabras tienen g\u00e9nero (y no sexo), mientras que los seres vivos tienen sexo (y no g\u00e9nero\u201d (2). En esa andana debemos deslindar, razonablemente, ambos significados. \u00bfQu\u00e9 g\u00e9nero tienen las palabras mano y pu\u00f1o? Las dos terminan en vocal O. Mano posee g\u00e9nero femenino, y pu\u00f1o abraza el masculino. \u00bfSabemos por qu\u00e9? No. Veamos ahora: la mano y el pu\u00f1o. El g\u00e9nero gramatical se determina por el empleo de los art\u00edculos (la mano y el pu\u00f1o); los sustantivos, entre ellos los epicenos -que nombran lo masculino y femenino, como el beb\u00e9-; los adjetivos, algunos pronombres, la terminaci\u00f3n y el contexto socio-cultural. Sexualizar el g\u00e9nero (sexo biol\u00f3gico) fundamentado en los par\u00e1metros de la ideolog\u00eda feminista del lenguaje rompe el rigor cient\u00edfico, con lesiones profundas en los esquemas morfol\u00f3gicos y sem\u00e1nticos, en virtud de que \u201cel g\u00e9nero de los sustantivos es una propiedad gramatical inherente, sin conexi\u00f3n con el sexo\u201d (3). Y no guarda relaci\u00f3n, en lo absoluto, con la ineludible equidad de derecho, ni oculta a ese ser prodigioso -el \u00fanico capaz de dar vida humana- llamado mujer. El espa\u00f1ol, que comenz\u00f3 en el a\u00f1o 1200 y que tonifica como la lengua m\u00e1s hablada (489 millones de personas), y otras romances o evoluci\u00f3n desde los tiempos de Roma (portugu\u00e9s, franc\u00e9s, italiano, rumano y una veintena m\u00e1s), est\u00e1 siendo degradado encarnizadamente por un ortodoxo y desafiante movimiento feminista, el bloque LGBTIQ+ (lesbianas, gays, bisexuales, transg\u00e9nero, intersexo, queer y m\u00e1s) y defensores de derechos humanos, que pretende llevarse por delante hasta la estructura morfol\u00f3gica y de sintaxis de la lengua espa\u00f1ola. Objetivo: ignorar el masculino como abarcador de todas las condiciones anat\u00f3micas, fisiol\u00f3gicas y psicol\u00f3gicas, para visibilizar a la mujer. Por lo antes dicho, la conjunci\u00f3n de nuevas jergas detr\u00e1s de una inclusi\u00f3n que ya existe, \u201cquiebra la esencia\u201d del \u201cl\u00e9xico, gram\u00e1tica y ortograf\u00eda\u201d (4) de los emisores castellanohablantes, y lanza un reto a la Real Academia Espa\u00f1ola, que \u201ctiene como misi\u00f3n principal velar porque los cambios que experimente la Lengua Espa\u00f1ola en su constante adaptaci\u00f3n a las necesidades de sus hablantes\u201d, \u201cconserve el genio propio de la lengua\u201d y \u201cno quiebren la esencial unidad que mantiene en todo el \u00e1mbito hisp\u00e1nico\u201d. Ejemplifiquemos el compuesto de distorsiones del denominado lenguaje de la sexualidad: 1.- \u201cLos\/las\u201d. El uso de esta barra para juntar dos art\u00edculos pisotea reglas gramaticales, en un superfluo desdoblamiento l\u00e9xico o duplicaci\u00f3n de g\u00e9neros. 2.- \u201cDominicanos y dominicanas respetuosos y respetuosas\u201d. Este doblete deviene en tautolog\u00eda o redundancia. Despliega como un dislate. 3.- Buenos d\u00edas \u201ca todos y a todas\u201d. Se trata de un hip\u00f3nimo o repetici\u00f3n, en virtud de que \u201cTodos\u201d engloba a hombres y mujeres. 4.- \u201cLa miembra\u201d y \u201cLa estudianta\u201d. Adem\u00e1s de la impropiedad, sustituir los morfemas \u201co\u201d y \u201ce\u201d por la vocal \u201ca\u201d resulta malsonante y extravagante. Como contraparte, en vez de periodista tendr\u00edamos que escribir o pronunciar periodisto; en lugar de artista dir\u00edamos artisto, policio o no polic\u00eda, cliento y no cliente, la hembro y no la hembra, la criaturo y no la criatura, la persono y no la persona, y la victimo y no la v\u00edctima. 5.- \u201cLa dirigente\/ta\u201d. Una cursiler\u00eda an\u00f3mala e improcedente. 6.-\u201c@\u201d (chic@). Agramatical, porque el recurso grafema de la arroba, que une la \u201ca\u201d y la \u201co\u201d como representaci\u00f3n del masculino y el femenino, es un injerto rid\u00edculo sin valor ling\u00fc\u00edstico. En ning\u00fan idioma ha sido admitida la colocaci\u00f3n de una s\u00edlaba con la @, debido a que no es una vocal. 7.- \u201cAmigues\u201d, en vez de amigos: un invento ins\u00f3lito, que se escurre como un eufemismo. 8.-\u201cLes ni\u00f1es\u201d, otra premisa de la subjetividad terminol\u00f3gica. 9.- \u201cTodes\u201d y \u201cTodxs\u201d, en reemplazo de todos. El espa\u00f1ol tampoco acepta una s\u00edlaba con la \u201cx\u201d, ya que no es una vocal. 10.- \u201cChicxs\u201d y \u201cchiques\u201d: dos locuciones improvisadas, que ni siquiera pueden pronunciarse, por las trabas fon\u00e9ticas. 11.- \u201cHen\u201d y \u201chon\u201d (ella o tercera persona sin g\u00e9nero), en un canje por \u201chan\u201d (\u00e9l), en otra forzada y confusa ligadura en la variaci\u00f3n de la genitalidad. 12.- \u201cQuerides alumnes\u201d, por queridos alumnos y queridas alumnas. \u00a1Qu\u00e9 chabacaner\u00eda! . En su informe de 2020, la Real Academia Espa\u00f1ola, m\u00e1xima autoridad rectora del habla materna que cuida la propiedad, la unidad y la comprensi\u00f3n del idioma en el \u00e1mbito hisp\u00e1nico, sostiene que \u201cel uso de la \u201c@\u201d o de las letras \u201ce\u201d y \u201cx\u201d como supuestas marcas de g\u00e9nero inclusivo es ajeno a la morfolog\u00eda del espa\u00f1ol, adem\u00e1s de innecesario, pues el masculino gramatical ya cumple esa funci\u00f3n como t\u00e9rmino no marcado de la oposici\u00f3n de g\u00e9nero\u201d (5). Plasmemos, como ilustraci\u00f3n, un texto que, por su exagerado sexismo, rueda con tautolog\u00eda o repetici\u00f3n recargada: \u201cSe\u00f1oras y se\u00f1ores: Gracias por asistir a esta importante reuni\u00f3n. Todos y todas fueron convocados y convocadas para analizar qu\u00e9 podemos hacer en beneficio de los y las moradores y moradoras de esta comunidad que hoy forman parte de la gran masa de damnificados y damnificadas, v\u00edctimas de las recientes inundaciones. En condiciones bastante infrahumanas, esos y esas damnificados y damnificadas yacen alojados y alojadas en diferentes lugares o refugios en espera de la ayuda humanitaria que podamos ofrecerles todos y todas los y las que nos consideramos ser verdaderos y verdaderas cristianos y cristianas o totalmente identificados e identificadas con el dolor ajeno\u201d (6). \u00bfQu\u00e9 le parece al presidente de la Rep\u00fablica leyendo la anterior pieza oratoria? \u00bfHan visto ustedes semejante fragmento en un libro publicado por una reconocida editora, un diario prestigioso o una revista cient\u00edfica? El discurso precedente boya en la redundancia estil\u00edstica, contrario a la econom\u00eda ling\u00fc\u00edstica, la sencillez y la claridad; en la incoherencia y se torna asaz aburrido en la complejidad sint\u00e1ctica\/sem\u00e1ntica. El idioma espa\u00f1ol est\u00e1 cargado de tanta riqueza y amplitud que permite la feminizaci\u00f3n del lenguaje o la inclusi\u00f3n, admitida por la Real Academia de la Lengua. Adem\u00e1s de los epicenos, en la perspectiva de la morfolog\u00eda \u201cse recomienda generalizar el femenino con a en los nombres de profesiones, cargos y t\u00edtulos que en masculino terminan con o cuando \u00e9stos son desempe\u00f1ados por mujeres: la abogada, la catedr\u00e1tica, la m\u00e9dica, la ministra, la diputada\u201d. Igualmente, lo facilita \u201cen los nombres de profesiones, cargos o t\u00edtulos terminados en consonante, se recomienda tratarlos como comunes en cuanto al g\u00e9nero: el juez-la juez, el fiscal-la fiscal, el concejal-la concejal, el edil-la edil, el bedel-la bedel, aunque en algunos casos, como el de juez, el Diccionario de la Real Academia ya recoge jueza\u201d (7). Obviando el antisexismo ling\u00fc\u00edstico, y para diferenciar el catalizador er\u00f3tico (hombre\/mujer) y el g\u00e9nero (masculino\/femenino), el \u201cLibro de estilo\u201d del diario espa\u00f1ol El Pa\u00eds (8) y otros textos sugieren variar \u201cigualdad de g\u00e9nero\u201d, por \u201cpol\u00edtica de igualdad\u201d, y \u201cviolencia de g\u00e9nero\u201d, por \u201cviolencia machista\u201d, \u201cviolencia sexista\u201d o \u201cviolencia contra las mujeres\u201d. Aislando los criterios extraling\u00fc\u00edsticos y admitiendo que son escasos los seres humanos que se oponen a la paridad de derechos entre hombres y mujeres, y que el lenguaje no pari\u00f3 ese fen\u00f3meno, tenemos que reconocer que las nuevas expresiones idiom\u00e1ticas atentan contra la tradici\u00f3n ling\u00fc\u00edstica y cultural, as\u00ed como contra la compactaci\u00f3n, la virginidad , la pertenencia y el buen uso de la lengua castellana. Y, como medida preventiva a las denominadas \u201clacras del lenguaje\u201d, maestros, fil\u00f3logos y especialistas en socioling\u00fc\u00edstica y psicoling\u00fc\u00edstica observan: 1) que dificultar\u00e1n a\u00fan m\u00e1s la incomprensi\u00f3n de la deficitaria lecto-escritura en ni\u00f1os y adolescentes, y 2) que los cambios se asientan meticulosamente durante cientos o miles de a\u00f1os, y que la imposici\u00f3n con una rapidez forzosa promueve la teor\u00eda del caos y empuja hacia la pendiente catastrofista. \u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026.. Citas bibliogr\u00e1ficas: 1.- Nueva Gram\u00e1tica de la Lengua Espa\u00f1ola, Asociaci\u00f3n de Academias de la Lengua, Decimotercera tirada, Editorial Planeta, Barcelona, Espa\u00f1a, 2021, p\u00e1g. 20. 2.- \u201cDiccionario panhisp\u00e1nico de dudas\u201d, Real Academia Espa\u00f1ola y Asociaci\u00f3n de Academias de la Lengua Espa\u00f1ola, Santillana Ediciones Generales, Bogot\u00e1, Colombia, 2005, p\u00e1g. 310. 3.- Nueva Gram\u00e1tica B\u00e1sica de la Lengua Espa\u00f1ola, Real Academia de la Lengua, Asociaci\u00f3n de Academias de la Lengua Espa\u00f1ola, Editorial Planeta, s\u00e9ptima tirada, Barcelona, Espa\u00f1a, 2021, p\u00e1g. 24. 4.- https:\/\/www.rae.es\/la-instituci%C3%B3n\/iiicentenario 5.- \u201cInforme de la Real Academia de la Lengua sobre el lenguaje inclusivo y cuestiones conexas\u201d, Madrid, Espa\u00f1a, 16 de enero de 2020. 6.- \u201cSexismo ling\u00fc\u00edstico y doble g\u00e9nero. La plaga del lenguaje contempor\u00e1neo\u201d, Academia Dominicana de la Lengua, Editora Corripio, Santo Domingo, Rep. Dom., 2012, p\u00e1g. 51. 7.- \u201cManual de espa\u00f1ol urgente\u201d, agencia espa\u00f1ola EFE, Ediciones C\u00e1tedra (Grupo Anaya), 2001, p\u00e1g. 60. 8.- \u201cLibro de estilo\u201d del diario espa\u00f1ol El Pa\u00eds, Penguin Random House Grupo Editorial, Barcelona, Espa\u00f1a, 2021, p\u00e1gs. 382 y 383.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15,52],"tags":[],"class_list":["post-123511","post","type-post","status-publish","format-standard","hentry","category-nacionales","category-opinion"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/123511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=123511"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/123511\/revisions"}],"predecessor-version":[{"id":123513,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/123511\/revisions\/123513"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=123511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=123511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=123511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}