{"id":125472,"date":"2022-11-27T07:53:41","date_gmt":"2022-11-27T11:53:41","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=125472"},"modified":"2022-11-27T07:53:41","modified_gmt":"2022-11-27T11:53:41","slug":"fjt-resalta-legado-y-sacrificio-de-las-hermanas-mirabal-en-el-dia-internacional-de-la-no-violencia-contra-la-mujer","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2022\/11\/27\/fjt-resalta-legado-y-sacrificio-de-las-hermanas-mirabal-en-el-dia-internacional-de-la-no-violencia-contra-la-mujer\/","title":{"rendered":"FJT resalta legado y sacrificio de las Hermanas Mirabal en el d\u00eda Internacional de la NO Violencia contra la Mujer"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-125473 aligncenter\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2022\/11\/thumbnail_IMG-20221125-WA0023-800x450.jpg\" alt=\"\" width=\"800\" height=\"450\" \/>Santo Domingo, Rep. Dom.,\u00a025\u00a0de\u00a0noviembre\u00a0del 2022.-\u00a0Con motivo de la celebraci\u00f3n del D\u00eda Internacional de la No Violencia contra la Mujer, (25\u00a0de\u00a0noviembre), la Fundaci\u00f3n Justicia y Transparencia (FJT), hizo un llamado a la reflexi\u00f3n de toda la naci\u00f3n dominicana, sobre las alarmantes estad\u00edsticas en el pa\u00eds, que dan cuenta de una cultura de abuso y maltrato a la mujer dominicana, incluso con reiterados feminicidios, convirti\u00e9ndonos en unos de los campeones de Latinoam\u00e9rica en tan aberrante pr\u00e1ctica.<\/p>\n<p>Asimismo, la entidad c\u00edvica resalt\u00f3 el significado de tan emblem\u00e1tico d\u00eda, exponiendo la persecuci\u00f3n, tortura, muerte y sacrificio, de que fueron objeto las hero\u00ednas dominicanas, Patria, Minerva y Mar\u00eda Teresa Mirabal, frente al echo vil y cobarde de la dictadura de Rafael Le\u00f3nidas Trujillo, cuando en el 1960 fueron asesinada por un r\u00e9gimen de sangre y terror.<\/p>\n<p>Para el presidente de Justicia y Transparencia, Trajano Potentini, la muerte de las Hermanas Mirabal, marco el inicio de todo un despertar c\u00edvico a nivel del mundo, sobre la necesidad de asumir un marco de respeto y protecci\u00f3n de la integridad y derechos de las mujeres, potencializado por el movimiento feminista latinoamericano, cuando en 1981 recordando el vil asesinato de 1960, desarrollo un conjunto de acciones reivindicativas en beneficio de las mujeres, concretadas en 1999, por la Asamblea General de las Naciones Unidas, mediante resoluci\u00f3n n\u00famero 54-134, de fecha 17 de diciembre, con la declaraci\u00f3n del 25 de noviembre de cada, como el\u00a0D\u00eda Internacional para Eliminar la Violencia contra la Mujer.<\/p>\n<p>Este acontecimiento tuvo por objeto, el\u00a0denunciar la violencia que se ejerce sobre las mujeres en todo el mundo y reclamar pol\u00edticas en todos los pa\u00edses para su erradicaci\u00f3n, donde tambi\u00e9n asumieron y oficializaron como definici\u00f3n lo que entend\u00edan por violencia contra la mujer y citamos: entendiendo por violencia contra la mujer \u00abtodo acto de violencia basado en la pertenencia al sexo femenino que tenga o pueda tener como resultado un da\u00f1o o sufrimiento f\u00edsico, sexual o psicol\u00f3gico para la mujer, as\u00ed como las amenazas de tales actos, la coacci\u00f3n o la privaci\u00f3n arbitraria de la libertad, tanto si se producen en la vida p\u00fablica como en la vida privada\u00bb, adem\u00e1s de invitar a los\u00a0gobiernos,\u00a0organizaciones internacionales\u00a0y\u00a0organizaciones no gubernamentales\u00a0a convocar actividades dirigidas a sensibilizar a la opini\u00f3n p\u00fablica sobre el problema de la violencia contra las mujeres \u00a0olas a as\u00ed como tambi\u00e9n los hechos hist\u00f3ricos en detalles que dieron origen a la declaratoria de naciones unidas del 25 de noviembre como el d\u00eda internacional de la eliminaci\u00f3n de la violencia contra la mujer.<\/p>\n<p>Finalmente, la FJT anunci\u00f3 que estar\u00e1 desarrollando un conjunto de acciones tendentes a crear conciencia sobre los derechos de las mujeres, mediante su Campa\u00f1a Permanente de Concientizaci\u00f3n C\u00edvica sobre Derechos Ciudadanos, resaltando y exigiendo en todos los \u00f3rdenes, el cese del maltrato y violaci\u00f3n a los derechos, de que son objeto las mujeres, en los diversos escenarios de la vida nacional, tanto social como econ\u00f3mico, pol\u00edtico y jur\u00eddico.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo, Rep. Dom.,\u00a025\u00a0de\u00a0noviembre\u00a0del 2022.-\u00a0Con motivo de la celebraci\u00f3n del D\u00eda Internacional de la No Violencia contra la Mujer, (25\u00a0de\u00a0noviembre), la Fundaci\u00f3n Justicia y Transparencia (FJT), hizo un llamado a la reflexi\u00f3n de toda la naci\u00f3n dominicana, sobre las alarmantes estad\u00edsticas en el pa\u00eds, que dan cuenta de una cultura de abuso y maltrato a la mujer dominicana, incluso con reiterados feminicidios, convirti\u00e9ndonos en unos de los campeones de Latinoam\u00e9rica en tan aberrante pr\u00e1ctica. Asimismo, la entidad c\u00edvica resalt\u00f3 el significado de tan emblem\u00e1tico d\u00eda, exponiendo la persecuci\u00f3n, tortura, muerte y sacrificio, de que fueron objeto las hero\u00ednas dominicanas, Patria, Minerva y Mar\u00eda Teresa Mirabal, frente al echo vil y cobarde de la dictadura de Rafael Le\u00f3nidas Trujillo, cuando en el 1960 fueron asesinada por un r\u00e9gimen de sangre y terror. Para el presidente de Justicia y Transparencia, Trajano Potentini, la muerte de las Hermanas Mirabal, marco el inicio de todo un despertar c\u00edvico a nivel del mundo, sobre la necesidad de asumir un marco de respeto y protecci\u00f3n de la integridad y derechos de las mujeres, potencializado por el movimiento feminista latinoamericano, cuando en 1981 recordando el vil asesinato de 1960, desarrollo un conjunto de acciones reivindicativas en beneficio de las mujeres, concretadas en 1999, por la Asamblea General de las Naciones Unidas, mediante resoluci\u00f3n n\u00famero 54-134, de fecha 17 de diciembre, con la declaraci\u00f3n del 25 de noviembre de cada, como el\u00a0D\u00eda Internacional para Eliminar la Violencia contra la Mujer. Este acontecimiento tuvo por objeto, el\u00a0denunciar la violencia que se ejerce sobre las mujeres en todo el mundo y reclamar pol\u00edticas en todos los pa\u00edses para su erradicaci\u00f3n, donde tambi\u00e9n asumieron y oficializaron como definici\u00f3n lo que entend\u00edan por violencia contra la mujer y citamos: entendiendo por violencia contra la mujer \u00abtodo acto de violencia basado en la pertenencia al sexo femenino que tenga o pueda tener como resultado un da\u00f1o o sufrimiento f\u00edsico, sexual o psicol\u00f3gico para la mujer, as\u00ed como las amenazas de tales actos, la coacci\u00f3n o la privaci\u00f3n arbitraria de la libertad, tanto si se producen en la vida p\u00fablica como en la vida privada\u00bb, adem\u00e1s de invitar a los\u00a0gobiernos,\u00a0organizaciones internacionales\u00a0y\u00a0organizaciones no gubernamentales\u00a0a convocar actividades dirigidas a sensibilizar a la opini\u00f3n p\u00fablica sobre el problema de la violencia contra las mujeres \u00a0olas a as\u00ed como tambi\u00e9n los hechos hist\u00f3ricos en detalles que dieron origen a la declaratoria de naciones unidas del 25 de noviembre como el d\u00eda internacional de la eliminaci\u00f3n de la violencia contra la mujer. Finalmente, la FJT anunci\u00f3 que estar\u00e1 desarrollando un conjunto de acciones tendentes a crear conciencia sobre los derechos de las mujeres, mediante su Campa\u00f1a Permanente de Concientizaci\u00f3n C\u00edvica sobre Derechos Ciudadanos, resaltando y exigiendo en todos los \u00f3rdenes, el cese del maltrato y violaci\u00f3n a los derechos, de que son objeto las mujeres, en los diversos escenarios de la vida nacional, tanto social como econ\u00f3mico, pol\u00edtico y jur\u00eddico. &nbsp;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-125472","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/125472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=125472"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/125472\/revisions"}],"predecessor-version":[{"id":125474,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/125472\/revisions\/125474"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=125472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=125472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=125472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}