{"id":127337,"date":"2023-06-20T19:42:17","date_gmt":"2023-06-20T23:42:17","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=127337"},"modified":"2023-06-20T19:42:17","modified_gmt":"2023-06-20T23:42:17","slug":"el-colegio-dominicano-de-odontologos-distingue-a-servidores-publicos-con-medalla-al-merito","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2023\/06\/20\/el-colegio-dominicano-de-odontologos-distingue-a-servidores-publicos-con-medalla-al-merito\/","title":{"rendered":"El Colegio Dominicano de Odont\u00f3logos distingue a servidores p\u00fablicos con Medalla al M\u00e9rito"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-127338 aligncenter\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2023\/06\/dcac7a90-8557-461a-b1d3-f322a56d506f-800x533.jpg\" alt=\"\" width=\"800\" height=\"533\" \/>Ese gremio tambi\u00e9n entreg\u00f3 un reconocimiento al presidente Luis Abinader a trav\u00e9s del ministro de Salud P\u00fablica, doctor Daniel Rivera<\/strong><\/p>\n<p>Santo Domingo._ Con la presencia del ministro de Salud P\u00fablica, doctor Daniel Rivera, el Colegio Dominicano de Odont\u00f3logos (CDO) entreg\u00f3 Medallas al M\u00e9rito a Servidores P\u00fablicos de la odontolog\u00eda.<\/p>\n<p>Durante la ceremonia, realizada en el local del CDO, directivos del gremio entregaron un reconocimiento especial al presidente Luis Abinader, que fue recibido por el ministro de Salud P\u00fablica.<\/p>\n<p>Las doctoras Lourdes Lassis y Mar\u00eda Rosanna de Jes\u00fas Matos, as\u00ed como la se\u00f1ora Antonia Rosario, recibieron reconocimientos en representaci\u00f3n de los odont\u00f3logos pensionados por su antig\u00fcedad en el servicio, y de los auxiliares y t\u00e9cnicos dentales.<\/p>\n<p>Al pronunciar el discurso central de la actividad, la presidenta del CDO, doctora Virginia Laureano, resalt\u00f3 el esfuerzo de los servidores de la odontolog\u00eda y su permanencia en funciones p\u00fablicas, poniendo su experiencia y conocimientos al servicio de sus compa\u00f1eros de m\u00e1s reciente incursi\u00f3n en el ejercicio profesional.<\/p>\n<p>Agradeci\u00f3 al presidente Abinader \u201cpor escucharnos y ser un mandatario amigo de los gremios, y junto a \u00e9l a usted se\u00f1or ministro de Salud P\u00fablica, por abrirnos las puertas de su despacho cuando se lo solicitamos preocupados por algunos temas que como Colegio nos sentimos en el deber desarrollar juntos\u201d.<\/p>\n<p>Aprovech\u00f3 la ocasi\u00f3n para poner a disposici\u00f3n al Colegio para desarrollar el tema de levantamiento nacional del profesional de la odontolog\u00eda, investigaci\u00f3n, educaci\u00f3n superior, \u201cque en este momento es uno de los temas m\u00e1s preocupante\u201d.<\/p>\n<p>De su lado, el ministro de Salud P\u00fablica resalt\u00f3 la importante labor realizada por los odont\u00f3logos y su gran capacidad, incluso, para detectar posibles enfermedades en otros \u00f3rganos del cuerpo, a partir de hallazgos en la boca.<\/p>\n<p>Indic\u00f3 que el presidente Abinader ha reconocido la ardua labor realizada por odont\u00f3logos y otros servicios p\u00fablicos de esa \u00e1rea con el otorgamiento de pensiones a 446 integrantes del CDO y de la Asociaci\u00f3n Odontol\u00f3gica.<\/p>\n<p>Al agradecer la entrega de la Medalla al M\u00e9rito a nombre de los distinguidos, la doctora Mar\u00eda Rosa de Jes\u00fas Matos, reconoci\u00f3 la labor realizada por la doctora Virginia Laureano como presidenta del CDO.<\/p>\n<p>La actividad fue encabezada, adem\u00e1s, por el director del Servicio Nacional de Salud, doctor Mario Lama; el director ejecutivo de Senasa, doctor Santiago Hazim; el director ejecutivo de Promesa\/Cal, ingeniero Adolfo P\u00e9rez; el asesor m\u00e9dico de la Presidencia, doctor V\u00edctor Atallah; el subdirector de Pensiones, F\u00e9lix Joel Almonte, y la viceministra de Trabajo, Sabrina de La Cruz<\/p>\n<p>Tambi\u00e9n asistieron al evento, el director de Habilitaci\u00f3n, Gerardo Mesa; la directora de Normas del Ministerio de Salud P\u00fablica, Milagros Pe\u00f1a y la directora de Tr\u00e1mites y Pensiones de la Direcci\u00f3n General de Jubilaciones y Pensiones (DGJP), licenciada Rosa Ventura; en representaci\u00f3n del director de ese organismo, licenciado Juan Rosa.<\/p>\n<p>En el acto de entrega de los pergaminos a servidores p\u00fablicos del \u00e1rea de odontolog\u00eda, participaron miembros honor\u00edficos del CDO, pasados presidentes del gremio, su Comit\u00e9 Ejecutivo, l\u00edderes de sociedades especializadas y grupos afines.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ese gremio tambi\u00e9n entreg\u00f3 un reconocimiento al presidente Luis Abinader a trav\u00e9s del ministro de Salud P\u00fablica, doctor Daniel Rivera Santo Domingo._ Con la presencia del ministro de Salud P\u00fablica, doctor Daniel Rivera, el Colegio Dominicano de Odont\u00f3logos (CDO) entreg\u00f3 Medallas al M\u00e9rito a Servidores P\u00fablicos de la odontolog\u00eda. Durante la ceremonia, realizada en el local del CDO, directivos del gremio entregaron un reconocimiento especial al presidente Luis Abinader, que fue recibido por el ministro de Salud P\u00fablica. Las doctoras Lourdes Lassis y Mar\u00eda Rosanna de Jes\u00fas Matos, as\u00ed como la se\u00f1ora Antonia Rosario, recibieron reconocimientos en representaci\u00f3n de los odont\u00f3logos pensionados por su antig\u00fcedad en el servicio, y de los auxiliares y t\u00e9cnicos dentales. Al pronunciar el discurso central de la actividad, la presidenta del CDO, doctora Virginia Laureano, resalt\u00f3 el esfuerzo de los servidores de la odontolog\u00eda y su permanencia en funciones p\u00fablicas, poniendo su experiencia y conocimientos al servicio de sus compa\u00f1eros de m\u00e1s reciente incursi\u00f3n en el ejercicio profesional. Agradeci\u00f3 al presidente Abinader \u201cpor escucharnos y ser un mandatario amigo de los gremios, y junto a \u00e9l a usted se\u00f1or ministro de Salud P\u00fablica, por abrirnos las puertas de su despacho cuando se lo solicitamos preocupados por algunos temas que como Colegio nos sentimos en el deber desarrollar juntos\u201d. Aprovech\u00f3 la ocasi\u00f3n para poner a disposici\u00f3n al Colegio para desarrollar el tema de levantamiento nacional del profesional de la odontolog\u00eda, investigaci\u00f3n, educaci\u00f3n superior, \u201cque en este momento es uno de los temas m\u00e1s preocupante\u201d. De su lado, el ministro de Salud P\u00fablica resalt\u00f3 la importante labor realizada por los odont\u00f3logos y su gran capacidad, incluso, para detectar posibles enfermedades en otros \u00f3rganos del cuerpo, a partir de hallazgos en la boca. Indic\u00f3 que el presidente Abinader ha reconocido la ardua labor realizada por odont\u00f3logos y otros servicios p\u00fablicos de esa \u00e1rea con el otorgamiento de pensiones a 446 integrantes del CDO y de la Asociaci\u00f3n Odontol\u00f3gica. Al agradecer la entrega de la Medalla al M\u00e9rito a nombre de los distinguidos, la doctora Mar\u00eda Rosa de Jes\u00fas Matos, reconoci\u00f3 la labor realizada por la doctora Virginia Laureano como presidenta del CDO. La actividad fue encabezada, adem\u00e1s, por el director del Servicio Nacional de Salud, doctor Mario Lama; el director ejecutivo de Senasa, doctor Santiago Hazim; el director ejecutivo de Promesa\/Cal, ingeniero Adolfo P\u00e9rez; el asesor m\u00e9dico de la Presidencia, doctor V\u00edctor Atallah; el subdirector de Pensiones, F\u00e9lix Joel Almonte, y la viceministra de Trabajo, Sabrina de La Cruz Tambi\u00e9n asistieron al evento, el director de Habilitaci\u00f3n, Gerardo Mesa; la directora de Normas del Ministerio de Salud P\u00fablica, Milagros Pe\u00f1a y la directora de Tr\u00e1mites y Pensiones de la Direcci\u00f3n General de Jubilaciones y Pensiones (DGJP), licenciada Rosa Ventura; en representaci\u00f3n del director de ese organismo, licenciado Juan Rosa. En el acto de entrega de los pergaminos a servidores p\u00fablicos del \u00e1rea de odontolog\u00eda, participaron miembros honor\u00edficos del CDO, pasados presidentes del gremio, su Comit\u00e9 Ejecutivo, l\u00edderes de sociedades especializadas y grupos afines.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-127337","post","type-post","status-publish","format-standard","hentry","category-nature"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/127337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=127337"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/127337\/revisions"}],"predecessor-version":[{"id":127339,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/127337\/revisions\/127339"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=127337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=127337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=127337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}