{"id":128202,"date":"2023-08-21T22:42:45","date_gmt":"2023-08-22T02:42:45","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=128202"},"modified":"2023-08-21T22:42:45","modified_gmt":"2023-08-22T02:42:45","slug":"agricultura-activa-plan-de-contingencia-preventivo-por-el-paso-de-franklin","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2023\/08\/21\/agricultura-activa-plan-de-contingencia-preventivo-por-el-paso-de-franklin\/","title":{"rendered":"Agricultura activa plan de contingencia preventivo por el paso de Franklin"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-128203 aligncenter\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2023\/08\/IMG-20230821-WA0088-800x533.jpg\" alt=\"\" width=\"800\" height=\"533\" \/>Santo Domingo. \u2013\u00a0El Ministerio de Agricultura, activ\u00f3 este lunes el Plan de Contingencia del Sector Agropecuario, que contiene un protocolo preventivo para minimizar los efectos negativos de la tormenta tropical Franklin.<\/p>\n<p>Todas las instituciones del Gabinete Agropecuario que encabeza el presidente, Luis Abinader, coordinan acciones y planes para enfrentar los posibles efectos.<\/p>\n<p>Por instrucciones del jefe del Estado, el ministro de Agricultura Limber Cruz, dispuso el desplazamiento de brigadas y maquinarias pesadas, (retropalas, bulldozer y volteos), hacia las zonas con pron\u00f3stico de inundaciones y vientos que puedan derribar y da\u00f1ar producci\u00f3n agr\u00edcola, ganados y aves.<\/p>\n<p>El Plan de Contingencia ante fen\u00f3menos naturales alerta a residentes en las zonas de alto y mediano riesgo. Los instruye a hacer un inventario previo de todos los animales y del estado del cultivo, reforzar techos y paredes de las instalaciones de las fincas, movilizar hacia zonas m\u00e1s seguras el ganado vacuno que es propenso a ahogamiento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo. \u2013\u00a0El Ministerio de Agricultura, activ\u00f3 este lunes el Plan de Contingencia del Sector Agropecuario, que contiene un protocolo preventivo para minimizar los efectos negativos de la tormenta tropical Franklin. Todas las instituciones del Gabinete Agropecuario que encabeza el presidente, Luis Abinader, coordinan acciones y planes para enfrentar los posibles efectos. Por instrucciones del jefe del Estado, el ministro de Agricultura Limber Cruz, dispuso el desplazamiento de brigadas y maquinarias pesadas, (retropalas, bulldozer y volteos), hacia las zonas con pron\u00f3stico de inundaciones y vientos que puedan derribar y da\u00f1ar producci\u00f3n agr\u00edcola, ganados y aves. El Plan de Contingencia ante fen\u00f3menos naturales alerta a residentes en las zonas de alto y mediano riesgo. Los instruye a hacer un inventario previo de todos los animales y del estado del cultivo, reforzar techos y paredes de las instalaciones de las fincas, movilizar hacia zonas m\u00e1s seguras el ganado vacuno que es propenso a ahogamiento.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-128202","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/128202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=128202"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/128202\/revisions"}],"predecessor-version":[{"id":128204,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/128202\/revisions\/128204"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=128202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=128202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=128202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}