{"id":128236,"date":"2023-08-23T20:43:19","date_gmt":"2023-08-24T00:43:19","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=128236"},"modified":"2023-08-23T20:43:19","modified_gmt":"2023-08-24T00:43:19","slug":"intrant-dispone-gruas-de-parqueate-bien-al-servicio-de-la-ciudadania-en-10-puntos-de-santo-domingo","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2023\/08\/23\/intrant-dispone-gruas-de-parqueate-bien-al-servicio-de-la-ciudadania-en-10-puntos-de-santo-domingo\/","title":{"rendered":"Intrant dispone gr\u00faas de Parqu\u00e9ate Bien al servicio de la ciudadan\u00eda en 10 puntos de Santo Domingo"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-128237 aligncenter\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2023\/08\/download-5-800x533.png\" alt=\"\" width=\"800\" height=\"533\" \/>Santo Domingo, 22 de agosto 2023.-El director ejecutivo del Instituto Nacional de Tr\u00e1nsito y Transporte Terrestre (Intrant), Hugo Beras, dispuso hoy las gr\u00faas del programa Parqu\u00e9ate Bien al servicio de la ciudadan\u00eda, ante las dificultades que puedan presentar sus veh\u00edculos producto de las lluvias pronosticadas por la tormenta Franklin.<\/p>\n<p>En ese sentido, el titular del Intrant manifest\u00f3 que el servicio estar\u00e1 disponible en diez puntos estrat\u00e9gicos de Santo Domingo, evaluados previamente por la direcci\u00f3n de Movilidad Sostenible de esa instituci\u00f3n, para dar asistencia ante las posibles dificultades que puedan tener los conductores en esa demarcaci\u00f3n.<\/p>\n<p>Las ubicaciones donde estar\u00e1n disponible las gr\u00faas son el puente Juan Bosch, Ave. 27 de Febrero con M\u00e1ximo G\u00f3mez y con Tiradentes, Ave. Padre Castellanos con Josefa Brea, Ave. John F. Kennedy con M\u00e1ximo G\u00f3mez, John F. Kennedy con Tiradentes y con N\u00fa\u00f1ez de C\u00e1ceres, Ave. Jacobo Majluta con Rep\u00fablica de Colombia, M\u00e1ximo G\u00f3mez con George Washington y el Puente Flotante.<\/p>\n<p>El director del Intrant reiter\u00f3 adem\u00e1s a los ciudadanos conducir con precauci\u00f3n ante las condiciones del tiempo y tomar en cuenta acciones de seguridad vial como el buen estado de los parabrisas, luces, frenos y neum\u00e1ticos y cuidar la velocidad dado los deslizamientos que pueden producirse por el pavimento mojado.<\/p>\n<p>Las acciones del Intrant forman parte del plan de emergencia dispuesto por el presidente Luis Abinader para salvaguardar la vida de los ciudadanos, junto a los organismos competentes como el Centro de Operaciones de Emergencias (COE).<\/p>\n<p>En esa misma medida, el Intrant llam\u00f3 a los ciudadanos a comunicarse con el Sistema de Atenci\u00f3n a Emergencias (9-1-1), la l\u00ednea de asistencia vial del Ministerio de Obras P\u00fablicas y Comunicaciones (829) 688-1000 y en el WhatsApp del Intrant en el (849) 455-2772.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo, 22 de agosto 2023.-El director ejecutivo del Instituto Nacional de Tr\u00e1nsito y Transporte Terrestre (Intrant), Hugo Beras, dispuso hoy las gr\u00faas del programa Parqu\u00e9ate Bien al servicio de la ciudadan\u00eda, ante las dificultades que puedan presentar sus veh\u00edculos producto de las lluvias pronosticadas por la tormenta Franklin. En ese sentido, el titular del Intrant manifest\u00f3 que el servicio estar\u00e1 disponible en diez puntos estrat\u00e9gicos de Santo Domingo, evaluados previamente por la direcci\u00f3n de Movilidad Sostenible de esa instituci\u00f3n, para dar asistencia ante las posibles dificultades que puedan tener los conductores en esa demarcaci\u00f3n. Las ubicaciones donde estar\u00e1n disponible las gr\u00faas son el puente Juan Bosch, Ave. 27 de Febrero con M\u00e1ximo G\u00f3mez y con Tiradentes, Ave. Padre Castellanos con Josefa Brea, Ave. John F. Kennedy con M\u00e1ximo G\u00f3mez, John F. Kennedy con Tiradentes y con N\u00fa\u00f1ez de C\u00e1ceres, Ave. Jacobo Majluta con Rep\u00fablica de Colombia, M\u00e1ximo G\u00f3mez con George Washington y el Puente Flotante. El director del Intrant reiter\u00f3 adem\u00e1s a los ciudadanos conducir con precauci\u00f3n ante las condiciones del tiempo y tomar en cuenta acciones de seguridad vial como el buen estado de los parabrisas, luces, frenos y neum\u00e1ticos y cuidar la velocidad dado los deslizamientos que pueden producirse por el pavimento mojado. Las acciones del Intrant forman parte del plan de emergencia dispuesto por el presidente Luis Abinader para salvaguardar la vida de los ciudadanos, junto a los organismos competentes como el Centro de Operaciones de Emergencias (COE). En esa misma medida, el Intrant llam\u00f3 a los ciudadanos a comunicarse con el Sistema de Atenci\u00f3n a Emergencias (9-1-1), la l\u00ednea de asistencia vial del Ministerio de Obras P\u00fablicas y Comunicaciones (829) 688-1000 y en el WhatsApp del Intrant en el (849) 455-2772.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-128236","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/128236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=128236"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/128236\/revisions"}],"predecessor-version":[{"id":128238,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/128236\/revisions\/128238"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=128236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=128236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=128236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}