{"id":128271,"date":"2023-08-27T11:25:49","date_gmt":"2023-08-27T15:25:49","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=128271"},"modified":"2023-08-27T11:25:49","modified_gmt":"2023-08-27T15:25:49","slug":"wellington-arnaud-recorre-puntos-criticos-canadas-bella-vista-y-naga-en-haina","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2023\/08\/27\/wellington-arnaud-recorre-puntos-criticos-canadas-bella-vista-y-naga-en-haina\/","title":{"rendered":"Wellington Arnaud recorre puntos cr\u00edticos ca\u00f1adas Bella Vista y \u00d1ag\u00e1, en Haina"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-128272 aligncenter\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2023\/08\/unnamed-1-800x533.jpg\" alt=\"\" width=\"800\" height=\"533\" \/>El director ejecutivo del Instituto Nacional de Aguas Potables y Alcantarillados (INAPA), Wellington Arnaud, realiz\u00f3 un recorrido por las zonas m\u00e1s vulnerables de las ca\u00f1adas Bella Vista y \u00d1ag\u00e1, en Haina, provincia San Crist\u00f3bal, tras el paso por el pa\u00eds de la tormenta Franklin.<\/p>\n<p>En los pr\u00f3ximos d\u00edas una unidad t\u00e9cnica har\u00e1 las evaluaciones correspondientes, y posteriormente, se proceder\u00e1 con la intervenci\u00f3n, iniciando con la ca\u00f1ada de \u00d1ag\u00e1.<\/p>\n<p>Arnaud estuvo acompa\u00f1ado del alcalde Osvaldo Rodr\u00edguez, los diputados Frank Junior Guerrero, Otoniel Tejeda y Margarita Tejeda, as\u00ed como de l\u00edderes comunitarios de la zona.<\/p>\n<p>Asimismo, el funcionario expres\u00f3 que el servicio de agua est\u00e1 siendo restablecido, luego de que 120 acueductos fueran sacados de funcionamiento de manera preventiva por la tormenta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El director ejecutivo del Instituto Nacional de Aguas Potables y Alcantarillados (INAPA), Wellington Arnaud, realiz\u00f3 un recorrido por las zonas m\u00e1s vulnerables de las ca\u00f1adas Bella Vista y \u00d1ag\u00e1, en Haina, provincia San Crist\u00f3bal, tras el paso por el pa\u00eds de la tormenta Franklin. En los pr\u00f3ximos d\u00edas una unidad t\u00e9cnica har\u00e1 las evaluaciones correspondientes, y posteriormente, se proceder\u00e1 con la intervenci\u00f3n, iniciando con la ca\u00f1ada de \u00d1ag\u00e1. Arnaud estuvo acompa\u00f1ado del alcalde Osvaldo Rodr\u00edguez, los diputados Frank Junior Guerrero, Otoniel Tejeda y Margarita Tejeda, as\u00ed como de l\u00edderes comunitarios de la zona. Asimismo, el funcionario expres\u00f3 que el servicio de agua est\u00e1 siendo restablecido, luego de que 120 acueductos fueran sacados de funcionamiento de manera preventiva por la tormenta.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-128271","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/128271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=128271"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/128271\/revisions"}],"predecessor-version":[{"id":128273,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/128271\/revisions\/128273"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=128271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=128271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=128271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}