{"id":130857,"date":"2024-01-21T09:43:53","date_gmt":"2024-01-21T13:43:53","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=130857"},"modified":"2024-01-21T09:43:53","modified_gmt":"2024-01-21T13:43:53","slug":"lmd-avanza-trabajos-instalacion-centro-formativo-en-alianza-con-naciones-unidas","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2024\/01\/21\/lmd-avanza-trabajos-instalacion-centro-formativo-en-alianza-con-naciones-unidas\/","title":{"rendered":"LMD avanza trabajos instalaci\u00f3n centro formativo en alianza con Naciones Unidas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-130858 aligncenter\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-18-at-8.29.39-AM-800x600.jpg\" alt=\"\" width=\"800\" height=\"600\" \/>Santo Domingo.\u00a0\u2013 Avanzan a buen ritmo, los trabajos para la instalaci\u00f3n en el edificio de la Liga Municipal Dominicana (LMD) del Centro Internacional de Formaci\u00f3n para Autoridades y L\u00edderes (CIFAL) de Naciones Unidas.<\/p>\n<p>&nbsp;<\/p>\n<p>As\u00ed lo inform\u00f3 el presidente de la Liga Municipal Dominicana, V\u00edctor D\u00b4Aza, quien detall\u00f3 que la apertura del centro de formaci\u00f3n coincidir\u00e1 con la inauguraci\u00f3n del remozamiento a que est\u00e1 sometida desde hace varios meses la planta f\u00edsica de la LMD.<\/p>\n<p>&nbsp;<\/p>\n<p>Este centro formativo de excelencia para autoridades p\u00fablicas, tanto del nivel local como congresual, ser\u00e1 el primero en Centro Am\u00e9rica y el Caribe por lo que ser\u00e1 utilizado como espacio para la formaci\u00f3n de la dirigencia pol\u00edtica y de la sociedad civil de la regi\u00f3n del Caribe y Centroam\u00e9rica.<\/p>\n<p>&nbsp;<\/p>\n<p>La gesti\u00f3n institucional para la instalaci\u00f3n en la Rep\u00fablica Dominicana del CIFAL fue encabezada por el presidente de la Liga Municipal Dominicana, V\u00edctor D\u00b4Aza, quien sostuvo encuentros de trabajo tanto en Ginebra como en el pa\u00eds, con una delegaci\u00f3n del Instituto de Formaci\u00f3n e Investigaci\u00f3n de Naciones Unidas (UNITAR), integrada por Nikhil Seth, secretario general adjunto de la ONU y director de UNITAR; y Alex Mej\u00eda, director de la divisi\u00f3n social de este instituto.<\/p>\n<p>&nbsp;<\/p>\n<p>Como organismo de Naciones Unidas, UNITAR integra una red global de centros de formaci\u00f3n a lo largo de los diferentes continentes desde los cuales se trabaja de manera transversal los Objetivos de Desarrollo Sostenible (ODS).<\/p>\n<p>&nbsp;<\/p>\n<p>Estos centros denominados CIFAL se constituyen como espacios formativos sobre temas fundamentales para el desarrollo de las comunidades como son: planificaci\u00f3n urbana, desarrollo econ\u00f3mico local, inclusi\u00f3n social, sostenibilidad ambiental, liderazgo del sector p\u00fablico, transparencia, alianzas p\u00fablico-privadas y responsabilidad social corporativa.<\/p>\n<p>&nbsp;<\/p>\n<p>En total esta red est\u00e1 integrada por 30 centros que se encuentran instalados en Asia, Ocean\u00eda, \u00c1frica, Europa y Am\u00e9rica, con una oferta formativa dirigida a funcionarios p\u00fablicos, as\u00ed como a representantes de sociedad civil y del sector privado.<\/p>\n<p>&nbsp;<\/p>\n<p>Este acuerdo entre Unitar y la Liga Municipal, cuenta con el benepl\u00e1cito y visto bueno institucional del Mirex y de su ministro Roberto \u00c1lvarez.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.\u00a0\u2013 Avanzan a buen ritmo, los trabajos para la instalaci\u00f3n en el edificio de la Liga Municipal Dominicana (LMD) del Centro Internacional de Formaci\u00f3n para Autoridades y L\u00edderes (CIFAL) de Naciones Unidas. &nbsp; As\u00ed lo inform\u00f3 el presidente de la Liga Municipal Dominicana, V\u00edctor D\u00b4Aza, quien detall\u00f3 que la apertura del centro de formaci\u00f3n coincidir\u00e1 con la inauguraci\u00f3n del remozamiento a que est\u00e1 sometida desde hace varios meses la planta f\u00edsica de la LMD. &nbsp; Este centro formativo de excelencia para autoridades p\u00fablicas, tanto del nivel local como congresual, ser\u00e1 el primero en Centro Am\u00e9rica y el Caribe por lo que ser\u00e1 utilizado como espacio para la formaci\u00f3n de la dirigencia pol\u00edtica y de la sociedad civil de la regi\u00f3n del Caribe y Centroam\u00e9rica. &nbsp; La gesti\u00f3n institucional para la instalaci\u00f3n en la Rep\u00fablica Dominicana del CIFAL fue encabezada por el presidente de la Liga Municipal Dominicana, V\u00edctor D\u00b4Aza, quien sostuvo encuentros de trabajo tanto en Ginebra como en el pa\u00eds, con una delegaci\u00f3n del Instituto de Formaci\u00f3n e Investigaci\u00f3n de Naciones Unidas (UNITAR), integrada por Nikhil Seth, secretario general adjunto de la ONU y director de UNITAR; y Alex Mej\u00eda, director de la divisi\u00f3n social de este instituto. &nbsp; Como organismo de Naciones Unidas, UNITAR integra una red global de centros de formaci\u00f3n a lo largo de los diferentes continentes desde los cuales se trabaja de manera transversal los Objetivos de Desarrollo Sostenible (ODS). &nbsp; Estos centros denominados CIFAL se constituyen como espacios formativos sobre temas fundamentales para el desarrollo de las comunidades como son: planificaci\u00f3n urbana, desarrollo econ\u00f3mico local, inclusi\u00f3n social, sostenibilidad ambiental, liderazgo del sector p\u00fablico, transparencia, alianzas p\u00fablico-privadas y responsabilidad social corporativa. &nbsp; En total esta red est\u00e1 integrada por 30 centros que se encuentran instalados en Asia, Ocean\u00eda, \u00c1frica, Europa y Am\u00e9rica, con una oferta formativa dirigida a funcionarios p\u00fablicos, as\u00ed como a representantes de sociedad civil y del sector privado. &nbsp; Este acuerdo entre Unitar y la Liga Municipal, cuenta con el benepl\u00e1cito y visto bueno institucional del Mirex y de su ministro Roberto \u00c1lvarez.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-130857","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/130857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=130857"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/130857\/revisions"}],"predecessor-version":[{"id":130859,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/130857\/revisions\/130859"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=130857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=130857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=130857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}