{"id":132938,"date":"2024-09-01T10:31:31","date_gmt":"2024-09-01T14:31:31","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=132938"},"modified":"2024-09-01T10:31:31","modified_gmt":"2024-09-01T14:31:31","slug":"alcaldia-del-dn-ejecuta-remodelacion-del-cementerio-municipal-de-la-avenida-independencia","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2024\/09\/01\/alcaldia-del-dn-ejecuta-remodelacion-del-cementerio-municipal-de-la-avenida-independencia\/","title":{"rendered":"Alcald\u00eda del DN ejecuta remodelaci\u00f3n del cementerio municipal de la avenida Independencia"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-132939 aligncenter\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2024\/09\/thumbnail_WhatsApp-Image-2024-08-30-at-9.18.00-AM-2-800x533.jpg\" alt=\"\" width=\"800\" height=\"533\" \/>La transformaci\u00f3n es impulsada por el compromiso de la alcaldesa de llevar bienestar y dignidad a cada rinc\u00f3n de la ciudad<\/strong><\/p>\n<p>Santo Domingo, DN &#8211; A prop\u00f3sito del bicentenario cementerio municipal de la avenida Independencia, la Alcald\u00eda del Distrito Nacional ejecuta un amplio remozamiento del camposanto que es considerado como un museo a cielo abierto.<\/p>\n<p>La intervenci\u00f3n inici\u00f3 el pasado mes de julio bajo las \u00f3rdenes de la alcaldesa Carolina Mej\u00eda, con la finalidad de dotar con condiciones m\u00e1s dignas al camposanto que no solamente es visitado por parientes de los fenecidos, sino tambi\u00e9n por quienes se ven atra\u00eddos por su valor arquitect\u00f3nico e hist\u00f3rico.<\/p>\n<p>El cabildo precis\u00f3 que se encuentra interviniendo la verja perimetral, incluyendo la restauraci\u00f3n de columnas perimetrales, muros intermedios, verjas met\u00e1licas intermedias, muro divisorio y pintura. De igual forma, se iniciar\u00e1 el proceso de restauraci\u00f3n de las tumbas.<\/p>\n<p>De igual forma, en el cementerio que data de 1824 y forma parte del legado patrimonial de la Rep\u00fablica Dominicana por sus m\u00e9ritos hist\u00f3ricos y art\u00edsticos, se reconstruyen la aceras norte, oeste y sur, donde se incluyen tambi\u00e9n contenes y embellecimiento con la colocaci\u00f3n de tierra negra y grama. Tambi\u00e9n se iluminar\u00e1 el camino interior y la acera de la Independencia.<\/p>\n<p>Adem\u00e1s, la alcald\u00eda interviene el camino interior en la v\u00eda principal del camposanto, donde se remueven los adoquines existentes y se sustituyen por nuevos, se reconstruye el muro Art Nouveau. Mientras que en la calle principal y la paralela a la Independencia se construir\u00e1n aceras y se colocar\u00e1n adoquines.<\/p>\n<p>La profunda transformaci\u00f3n del antiguo cementerio municipal es impulsada por el compromiso de la alcaldesa con seguir llevando bienestar a cada rinc\u00f3n de Santo Domingo.<\/p>\n<p>El antiguo cementerio municipal alberga sepulturas de pr\u00f3ceres de la Independencia y de la Restauraci\u00f3n, insignes maestros, poetas, pol\u00edticos, cient\u00edficos, m\u00fasicos, artistas e intelectuales de renombre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La transformaci\u00f3n es impulsada por el compromiso de la alcaldesa de llevar bienestar y dignidad a cada rinc\u00f3n de la ciudad Santo Domingo, DN &#8211; A prop\u00f3sito del bicentenario cementerio municipal de la avenida Independencia, la Alcald\u00eda del Distrito Nacional ejecuta un amplio remozamiento del camposanto que es considerado como un museo a cielo abierto. La intervenci\u00f3n inici\u00f3 el pasado mes de julio bajo las \u00f3rdenes de la alcaldesa Carolina Mej\u00eda, con la finalidad de dotar con condiciones m\u00e1s dignas al camposanto que no solamente es visitado por parientes de los fenecidos, sino tambi\u00e9n por quienes se ven atra\u00eddos por su valor arquitect\u00f3nico e hist\u00f3rico. El cabildo precis\u00f3 que se encuentra interviniendo la verja perimetral, incluyendo la restauraci\u00f3n de columnas perimetrales, muros intermedios, verjas met\u00e1licas intermedias, muro divisorio y pintura. De igual forma, se iniciar\u00e1 el proceso de restauraci\u00f3n de las tumbas. De igual forma, en el cementerio que data de 1824 y forma parte del legado patrimonial de la Rep\u00fablica Dominicana por sus m\u00e9ritos hist\u00f3ricos y art\u00edsticos, se reconstruyen la aceras norte, oeste y sur, donde se incluyen tambi\u00e9n contenes y embellecimiento con la colocaci\u00f3n de tierra negra y grama. Tambi\u00e9n se iluminar\u00e1 el camino interior y la acera de la Independencia. Adem\u00e1s, la alcald\u00eda interviene el camino interior en la v\u00eda principal del camposanto, donde se remueven los adoquines existentes y se sustituyen por nuevos, se reconstruye el muro Art Nouveau. Mientras que en la calle principal y la paralela a la Independencia se construir\u00e1n aceras y se colocar\u00e1n adoquines. La profunda transformaci\u00f3n del antiguo cementerio municipal es impulsada por el compromiso de la alcaldesa con seguir llevando bienestar a cada rinc\u00f3n de Santo Domingo. El antiguo cementerio municipal alberga sepulturas de pr\u00f3ceres de la Independencia y de la Restauraci\u00f3n, insignes maestros, poetas, pol\u00edticos, cient\u00edficos, m\u00fasicos, artistas e intelectuales de renombre.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-132938","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/132938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=132938"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/132938\/revisions"}],"predecessor-version":[{"id":132940,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/132938\/revisions\/132940"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=132938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=132938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=132938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}