{"id":132944,"date":"2024-09-01T11:33:40","date_gmt":"2024-09-01T15:33:40","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=132944"},"modified":"2024-09-01T11:33:40","modified_gmt":"2024-09-01T15:33:40","slug":"adosinet-saluda-designacion-de-guido-gomez-mazara-como-presidente-del-indotel","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2024\/09\/01\/adosinet-saluda-designacion-de-guido-gomez-mazara-como-presidente-del-indotel\/","title":{"rendered":"ADOSINET saluda designaci\u00f3n de Guido G\u00f3mez Mazara como presidente del Indotel"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-132945 aligncenter\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2024\/09\/b8f4f407-78af-447e-877e-6a15ba402dde-800x800.jpg\" alt=\"\" width=\"800\" height=\"800\" \/>La Asociaci\u00f3n Dominicana de Suplidores de Internet (ADOSINET) expres\u00f3 su satisfacci\u00f3n por la designaci\u00f3n del doctor Guido G\u00f3mez Mazara como nuevo presidente del Instituto Dominicano de las Telecomunicaciones (Indotel).<\/p>\n<p>A trav\u00e9s de un comunicado de prensa, el presidente de ADOSINET, Melvin Olmos Javier, destac\u00f3 la disposici\u00f3n de la asociaci\u00f3n para colaborar en los planes que se implementen para cerrar la brecha digital en la Rep\u00fablica Dominicana.<\/p>\n<p>ADOSINET, representando a sus miembros, solicit\u00f3 su inclusi\u00f3n en proyectos comunitarios y rurales como microempresarios locales, con el fin de continuar expandiendo la cobertura de Internet en todo el pa\u00eds.<\/p>\n<p>La asociaci\u00f3n espera que el nuevo presidente del Indotel valore las inversiones realizadas para asegurar la conectividad en \u00e1reas remotas del pa\u00eds.<\/p>\n<p>En ese orden, el gremio que agrupa a los suplidores de internet, se\u00f1al\u00f3 que la reducci\u00f3n de la brecha digital es posible con la integraci\u00f3n de los micro empresarios locales que invierten en este importante sector de la telecomunicaciones del pa\u00eds.<\/p>\n<p>Adem\u00e1s, record\u00f3 que en 2021, durante la pandemia de COVID-19, ADOSINET lanz\u00f3 el plan \u00abInternet Democr\u00e1tico\u00bb para garantizar la conectividad en instituciones ubicadas en zonas vulnerables.<\/p>\n<p>Olmos Javier subray\u00f3 la importancia de ADOSINET como complemento a los esfuerzos del Gobierno dominicano para mejorar la conectividad digital en esas \u00e1reas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Asociaci\u00f3n Dominicana de Suplidores de Internet (ADOSINET) expres\u00f3 su satisfacci\u00f3n por la designaci\u00f3n del doctor Guido G\u00f3mez Mazara como nuevo presidente del Instituto Dominicano de las Telecomunicaciones (Indotel). A trav\u00e9s de un comunicado de prensa, el presidente de ADOSINET, Melvin Olmos Javier, destac\u00f3 la disposici\u00f3n de la asociaci\u00f3n para colaborar en los planes que se implementen para cerrar la brecha digital en la Rep\u00fablica Dominicana. ADOSINET, representando a sus miembros, solicit\u00f3 su inclusi\u00f3n en proyectos comunitarios y rurales como microempresarios locales, con el fin de continuar expandiendo la cobertura de Internet en todo el pa\u00eds. La asociaci\u00f3n espera que el nuevo presidente del Indotel valore las inversiones realizadas para asegurar la conectividad en \u00e1reas remotas del pa\u00eds. En ese orden, el gremio que agrupa a los suplidores de internet, se\u00f1al\u00f3 que la reducci\u00f3n de la brecha digital es posible con la integraci\u00f3n de los micro empresarios locales que invierten en este importante sector de la telecomunicaciones del pa\u00eds. Adem\u00e1s, record\u00f3 que en 2021, durante la pandemia de COVID-19, ADOSINET lanz\u00f3 el plan \u00abInternet Democr\u00e1tico\u00bb para garantizar la conectividad en instituciones ubicadas en zonas vulnerables. Olmos Javier subray\u00f3 la importancia de ADOSINET como complemento a los esfuerzos del Gobierno dominicano para mejorar la conectividad digital en esas \u00e1reas.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-132944","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/132944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=132944"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/132944\/revisions"}],"predecessor-version":[{"id":132946,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/132944\/revisions\/132946"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=132944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=132944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=132944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}