{"id":133589,"date":"2024-12-08T12:57:20","date_gmt":"2024-12-08T16:57:20","guid":{"rendered":"https:\/\/conexiondigital.com.do\/?p=133589"},"modified":"2024-12-08T12:57:22","modified_gmt":"2024-12-08T16:57:22","slug":"ministro-de-salud-victor-atallah-presenta-26-documentos-normativos-para-fortalecer-la-calidad-en-la-atencion-sanitaria","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2024\/12\/08\/ministro-de-salud-victor-atallah-presenta-26-documentos-normativos-para-fortalecer-la-calidad-en-la-atencion-sanitaria\/","title":{"rendered":"Ministro de Salud, V\u00edctor Atallah presenta 26 documentos normativos para fortalecer la calidad en la atenci\u00f3n sanitaria"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2024\/12\/1619c1bf-93fc-49c2-9455-8bcf7860017c-1024x665.jpg\" alt=\"\" class=\"wp-image-133590\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El dossier ofrece una estandarizaci\u00f3n de la atenci\u00f3n que se ofrece a las personas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Santo Domingo- El ministro de Salud, V\u00edctor Atallah, encabez\u00f3 el acto de lanzamiento de los Documentos Normativos y T\u00e9cnicos Sanitarios para diversos Eventos Cl\u00ednicos, a trav\u00e9s de los cuales se ofrecer\u00e1 una mejor garant\u00eda de la calidad de los servicios de salud en el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La documentaci\u00f3n est\u00e1 compuesta por gu\u00edas de atenci\u00f3n en salud, manuales, procedimientos, informes y protocolos de atenci\u00f3n, con el objetivo de promover la calidad de la atenci\u00f3n, impactar positivamente en la poblaci\u00f3n y fortalecer la capacitaci\u00f3n continua del sector salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el acto, Atallah precis\u00f3 que estos documentos, que abarcan diversas especialidades m\u00e9dicas, ofrecen una estandarizaci\u00f3n de la atenci\u00f3n que se ofrece a las personas y los protocolos necesarios para quienes trabajan en el sector salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl Ministerio de Salud P\u00fablica se enorgullece de presentar hoy esta cantidad enorme de documentos en colaboraci\u00f3n con diversos sectores. Si hay algo en lo que nosotros vamos a trabajar es en normas, protocolos, capacitaci\u00f3n y concientizaci\u00f3n para la mejor\u00eda de nuestros recursos humanos\u201d, afirm\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, destac\u00f3 que tanto el Ministerio de Salud y el Gobierno se encuentran trabajando en sinergia con todas las sociedades m\u00e9dicas para lograr el apoyo necesario para que los proyectos que se est\u00e1n realizando sean un logro en com\u00fan que beneficie a toda la poblaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De su lado, Winston Genao, director de Coordinaci\u00f3n T\u00e9cnica del Viceministerio de la Garant\u00eda de la Calidad de los servicios de Salud, indic\u00f3 que la puesta en circulaci\u00f3n de los documentos normativos es un proceso trascendental que asegura y refuerza la calidad de la atenci\u00f3n en salud a las personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCon regocijo anunciamos la puesta en vigencia de este seriado de documentos que vienen a satisfacer el requerimiento pendiente de estandarizar el manejo de las patolog\u00edas de mayor demanda que se registran en nuestros centros p\u00fablicos y privados\u201d, dijo Genao.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto que Milagros Pe\u00f1a, directora de Normas, Gu\u00edas y Protocolos, extern\u00f3 que la documentaci\u00f3n dotar\u00e1 al sector salud de los procedimientos especializados que favorecer\u00e1n el tratamiento oportuno e integral y con la garant\u00eda de la calidad que la poblaci\u00f3n dominicana amerita.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presentaci\u00f3n de los documentos estuvo a cargo de Anel Payero Gonz\u00e1lez, encargada del departamento de Documentos T\u00e9cnicos Sanitarios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los 26 Documentos Normativos y T\u00e9cnicos Sanitarios incluyen el reglamento t\u00e9cnico para la habilitaci\u00f3n de los servicios cl\u00ednicos, quir\u00fargicos y diagn\u00f3sticos; el cuadro b\u00e1sico medicamentos esenciales de Rep\u00fablica Dominicana; la jornada nacional de tipificaci\u00f3n sangu\u00ednea: informe de resultados; la jornada nacional de diabetes: informe de resultados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n forman parte de estos protocolos y gu\u00eda las normas generales para la implementaci\u00f3n de la revista dominicana de Salud P\u00fablica; la gu\u00eda de llenado de la c\u00e9dula del ni\u00f1o y de la ni\u00f1a; los procedimientos de cuidados de enfermer\u00eda en la canalizaci\u00f3n umbilical, los protocolos de manejo de Linfoma Hodgkin en adultos; los Informe de medici\u00f3n del gasto en tuberculosis en la Rep\u00fablica Dominicana entre otros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el acto estuvieron presentes representantes del Servicio Nacional de Salud (SNS), la Sociedad Dominicana de Senolog\u00eda, de la Asociaci\u00f3n Nacional de Cl\u00ednicas Privadas (ANDECLIP), la Sociedad Dominicana de Hematolog\u00eda, la Organizaci\u00f3n Panamericana de Salud (OPS), Sociedad Dominicana de Oncolog\u00eda, de la Agencia de los Estados Unidos para el Desarrollo Internacional (USAID), de la Sociedad Dominicana de Cirug\u00eda Pl\u00e1stica, Reconstructiva y Est\u00e9tica (SODOCIPRE) entre otros organismos de salud.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El dossier ofrece una estandarizaci\u00f3n de la atenci\u00f3n que se ofrece a las personas Santo Domingo- El ministro de Salud, V\u00edctor Atallah, encabez\u00f3 el acto de lanzamiento de los Documentos Normativos y T\u00e9cnicos Sanitarios para diversos Eventos Cl\u00ednicos, a trav\u00e9s de los cuales se ofrecer\u00e1 una mejor garant\u00eda de la calidad de los servicios de salud en el pa\u00eds. La documentaci\u00f3n est\u00e1 compuesta por gu\u00edas de atenci\u00f3n en salud, manuales, procedimientos, informes y protocolos de atenci\u00f3n, con el objetivo de promover la calidad de la atenci\u00f3n, impactar positivamente en la poblaci\u00f3n y fortalecer la capacitaci\u00f3n continua del sector salud. Durante el acto, Atallah precis\u00f3 que estos documentos, que abarcan diversas especialidades m\u00e9dicas, ofrecen una estandarizaci\u00f3n de la atenci\u00f3n que se ofrece a las personas y los protocolos necesarios para quienes trabajan en el sector salud. \u201cEl Ministerio de Salud P\u00fablica se enorgullece de presentar hoy esta cantidad enorme de documentos en colaboraci\u00f3n con diversos sectores. Si hay algo en lo que nosotros vamos a trabajar es en normas, protocolos, capacitaci\u00f3n y concientizaci\u00f3n para la mejor\u00eda de nuestros recursos humanos\u201d, afirm\u00f3. Asimismo, destac\u00f3 que tanto el Ministerio de Salud y el Gobierno se encuentran trabajando en sinergia con todas las sociedades m\u00e9dicas para lograr el apoyo necesario para que los proyectos que se est\u00e1n realizando sean un logro en com\u00fan que beneficie a toda la poblaci\u00f3n. De su lado, Winston Genao, director de Coordinaci\u00f3n T\u00e9cnica del Viceministerio de la Garant\u00eda de la Calidad de los servicios de Salud, indic\u00f3 que la puesta en circulaci\u00f3n de los documentos normativos es un proceso trascendental que asegura y refuerza la calidad de la atenci\u00f3n en salud a las personas. \u201cCon regocijo anunciamos la puesta en vigencia de este seriado de documentos que vienen a satisfacer el requerimiento pendiente de estandarizar el manejo de las patolog\u00edas de mayor demanda que se registran en nuestros centros p\u00fablicos y privados\u201d, dijo Genao. En tanto que Milagros Pe\u00f1a, directora de Normas, Gu\u00edas y Protocolos, extern\u00f3 que la documentaci\u00f3n dotar\u00e1 al sector salud de los procedimientos especializados que favorecer\u00e1n el tratamiento oportuno e integral y con la garant\u00eda de la calidad que la poblaci\u00f3n dominicana amerita. La presentaci\u00f3n de los documentos estuvo a cargo de Anel Payero Gonz\u00e1lez, encargada del departamento de Documentos T\u00e9cnicos Sanitarios. Los 26 Documentos Normativos y T\u00e9cnicos Sanitarios incluyen el reglamento t\u00e9cnico para la habilitaci\u00f3n de los servicios cl\u00ednicos, quir\u00fargicos y diagn\u00f3sticos; el cuadro b\u00e1sico medicamentos esenciales de Rep\u00fablica Dominicana; la jornada nacional de tipificaci\u00f3n sangu\u00ednea: informe de resultados; la jornada nacional de diabetes: informe de resultados. Tambi\u00e9n forman parte de estos protocolos y gu\u00eda las normas generales para la implementaci\u00f3n de la revista dominicana de Salud P\u00fablica; la gu\u00eda de llenado de la c\u00e9dula del ni\u00f1o y de la ni\u00f1a; los procedimientos de cuidados de enfermer\u00eda en la canalizaci\u00f3n umbilical, los protocolos de manejo de Linfoma Hodgkin en adultos; los Informe de medici\u00f3n del gasto en tuberculosis en la Rep\u00fablica Dominicana entre otros. En el acto estuvieron presentes representantes del Servicio Nacional de Salud (SNS), la Sociedad Dominicana de Senolog\u00eda, de la Asociaci\u00f3n Nacional de Cl\u00ednicas Privadas (ANDECLIP), la Sociedad Dominicana de Hematolog\u00eda, la Organizaci\u00f3n Panamericana de Salud (OPS), Sociedad Dominicana de Oncolog\u00eda, de la Agencia de los Estados Unidos para el Desarrollo Internacional (USAID), de la Sociedad Dominicana de Cirug\u00eda Pl\u00e1stica, Reconstructiva y Est\u00e9tica (SODOCIPRE) entre otros organismos de salud.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-133589","post","type-post","status-publish","format-standard","hentry","category-nature"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/133589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=133589"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/133589\/revisions"}],"predecessor-version":[{"id":133591,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/133589\/revisions\/133591"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=133589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=133589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=133589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}