{"id":133631,"date":"2024-12-08T13:42:25","date_gmt":"2024-12-08T17:42:25","guid":{"rendered":"https:\/\/conexiondigital.com.do\/?p=133631"},"modified":"2024-12-08T13:42:27","modified_gmt":"2024-12-08T17:42:27","slug":"franklin-garcia-fermin-las-universidades-dominicanas-estan-apareciendo-en-los-rankings-internacionales-entre-las-mejores","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2024\/12\/08\/franklin-garcia-fermin-las-universidades-dominicanas-estan-apareciendo-en-los-rankings-internacionales-entre-las-mejores\/","title":{"rendered":"Franklin Garc\u00eda Ferm\u00edn: Las universidades dominicanas est\u00e1n apareciendo en los rankings internacionales entre las mejores"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2024\/12\/thumbnail_PHOTO-2024-12-06-18-59-53.jpg\" alt=\"\" class=\"wp-image-133632\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cLas universidades dominicanas van muy bien y est\u00e1n fortaleciendo cada d\u00eda la calidad\u201d<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Afirma que PRM tomar\u00e1 medidas para evitar campa\u00f1a a destiempo<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Ministro de Educaci\u00f3n Superior, Ciencia y Tecnolog\u00edas (MECyT), doctor Franklin Garc\u00eda Ferm\u00edn, proclam\u00f3 que la elevaci\u00f3n de la calidad de las universidades de Rep\u00fablica Dominicana ha originado que comiencen a aparecer en los rankings entre las mejores en Am\u00e9rica Latina y el Caribe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entrevistado por el periodista Federico M\u00e9ndez, en el programa Esferas de Poder, que se transmite los domingos de 8:00 a 9:00 de la ma\u00f1ana, por RNN Canal 27, asegur\u00f3 que la educaci\u00f3n superior en el pa\u00eds es robusta y ha fortalecido su calidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPero tambi\u00e9n en los rankings mundiales ya estamos apareciendo, que no aparec\u00edamos, pero no porque no tengamos la calidad para aparecer, sino porque muchas veces no hac\u00edamos lo que hay que hacer para aparecer en esos rankings\u201d, argumenta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Revel\u00f3 que en el pasado las universidades dominicanas no aparec\u00edan en los estudios de calidad internacionales, pero ahora comienzan a aparecer cuando se eval\u00faan las academias a nivel mundial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asegur\u00f3 que los proyectos de investigaci\u00f3n que tienen las universidades constituyen factores que influyen para figurar entre las mejores academias a nivel internacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Garc\u00eda Ferm\u00edn sostuvo que el MECyT dispone de fondos para que las universidades sometan proyectos de investigaci\u00f3n, para su evaluaci\u00f3n y aprobaci\u00f3n, con la participaci\u00f3n de expertos nacionales e internacionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Expuso que las universidades est\u00e1n siendo sometidas a una evaluaci\u00f3n quinquenal, donde se examinan externa e internamente las academias, el cual concluy\u00f3 el a\u00f1o pasado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa educaci\u00f3n superior en la Rep\u00fablica Dominicana ha mejorado y ha avanzado de manera sustancial y un hecho que puedo agregar al ya explicado de la evaluaci\u00f3n quinquenal es que ya estamos apareciendo en las evaluaciones y en los estudios de instituciones a nivel del mundo\u201d, adujo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El funcionario dijo que en revistas de prestigio internacional est\u00e1n apareciendo publicaciones indexadas de investigaciones hechas por acad\u00e9micos e investigadores en la Rep\u00fablica Dominicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA la hora de evaluar y medir los rankings eso tiene una importancia capital\u201d, enfatiz\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Afirma que PRM tomar\u00e1 medidas para evitar campa\u00f1a a destiempo<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Ministro de Educaci\u00f3n Superior, Ciencia y Tecnolog\u00edas (MECyT) y miembro de la Direcci\u00f3n Ejecutiva del Partido Revolucionario Moderno (PRM), doctor Franklin Garc\u00eda Ferm\u00edn, advirti\u00f3 que la organizaci\u00f3n adoptar\u00e1 medidas para evitar una campa\u00f1a interna a destiempo de aspirantes presidenciales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El jurista y dirigente pol\u00edtico consider\u00f3 que no es el momento para que afloren aspiraciones presidenciales en esa organizaci\u00f3n pol\u00edtica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Manifest\u00f3 que actualmente no puede haber una lucha interna por aspiraciones a la candidatura presidencial con miras al 2028, porque eso contribuir\u00e1 a una distracci\u00f3n de las cosas fundamentales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El dirigente pol\u00edtico exhort\u00f3 a los perreme\u00edstas a esperar que llegue el momento de la competencia interna, que no es el actual, cumpliendo con el mandato de la Ley Electoral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDebo decir, ante todo, que en el momento que estamos viviendo los perreme\u00edstas y nuestros aliados es para gobernar y hacerlo bien, trabajar para seguir haciendo un gobierno honesto, de grandes realizaciones, como lo han sido estos primeros cuatro a\u00f1os\u201d, adujo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Record\u00f3 que el presidente del PRM, Jos\u00e9 Ignacio Paliza, anunci\u00f3 que en enero la Direcci\u00f3n Ejecutiva se reunir\u00e1 para decidir los pasos a seguir en torno a la estrategia de cara al 2028.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cLas universidades dominicanas van muy bien y est\u00e1n fortaleciendo cada d\u00eda la calidad\u201d Afirma que PRM tomar\u00e1 medidas para evitar campa\u00f1a a destiempo El Ministro de Educaci\u00f3n Superior, Ciencia y Tecnolog\u00edas (MECyT), doctor Franklin Garc\u00eda Ferm\u00edn, proclam\u00f3 que la elevaci\u00f3n de la calidad de las universidades de Rep\u00fablica Dominicana ha originado que comiencen a aparecer en los rankings entre las mejores en Am\u00e9rica Latina y el Caribe. Entrevistado por el periodista Federico M\u00e9ndez, en el programa Esferas de Poder, que se transmite los domingos de 8:00 a 9:00 de la ma\u00f1ana, por RNN Canal 27, asegur\u00f3 que la educaci\u00f3n superior en el pa\u00eds es robusta y ha fortalecido su calidad. \u201cPero tambi\u00e9n en los rankings mundiales ya estamos apareciendo, que no aparec\u00edamos, pero no porque no tengamos la calidad para aparecer, sino porque muchas veces no hac\u00edamos lo que hay que hacer para aparecer en esos rankings\u201d, argumenta. Revel\u00f3 que en el pasado las universidades dominicanas no aparec\u00edan en los estudios de calidad internacionales, pero ahora comienzan a aparecer cuando se eval\u00faan las academias a nivel mundial. Asegur\u00f3 que los proyectos de investigaci\u00f3n que tienen las universidades constituyen factores que influyen para figurar entre las mejores academias a nivel internacional. Garc\u00eda Ferm\u00edn sostuvo que el MECyT dispone de fondos para que las universidades sometan proyectos de investigaci\u00f3n, para su evaluaci\u00f3n y aprobaci\u00f3n, con la participaci\u00f3n de expertos nacionales e internacionales. Expuso que las universidades est\u00e1n siendo sometidas a una evaluaci\u00f3n quinquenal, donde se examinan externa e internamente las academias, el cual concluy\u00f3 el a\u00f1o pasado. \u201cLa educaci\u00f3n superior en la Rep\u00fablica Dominicana ha mejorado y ha avanzado de manera sustancial y un hecho que puedo agregar al ya explicado de la evaluaci\u00f3n quinquenal es que ya estamos apareciendo en las evaluaciones y en los estudios de instituciones a nivel del mundo\u201d, adujo. El funcionario dijo que en revistas de prestigio internacional est\u00e1n apareciendo publicaciones indexadas de investigaciones hechas por acad\u00e9micos e investigadores en la Rep\u00fablica Dominicana. \u201cA la hora de evaluar y medir los rankings eso tiene una importancia capital\u201d, enfatiz\u00f3. Afirma que PRM tomar\u00e1 medidas para evitar campa\u00f1a a destiempo El Ministro de Educaci\u00f3n Superior, Ciencia y Tecnolog\u00edas (MECyT) y miembro de la Direcci\u00f3n Ejecutiva del Partido Revolucionario Moderno (PRM), doctor Franklin Garc\u00eda Ferm\u00edn, advirti\u00f3 que la organizaci\u00f3n adoptar\u00e1 medidas para evitar una campa\u00f1a interna a destiempo de aspirantes presidenciales. El jurista y dirigente pol\u00edtico consider\u00f3 que no es el momento para que afloren aspiraciones presidenciales en esa organizaci\u00f3n pol\u00edtica. Manifest\u00f3 que actualmente no puede haber una lucha interna por aspiraciones a la candidatura presidencial con miras al 2028, porque eso contribuir\u00e1 a una distracci\u00f3n de las cosas fundamentales. El dirigente pol\u00edtico exhort\u00f3 a los perreme\u00edstas a esperar que llegue el momento de la competencia interna, que no es el actual, cumpliendo con el mandato de la Ley Electoral. \u201cDebo decir, ante todo, que en el momento que estamos viviendo los perreme\u00edstas y nuestros aliados es para gobernar y hacerlo bien, trabajar para seguir haciendo un gobierno honesto, de grandes realizaciones, como lo han sido estos primeros cuatro a\u00f1os\u201d, adujo. Record\u00f3 que el presidente del PRM, Jos\u00e9 Ignacio Paliza, anunci\u00f3 que en enero la Direcci\u00f3n Ejecutiva se reunir\u00e1 para decidir los pasos a seguir en torno a la estrategia de cara al 2028.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-133631","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/133631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=133631"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/133631\/revisions"}],"predecessor-version":[{"id":133633,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/133631\/revisions\/133633"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=133631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=133631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=133631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}