{"id":135570,"date":"2025-03-11T20:59:20","date_gmt":"2025-03-12T00:59:20","guid":{"rendered":"https:\/\/conexiondigital.com.do\/?p=135570"},"modified":"2025-03-11T20:59:21","modified_gmt":"2025-03-12T00:59:21","slug":"contraloria-inicia-tercera-certificacion-en-control-interno-bajo-la-normativa-coso","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2025\/03\/11\/contraloria-inicia-tercera-certificacion-en-control-interno-bajo-la-normativa-coso\/","title":{"rendered":"Contralor\u00eda inicia tercera certificaci\u00f3n en\u00a0Control\u00a0Interno bajo la normativa COSO"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/03\/thumbnail_Actividad-COSO-3-1024x682.jpg\" alt=\"\" class=\"wp-image-135571\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Santo Domingo, R. D.-<\/strong>&nbsp;La Contralor\u00eda General de la Rep\u00fablica (CGR) inici\u00f3 la tercera convocatoria de la certificaci\u00f3n en Control Interno, bajo el marco normativo del Comit\u00e9 de Organizaciones Patrocinadoras de la Comisi\u00f3n Treadway (COSO,&nbsp;<em>por sus siglas en ingl\u00e9s<\/em>).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">COSO es un marco de control ampliamente utilizado para mejorar la gesti\u00f3n de riesgo, el control interno y el gobierno corporativo, tanto en el sector p\u00fablico como privado, el cual contribuye a fortalecer el cumplimiento normativo y la transparencia en la gesti\u00f3n de recursos, as\u00ed como la optimizaci\u00f3n de los procesos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El contralor general de la Rep\u00fablica, F\u00e9lix Santana Garc\u00eda, expres\u00f3 que&nbsp;<em>\u201ccon iniciativas como esta, la Contralor\u00eda sigue avanzando en su misi\u00f3n de fortalecer la transparencia y el buen gobierno, asegurando que sus colaboradores cuenten con las herramientas necesarias para enfrentar los desaf\u00edos de la administraci\u00f3n p\u00fablica, en el \u00e1mbito de la fiscalizaci\u00f3n y uso de los recursos\u201d<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta nueva edici\u00f3n, realizada con el apoyo del Banco Interamericano de Desarrollo (BID), participan 50 colaboradores de diferentes \u00e1reas de la instituci\u00f3n, cuyo objetivo es fortalecer sus competencias en gesti\u00f3n de riesgos y control interno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con esta convocatoria, que tiene como sede la Escuela Nacional de Control Interno (ENCI) de la Contralor\u00eda, ascender\u00e1 a 150 el n\u00famero de colaboradores formados en dicha normativa, reafirmando el compromiso de la CGR con el fortalecimiento institucional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta capacitaci\u00f3n es desarrollada por el Instituto de Auditores Internos de Rep\u00fablica Dominicana (IAIRD), con la participaci\u00f3n de expertos en control interno y gesti\u00f3n p\u00fablica, quienes aportar\u00e1n conocimientos claves para potenciar las capacidades t\u00e9cnicas de los colaboradores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este proceso formativo se enmarca dentro del Programa de Apoyo a la Agenda de Transparencia e Integridad en Rep\u00fablica Dominicana (ProTransparenciaRD), con el objetivo de fortalecer el Sistema Nacional de Control Interno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, se alinea con los esfuerzos del Decreto n\u00fam. 76-25, que crea la Comisi\u00f3n Nacional de Transparencia y Anticorrupci\u00f3n (CPTA), que busca consolidar una cultura de integridad y control en la gesti\u00f3n p\u00fablica, en respuesta a los desaf\u00edos que plantea la corrupci\u00f3n para la estabilidad institucional y el desarrollo del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Decreto 76-25 establece que la lucha contra la corrupci\u00f3n y la promoci\u00f3n de la transparencia son fundamentales para fortalecer la confianza en el Estado y cumplir con los compromisos internacionales en materia de gobernanza. En ese sentido, la certificaci\u00f3n en Control Interno bajo el marco COSO se convierte en una herramienta clave para avanzar hacia una administraci\u00f3n m\u00e1s eficiente, con mayor transparencia en la gesti\u00f3n p\u00fablica, reducci\u00f3n de la corrupci\u00f3n e impunidad, uso eficiente de los recursos del Estado y fortalecimiento de la confianza en el Gobierno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo, R. D.-&nbsp;La Contralor\u00eda General de la Rep\u00fablica (CGR) inici\u00f3 la tercera convocatoria de la certificaci\u00f3n en Control Interno, bajo el marco normativo del Comit\u00e9 de Organizaciones Patrocinadoras de la Comisi\u00f3n Treadway (COSO,&nbsp;por sus siglas en ingl\u00e9s). COSO es un marco de control ampliamente utilizado para mejorar la gesti\u00f3n de riesgo, el control interno y el gobierno corporativo, tanto en el sector p\u00fablico como privado, el cual contribuye a fortalecer el cumplimiento normativo y la transparencia en la gesti\u00f3n de recursos, as\u00ed como la optimizaci\u00f3n de los procesos. El contralor general de la Rep\u00fablica, F\u00e9lix Santana Garc\u00eda, expres\u00f3 que&nbsp;\u201ccon iniciativas como esta, la Contralor\u00eda sigue avanzando en su misi\u00f3n de fortalecer la transparencia y el buen gobierno, asegurando que sus colaboradores cuenten con las herramientas necesarias para enfrentar los desaf\u00edos de la administraci\u00f3n p\u00fablica, en el \u00e1mbito de la fiscalizaci\u00f3n y uso de los recursos\u201d. En esta nueva edici\u00f3n, realizada con el apoyo del Banco Interamericano de Desarrollo (BID), participan 50 colaboradores de diferentes \u00e1reas de la instituci\u00f3n, cuyo objetivo es fortalecer sus competencias en gesti\u00f3n de riesgos y control interno. Con esta convocatoria, que tiene como sede la Escuela Nacional de Control Interno (ENCI) de la Contralor\u00eda, ascender\u00e1 a 150 el n\u00famero de colaboradores formados en dicha normativa, reafirmando el compromiso de la CGR con el fortalecimiento institucional. Esta capacitaci\u00f3n es desarrollada por el Instituto de Auditores Internos de Rep\u00fablica Dominicana (IAIRD), con la participaci\u00f3n de expertos en control interno y gesti\u00f3n p\u00fablica, quienes aportar\u00e1n conocimientos claves para potenciar las capacidades t\u00e9cnicas de los colaboradores. Este proceso formativo se enmarca dentro del Programa de Apoyo a la Agenda de Transparencia e Integridad en Rep\u00fablica Dominicana (ProTransparenciaRD), con el objetivo de fortalecer el Sistema Nacional de Control Interno. Adem\u00e1s, se alinea con los esfuerzos del Decreto n\u00fam. 76-25, que crea la Comisi\u00f3n Nacional de Transparencia y Anticorrupci\u00f3n (CPTA), que busca consolidar una cultura de integridad y control en la gesti\u00f3n p\u00fablica, en respuesta a los desaf\u00edos que plantea la corrupci\u00f3n para la estabilidad institucional y el desarrollo del pa\u00eds. El Decreto 76-25 establece que la lucha contra la corrupci\u00f3n y la promoci\u00f3n de la transparencia son fundamentales para fortalecer la confianza en el Estado y cumplir con los compromisos internacionales en materia de gobernanza. En ese sentido, la certificaci\u00f3n en Control Interno bajo el marco COSO se convierte en una herramienta clave para avanzar hacia una administraci\u00f3n m\u00e1s eficiente, con mayor transparencia en la gesti\u00f3n p\u00fablica, reducci\u00f3n de la corrupci\u00f3n e impunidad, uso eficiente de los recursos del Estado y fortalecimiento de la confianza en el Gobierno.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-135570","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/135570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=135570"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/135570\/revisions"}],"predecessor-version":[{"id":135572,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/135570\/revisions\/135572"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=135570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=135570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=135570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}