{"id":136260,"date":"2025-04-13T20:19:06","date_gmt":"2025-04-14T00:19:06","guid":{"rendered":"https:\/\/conexiondigital.com.do\/?p=136260"},"modified":"2025-04-13T20:19:44","modified_gmt":"2025-04-14T00:19:44","slug":"presidente-abinader-asiste-a-honras-funebres-de-la-gobernadora-de-montecristi-nelsy-cruz-2","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2025\/04\/13\/presidente-abinader-asiste-a-honras-funebres-de-la-gobernadora-de-montecristi-nelsy-cruz-2\/","title":{"rendered":"Presidente Abinader asiste a honras f\u00fanebres de la gobernadora de Montecristi, Nelsy Cruz"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/04\/th-3.jpg\" alt=\"\" class=\"wp-image-136261\" style=\"width:840px;height:auto\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mandatario destaca cualidades humanas, profesionales, honestidad y eficiencia de la gobernadora fallecida.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las Matas de Santa Cruz, Montecristi.\u2013 El presidente Luis Abinader, acompa\u00f1ado de la primera dama, Raquel Arbaje, asisti\u00f3 este mi\u00e9rcoles a las honras f\u00fanebres de la gobernadora de Montecristi, Nelsy Cruz, quien falleci\u00f3 tras el colapso del techo de la discoteca Jet Set en Santo Domingo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Visiblemente afectado, el mandatario se dirigi\u00f3 a los presentes, resaltando el dolor que embarga a todo el pueblo dominicano, al tiempo de se\u00f1alar las virtudes de la funcionaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente Abinader defini\u00f3 a Nelsy Cruz como una persona de extraordinarias cualidades humanas, profesionales, eficiencia y honestidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl pa\u00eds est\u00e1 de luto. Esta tragedia ha conmovido profundamente a los dominicanos y dominicanas de buen coraz\u00f3n y sensibilidad, que hoy lloran junto a las familias afectadas\u00bb, expres\u00f3 Abinader.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mandatario agreg\u00f3 que: \u201cComo gobierno, estamos haciendo todo lo posible, brindando atenci\u00f3n a los heridos para que puedan recuperarse, y acompa\u00f1ando con solidaridad y paz a quienes han perdido a sus seres queridos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que, hoy hab\u00eda ido a despedir a una compa\u00f1era de trabajo, una compa\u00f1era de partido y tambi\u00e9n a una amiga.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ceremonia religiosa se llev\u00f3 a cabo en su natal municipio de Las Matas de Santa Cruz, donde cientos de ciudadanos, autoridades y dirigentes comunitarios se unieron para dar el \u00faltimo adi\u00f3s a quien fuera una servidora p\u00fablica cercana y comprometida con su provincia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La misa de cuerpo presente fue oficiada por el obispo Diomedes Espinal, de la di\u00f3cesis Mao-Montecristi y cont\u00f3 con la presencia de representantes del Gobierno central, congresistas, alcaldes, regidores y representantes institucionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el acto se resaltaron las cualidades humanas y profesionales de Nelsy Cruz, destacando su vocaci\u00f3n de servicio, su liderazgo cercano y su compromiso con el desarrollo social de Montecristi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente Abinader expres\u00f3 sus condolencias a los familiares, resaltando el legado de Cruz como una mujer entregada, trabajadora y leal al pueblo que representaba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQui\u00e9n era Nelsy Cruz?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nelsy Milagros Cruz Mart\u00ednez naci\u00f3 el 6 de agosto de 1982 en Las Matas de Santa Cruz, provincia Montecristi. Fue una destacada dirigente del Partido Revolucionario Moderno (PRM) y una figura influyente en el desarrollo de su provincia. Curs\u00f3 estudios en la Escuela de Dise\u00f1o de Chav\u00f3n y m\u00e1s adelante se traslad\u00f3 a Santiago de los Caballeros, donde desarroll\u00f3 parte de su vida profesional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En agosto de 2020, fue designada por el presidente Luis Abinader como gobernadora civil de Montecristi, convirti\u00e9ndose en una de las voces femeninas m\u00e1s representativas de la regi\u00f3n en el tren gubernamental. Desde esa posici\u00f3n, impuls\u00f3 m\u00faltiples iniciativas enfocadas en el desarrollo social, el fortalecimiento institucional y la mejora de los servicios p\u00fablicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nelsy Cruz fue reconocida por su cercan\u00eda con las comunidades, su liderazgo comprometido y su disposici\u00f3n permanente al di\u00e1logo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hermana del exjugador de Grandes Ligas Nelson Cruz, con quien compart\u00eda un profundo amor por su tierra natal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estuvieron presentes en las honras f\u00fanebres, los ministros de la Presidencia, Jos\u00e9 Ignacio Paliza; Administrativo de la Presidencia, Andr\u00e9s Bautista; de Deportes, Kelvin Cruz; el presidente de la DNCD, vicealmirante Jos\u00e9 Cabrera Ulloa; el director del INFOTEP, Rafael Santos Bad\u00eda; gobernadoras provinciales, as\u00ed como senadores, diputados, alcaldes, regidores y otras autoridades locales y nacionales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mandatario destaca cualidades humanas, profesionales, honestidad y eficiencia de la gobernadora fallecida. Las Matas de Santa Cruz, Montecristi.\u2013 El presidente Luis Abinader, acompa\u00f1ado de la primera dama, Raquel Arbaje, asisti\u00f3 este mi\u00e9rcoles a las honras f\u00fanebres de la gobernadora de Montecristi, Nelsy Cruz, quien falleci\u00f3 tras el colapso del techo de la discoteca Jet Set en Santo Domingo. Visiblemente afectado, el mandatario se dirigi\u00f3 a los presentes, resaltando el dolor que embarga a todo el pueblo dominicano, al tiempo de se\u00f1alar las virtudes de la funcionaria. El presidente Abinader defini\u00f3 a Nelsy Cruz como una persona de extraordinarias cualidades humanas, profesionales, eficiencia y honestidad. \u201cEl pa\u00eds est\u00e1 de luto. Esta tragedia ha conmovido profundamente a los dominicanos y dominicanas de buen coraz\u00f3n y sensibilidad, que hoy lloran junto a las familias afectadas\u00bb, expres\u00f3 Abinader. El mandatario agreg\u00f3 que: \u201cComo gobierno, estamos haciendo todo lo posible, brindando atenci\u00f3n a los heridos para que puedan recuperarse, y acompa\u00f1ando con solidaridad y paz a quienes han perdido a sus seres queridos\u201d. Dijo que, hoy hab\u00eda ido a despedir a una compa\u00f1era de trabajo, una compa\u00f1era de partido y tambi\u00e9n a una amiga. La ceremonia religiosa se llev\u00f3 a cabo en su natal municipio de Las Matas de Santa Cruz, donde cientos de ciudadanos, autoridades y dirigentes comunitarios se unieron para dar el \u00faltimo adi\u00f3s a quien fuera una servidora p\u00fablica cercana y comprometida con su provincia. La misa de cuerpo presente fue oficiada por el obispo Diomedes Espinal, de la di\u00f3cesis Mao-Montecristi y cont\u00f3 con la presencia de representantes del Gobierno central, congresistas, alcaldes, regidores y representantes institucionales. Durante el acto se resaltaron las cualidades humanas y profesionales de Nelsy Cruz, destacando su vocaci\u00f3n de servicio, su liderazgo cercano y su compromiso con el desarrollo social de Montecristi. El presidente Abinader expres\u00f3 sus condolencias a los familiares, resaltando el legado de Cruz como una mujer entregada, trabajadora y leal al pueblo que representaba. \u00bfQui\u00e9n era Nelsy Cruz? Nelsy Milagros Cruz Mart\u00ednez naci\u00f3 el 6 de agosto de 1982 en Las Matas de Santa Cruz, provincia Montecristi. Fue una destacada dirigente del Partido Revolucionario Moderno (PRM) y una figura influyente en el desarrollo de su provincia. Curs\u00f3 estudios en la Escuela de Dise\u00f1o de Chav\u00f3n y m\u00e1s adelante se traslad\u00f3 a Santiago de los Caballeros, donde desarroll\u00f3 parte de su vida profesional. En agosto de 2020, fue designada por el presidente Luis Abinader como gobernadora civil de Montecristi, convirti\u00e9ndose en una de las voces femeninas m\u00e1s representativas de la regi\u00f3n en el tren gubernamental. Desde esa posici\u00f3n, impuls\u00f3 m\u00faltiples iniciativas enfocadas en el desarrollo social, el fortalecimiento institucional y la mejora de los servicios p\u00fablicos. Nelsy Cruz fue reconocida por su cercan\u00eda con las comunidades, su liderazgo comprometido y su disposici\u00f3n permanente al di\u00e1logo. Hermana del exjugador de Grandes Ligas Nelson Cruz, con quien compart\u00eda un profundo amor por su tierra natal. Estuvieron presentes en las honras f\u00fanebres, los ministros de la Presidencia, Jos\u00e9 Ignacio Paliza; Administrativo de la Presidencia, Andr\u00e9s Bautista; de Deportes, Kelvin Cruz; el presidente de la DNCD, vicealmirante Jos\u00e9 Cabrera Ulloa; el director del INFOTEP, Rafael Santos Bad\u00eda; gobernadoras provinciales, as\u00ed como senadores, diputados, alcaldes, regidores y otras autoridades locales y nacionales.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-136260","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/136260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=136260"}],"version-history":[{"count":2,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/136260\/revisions"}],"predecessor-version":[{"id":136263,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/136260\/revisions\/136263"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=136260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=136260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=136260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}