{"id":136568,"date":"2025-05-07T20:59:36","date_gmt":"2025-05-08T00:59:36","guid":{"rendered":"https:\/\/conexiondigital.com.do\/?p=136568"},"modified":"2025-05-07T21:00:00","modified_gmt":"2025-05-08T01:00:00","slug":"rey-de-espana-abinader-y-carolina-mejia-inauguran-monumento-a-la-paz-y-la-libertad-en-malecon-de-sd","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2025\/05\/07\/rey-de-espana-abinader-y-carolina-mejia-inauguran-monumento-a-la-paz-y-la-libertad-en-malecon-de-sd\/","title":{"rendered":"Rey de Espa\u00f1a, Abinader y Carolina Mej\u00eda inauguran monumento a la paz y la libertad en Malec\u00f3n de SD\u00a0"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/05\/thumbnail_WhatsApp-Image-2025-05-06-at-1.36.26-PM-683x1024.jpg\" alt=\"\" class=\"wp-image-136569\" style=\"width:840px;height:auto\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Santo Domingo, DN &#8211; El rey de Espa\u00f1a, Felipe VI, el presidente Luis Abinader y la alcaldesa Carolina Mej\u00eda inauguraron el monumento Flame, una escultura dedicada a la paz y la libertad ubicada en el kil\u00f3metro siete y medio del Malec\u00f3n de Santo Domingo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El monumento consagra a Santo Domingo como capital del derecho a nivel mundial, un reconocimiento que destaca los avances de Rep\u00fablica Dominicana en materia de Estado de Derecho, a prop\u00f3sito de la celebraci\u00f3n del Congreso Mundial del Derecho del que fue sede.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La escultura, por el artista Carlos Albert, representa el premio Rainer Arnold Award, creado por la World Jurist Association (WJA) y la World Law Foundation para reconocer la excelencia en la investigaci\u00f3n constitucional en el \u00e1mbito jur\u00eddico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El monarca espa\u00f1ol se encuentra en suelo dominicano para participar en la clausura del Congreso Mundial del Derecho, as\u00ed como otras actividades de car\u00e1cter oficial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al participar en el Congreso Mundial del Derecho celebrado en Santo Domingo, la alcaldesa del Distrito Nacional dijo que es una gran satisfacci\u00f3n y reconocimiento que la ciudad haya sido seleccionada como sede de tan magno evento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa justicia y la legalidad son los pilares sobre los cuales estamos construyendo y seguiremos construyendo una sociedad m\u00e1s equitativa, segura y pr\u00f3spera para todos los dominicanos\u201d, sostuvo Carolina Mej\u00eda durante su disertaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Congreso Mundial de Derecho aglutina a m\u00e1s de 300 panelistas de m\u00e1s de 70 pa\u00edses en la capital dominicana, iniciando el pasado s\u00e1bado y concluyendo este martes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo, DN &#8211; El rey de Espa\u00f1a, Felipe VI, el presidente Luis Abinader y la alcaldesa Carolina Mej\u00eda inauguraron el monumento Flame, una escultura dedicada a la paz y la libertad ubicada en el kil\u00f3metro siete y medio del Malec\u00f3n de Santo Domingo.&nbsp; El monumento consagra a Santo Domingo como capital del derecho a nivel mundial, un reconocimiento que destaca los avances de Rep\u00fablica Dominicana en materia de Estado de Derecho, a prop\u00f3sito de la celebraci\u00f3n del Congreso Mundial del Derecho del que fue sede. La escultura, por el artista Carlos Albert, representa el premio Rainer Arnold Award, creado por la World Jurist Association (WJA) y la World Law Foundation para reconocer la excelencia en la investigaci\u00f3n constitucional en el \u00e1mbito jur\u00eddico. El monarca espa\u00f1ol se encuentra en suelo dominicano para participar en la clausura del Congreso Mundial del Derecho, as\u00ed como otras actividades de car\u00e1cter oficial. Al participar en el Congreso Mundial del Derecho celebrado en Santo Domingo, la alcaldesa del Distrito Nacional dijo que es una gran satisfacci\u00f3n y reconocimiento que la ciudad haya sido seleccionada como sede de tan magno evento. \u201cLa justicia y la legalidad son los pilares sobre los cuales estamos construyendo y seguiremos construyendo una sociedad m\u00e1s equitativa, segura y pr\u00f3spera para todos los dominicanos\u201d, sostuvo Carolina Mej\u00eda durante su disertaci\u00f3n. El Congreso Mundial de Derecho aglutina a m\u00e1s de 300 panelistas de m\u00e1s de 70 pa\u00edses en la capital dominicana, iniciando el pasado s\u00e1bado y concluyendo este martes.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-136568","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/136568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=136568"}],"version-history":[{"count":2,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/136568\/revisions"}],"predecessor-version":[{"id":136571,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/136568\/revisions\/136571"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=136568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=136568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=136568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}