{"id":137012,"date":"2025-06-03T18:40:59","date_gmt":"2025-06-03T22:40:59","guid":{"rendered":"https:\/\/conexiondigital.com.do\/?p=137012"},"modified":"2025-06-03T18:41:00","modified_gmt":"2025-06-03T22:41:00","slug":"ministro-de-salud-recibe-premio-internacional-otorgado-a-rd-por-la-ejecucion-de-la-estrategia-hearts","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2025\/06\/03\/ministro-de-salud-recibe-premio-internacional-otorgado-a-rd-por-la-ejecucion-de-la-estrategia-hearts\/","title":{"rendered":"Ministro de Salud recibe premio internacional otorgado a RD por la ejecuci\u00f3n de la estrategia HEARTS"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/06\/4e4940ef-6b53-44a1-a639-0dc9cbcb27e8.jpg\" alt=\"\" class=\"wp-image-137013\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El reconocimiento que otorga la Liga Mundial de Hipertensi\u00f3n fue entregado por la representante en el pa\u00eds de la OPS, durante el acto de conmemoraci\u00f3n del D\u00eda Mundial de La Hipertensi\u00f3n.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Santo Domingo-. Durante el acto de conmemoraci\u00f3n del D\u00eda Mundial de la Hipertensi\u00f3n, el ministro de Salud, V\u00edctor Atallah, recibi\u00f3 el premio internacional WHL Organizaci\u00f3n Excellence Arwards 2025, otorgado a Rep\u00fablica Dominicana por la Liga Mundial de Hipertensi\u00f3n por la exitosa implementaci\u00f3n de la estrategia HERTS, basada en acciones oportunas para el control de la hipertensi\u00f3n, la diabetes y otras enfermedades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al entregar el premio, la representante en el pa\u00eds de la Organizaci\u00f3n Panamericana de la Salud (OPS), Alba Mar\u00eda Ropero \u00c1lvarez, felicit\u00f3 al Gobierno de Rep\u00fablica Dominicana por ese logro y detall\u00f3 algunas de las acciones realizadas por el pa\u00eds para merecer esa distinci\u00f3n, entre ellas: la capacitaci\u00f3n de m\u00e1s de 23,222 miembros del personal de salud (m\u00e9dicos, enfermeras y promotores) en medici\u00f3n correcta de la presi\u00f3n, paquete t\u00e9cnico HEARTS, enfermedad renal cr\u00f3nica y manejo integral de la diabetes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, por el uso estandarizado en el primer nivel atenci\u00f3n, de herramientas en intervenciones de cambios en el estilo de vida, en evaluaci\u00f3n de riesgos cardiovascular, en ficha de control de pacientes cr\u00f3nicos, Pasaporte para una Vida Saludable, lineamientos Salsa (Saludable y Sabroso) para la promoci\u00f3n de h\u00e1bitos alimenticios saludables, seg\u00fan la cultura culinaria dominicana y en cumplimiento de espacios libres de humo, entre otras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al recibir el galard\u00f3n, Atallah expres\u00f3 que la ejecuci\u00f3n de la estrategia HEART ha sido exitosa gracias al apoyo del presidente Luis Abinader a esa iniciativa y a otras acciones para favorecer el bienestar de la poblaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs del presidente de la Rep\u00fablica que nosotros recibimos ese espaldarazo fuerte, esa fuerza que motiva, y que nos dice vamos a hacer todo para que la hipertensi\u00f3n y la diabetes tengan control y m\u00e1s avances, y eso se formaliza en el programa M\u00e1s Salud y Esperanza, para tener un sistema m\u00e1s preventivo\u201d, agreg\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destac\u00f3 los avances que ha alcanzado el pa\u00eds en materia de prevenci\u00f3n de la hipertensi\u00f3n, que contin\u00faa causando muertes a nivel mundial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, asever\u00f3 que en el pa\u00eds la estrategia HEARTS ha sido un pilar clave en la prevenci\u00f3n y control de la enfermedad, al incorporar protocolos cl\u00ednicos estandarizados, tecnolog\u00edas de informaci\u00f3n, acceso gratuito a medicamentos esenciales a trav\u00e9s de la Red de Farmacias del Pueblo, promoci\u00f3n de estilos de vida saludables y herramientas digitales para la evaluaci\u00f3n del riesgo cardiovascular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agreg\u00f3 que actualmente, m\u00e1s de 280,000 personas reciben seguimiento activo en la red de Centros de Primer Nivel (CPN), de las cuales un 66% mantiene su presi\u00f3n arterial bajo control.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Precis\u00f3 que este enfoque integral no solo ha permitido mejorar indicadores de salud, sino tambi\u00e9n se ha logrado transformar la forma en que se previenen y manejan las enfermedades cr\u00f3nicas en el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Expres\u00f3 satisfacci\u00f3n por la buena planificaci\u00f3n y ejecuci\u00f3n de las acciones de la estrategia HEARTS, especialmente por el equipo de la divisi\u00f3n de Enfermedades no Transmisibles del Ministerio de Salud, que es dirigida por la doctora Andelys de la Rosa, a quienes felicit\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De su lado, el director del SNS, doctor Mario Lama, felicit\u00f3 a los equipos de salud reconocidos y destac\u00f3 la labor conjunta en el desarrollo de la estrategia de atenci\u00f3n primaria, liderada por el Ministerio de Salud P\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Exhort\u00f3 a continuar fortaleciendo esta estrategia para reducir enfermedades cr\u00f3nicas y su comorbilidad, y afirm\u00f3 que el compromiso debe ser permanente, \u201csirviendo estos reconocimientos para renovar energ\u00edas y motivar a todos los actores del sistema\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la actividad fueron reconocidas, la Regional de Salud Nordeste, el Servicio Regional de Salud Enriquillo y la Regional de Salud Este del Servicio Nacional de Salud (SNS), as\u00ed como las Direcciones Provinciales de Salud de La Romana, Espaillat y Santiago 2 de Salud P\u00fablica por encabezar las labores de seguimiento de la estrategia HEARTS.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el acto, el viceministro de Salud Colectiva, doctor Eladio P\u00e9rez, pronunci\u00f3 las palabras de bienvenida, mientras que la directora de Enfermedades no Transmisible, explic\u00f3 la metodolog\u00eda para escoger los ganadores de las regionales de Salud P\u00fablica y el SNS.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estuvieron presentes el director de Promese\/Cal, Adolfo P\u00e9rez; el viceministro de las Direcciones Provinciales de Salud, doctor Luis Nelson Rosario, y el viceministro de Garant\u00eda de la Calidad, doctor Jos\u00e9 Antonio Matos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El reconocimiento que otorga la Liga Mundial de Hipertensi\u00f3n fue entregado por la representante en el pa\u00eds de la OPS, durante el acto de conmemoraci\u00f3n del D\u00eda Mundial de La Hipertensi\u00f3n. Santo Domingo-. Durante el acto de conmemoraci\u00f3n del D\u00eda Mundial de la Hipertensi\u00f3n, el ministro de Salud, V\u00edctor Atallah, recibi\u00f3 el premio internacional WHL Organizaci\u00f3n Excellence Arwards 2025, otorgado a Rep\u00fablica Dominicana por la Liga Mundial de Hipertensi\u00f3n por la exitosa implementaci\u00f3n de la estrategia HERTS, basada en acciones oportunas para el control de la hipertensi\u00f3n, la diabetes y otras enfermedades. Al entregar el premio, la representante en el pa\u00eds de la Organizaci\u00f3n Panamericana de la Salud (OPS), Alba Mar\u00eda Ropero \u00c1lvarez, felicit\u00f3 al Gobierno de Rep\u00fablica Dominicana por ese logro y detall\u00f3 algunas de las acciones realizadas por el pa\u00eds para merecer esa distinci\u00f3n, entre ellas: la capacitaci\u00f3n de m\u00e1s de 23,222 miembros del personal de salud (m\u00e9dicos, enfermeras y promotores) en medici\u00f3n correcta de la presi\u00f3n, paquete t\u00e9cnico HEARTS, enfermedad renal cr\u00f3nica y manejo integral de la diabetes. Asimismo, por el uso estandarizado en el primer nivel atenci\u00f3n, de herramientas en intervenciones de cambios en el estilo de vida, en evaluaci\u00f3n de riesgos cardiovascular, en ficha de control de pacientes cr\u00f3nicos, Pasaporte para una Vida Saludable, lineamientos Salsa (Saludable y Sabroso) para la promoci\u00f3n de h\u00e1bitos alimenticios saludables, seg\u00fan la cultura culinaria dominicana y en cumplimiento de espacios libres de humo, entre otras. Al recibir el galard\u00f3n, Atallah expres\u00f3 que la ejecuci\u00f3n de la estrategia HEART ha sido exitosa gracias al apoyo del presidente Luis Abinader a esa iniciativa y a otras acciones para favorecer el bienestar de la poblaci\u00f3n. \u201cEs del presidente de la Rep\u00fablica que nosotros recibimos ese espaldarazo fuerte, esa fuerza que motiva, y que nos dice vamos a hacer todo para que la hipertensi\u00f3n y la diabetes tengan control y m\u00e1s avances, y eso se formaliza en el programa M\u00e1s Salud y Esperanza, para tener un sistema m\u00e1s preventivo\u201d, agreg\u00f3. Destac\u00f3 los avances que ha alcanzado el pa\u00eds en materia de prevenci\u00f3n de la hipertensi\u00f3n, que contin\u00faa causando muertes a nivel mundial. Asimismo, asever\u00f3 que en el pa\u00eds la estrategia HEARTS ha sido un pilar clave en la prevenci\u00f3n y control de la enfermedad, al incorporar protocolos cl\u00ednicos estandarizados, tecnolog\u00edas de informaci\u00f3n, acceso gratuito a medicamentos esenciales a trav\u00e9s de la Red de Farmacias del Pueblo, promoci\u00f3n de estilos de vida saludables y herramientas digitales para la evaluaci\u00f3n del riesgo cardiovascular. Agreg\u00f3 que actualmente, m\u00e1s de 280,000 personas reciben seguimiento activo en la red de Centros de Primer Nivel (CPN), de las cuales un 66% mantiene su presi\u00f3n arterial bajo control. Precis\u00f3 que este enfoque integral no solo ha permitido mejorar indicadores de salud, sino tambi\u00e9n se ha logrado transformar la forma en que se previenen y manejan las enfermedades cr\u00f3nicas en el pa\u00eds. Expres\u00f3 satisfacci\u00f3n por la buena planificaci\u00f3n y ejecuci\u00f3n de las acciones de la estrategia HEARTS, especialmente por el equipo de la divisi\u00f3n de Enfermedades no Transmisibles del Ministerio de Salud, que es dirigida por la doctora Andelys de la Rosa, a quienes felicit\u00f3. De su lado, el director del SNS, doctor Mario Lama, felicit\u00f3 a los equipos de salud reconocidos y destac\u00f3 la labor conjunta en el desarrollo de la estrategia de atenci\u00f3n primaria, liderada por el Ministerio de Salud P\u00fablica. Exhort\u00f3 a continuar fortaleciendo esta estrategia para reducir enfermedades cr\u00f3nicas y su comorbilidad, y afirm\u00f3 que el compromiso debe ser permanente, \u201csirviendo estos reconocimientos para renovar energ\u00edas y motivar a todos los actores del sistema\u201d. Durante la actividad fueron reconocidas, la Regional de Salud Nordeste, el Servicio Regional de Salud Enriquillo y la Regional de Salud Este del Servicio Nacional de Salud (SNS), as\u00ed como las Direcciones Provinciales de Salud de La Romana, Espaillat y Santiago 2 de Salud P\u00fablica por encabezar las labores de seguimiento de la estrategia HEARTS. En el acto, el viceministro de Salud Colectiva, doctor Eladio P\u00e9rez, pronunci\u00f3 las palabras de bienvenida, mientras que la directora de Enfermedades no Transmisible, explic\u00f3 la metodolog\u00eda para escoger los ganadores de las regionales de Salud P\u00fablica y el SNS. Estuvieron presentes el director de Promese\/Cal, Adolfo P\u00e9rez; el viceministro de las Direcciones Provinciales de Salud, doctor Luis Nelson Rosario, y el viceministro de Garant\u00eda de la Calidad, doctor Jos\u00e9 Antonio Matos.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-137012","post","type-post","status-publish","format-standard","hentry","category-nature"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/137012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=137012"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/137012\/revisions"}],"predecessor-version":[{"id":137014,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/137012\/revisions\/137014"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=137012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=137012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=137012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}