{"id":137487,"date":"2025-06-29T08:05:11","date_gmt":"2025-06-29T12:05:11","guid":{"rendered":"https:\/\/conexiondigital.com.do\/?p=137487"},"modified":"2025-06-29T08:05:12","modified_gmt":"2025-06-29T12:05:12","slug":"presidente-abinader-inaugura-proyectos-de-asfaltado-ejecutados-por-la-liga-municipal-dominicana-lmd-en-constanza","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2025\/06\/29\/presidente-abinader-inaugura-proyectos-de-asfaltado-ejecutados-por-la-liga-municipal-dominicana-lmd-en-constanza\/","title":{"rendered":"Presidente Abinader inaugura proyectos de asfaltado ejecutados por la Liga Municipal Dominicana (LMD) en Constanza"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/06\/Asfaltado-Constanza-1-1024x536.jpg\" alt=\"\" class=\"wp-image-137488\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Constanza, La Vega. &#8211; El presidente de la Rep\u00fablica Luis Abinader junto al presidente de la Liga Municipal Dominicana (LMD), V\u00edctor D\u00b4Aza, inauguraron varios proyectos de asfaltado en el municipio de Constanza, provincia La Vega, ejecutados con la inversi\u00f3n del programa de Apoyo a los Gobiernos locales que implementa la LMD con fondos de la Presidencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En total, se invirtieron RD$68,462,430.79 de este programa, resultando 8.6 km de v\u00edas pavimentadas y 34,687 habitantes beneficiados en los sectores Leopoldo Suriel, La Colonia, Don \u00c1ngel, Vista Hermosa Primero, Las Auyamas, Pueblo Nuevo de Buenos Aires, El Evang\u00e9lico y Vista Hermosa Segunda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta inversi\u00f3n se suma a los RD$10,979,097.76 ejecutados por el ayuntamiento de Constanza en proyectos de aceras y contenes, transferidos por la LMD desde el programa de Apoyo a los Gobiernos Locales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente de la LMD, V\u00edctor D\u00b4Aza, destac\u00f3 el impacto en todo el territorio nacional de este programa que ha beneficiado a todos los municipios y distritos municipales del pa\u00eds con proyectos de alto valor para la calidad de vida de las comunidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cGracias al compromiso del presidente Luis Abinader con el desarrollo local, hemos podido impactar con peque\u00f1os proyectos que contaban con una alta demanda ciudadana como es la pavimentaci\u00f3n de las v\u00edas y su acondicionamiento con aceras y contenes para mejorar la movilidad cotidiana en los diferentes sectores m\u00e1s carenciados\u201d, afirm\u00f3 D\u00b4Aza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras, el alcalde de Constanza, Francisco Antonio Marte Hern\u00e1ndez&nbsp;valor\u00f3 esta iniciativa que dignifica la vida de los residentes, destacando el trabajo que realizan la Presidencia y la Liga Municipal Dominicana en apoyo al desarrollo en los municipios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En total, el programa de Apoyo a los Gobiernos Locales ha destinado RD$1,500,000,000.00 en asfaltado para completar proyectos de adecuaci\u00f3n de las v\u00edas que ya contaban con aceras y contenes construidas en la primera fase de desarrollo de este programa, interviniendo as\u00ed municipios de 22 provincias del pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Constanza, La Vega. &#8211; El presidente de la Rep\u00fablica Luis Abinader junto al presidente de la Liga Municipal Dominicana (LMD), V\u00edctor D\u00b4Aza, inauguraron varios proyectos de asfaltado en el municipio de Constanza, provincia La Vega, ejecutados con la inversi\u00f3n del programa de Apoyo a los Gobiernos locales que implementa la LMD con fondos de la Presidencia. En total, se invirtieron RD$68,462,430.79 de este programa, resultando 8.6 km de v\u00edas pavimentadas y 34,687 habitantes beneficiados en los sectores Leopoldo Suriel, La Colonia, Don \u00c1ngel, Vista Hermosa Primero, Las Auyamas, Pueblo Nuevo de Buenos Aires, El Evang\u00e9lico y Vista Hermosa Segunda. Esta inversi\u00f3n se suma a los RD$10,979,097.76 ejecutados por el ayuntamiento de Constanza en proyectos de aceras y contenes, transferidos por la LMD desde el programa de Apoyo a los Gobiernos Locales. El presidente de la LMD, V\u00edctor D\u00b4Aza, destac\u00f3 el impacto en todo el territorio nacional de este programa que ha beneficiado a todos los municipios y distritos municipales del pa\u00eds con proyectos de alto valor para la calidad de vida de las comunidades. \u201cGracias al compromiso del presidente Luis Abinader con el desarrollo local, hemos podido impactar con peque\u00f1os proyectos que contaban con una alta demanda ciudadana como es la pavimentaci\u00f3n de las v\u00edas y su acondicionamiento con aceras y contenes para mejorar la movilidad cotidiana en los diferentes sectores m\u00e1s carenciados\u201d, afirm\u00f3 D\u00b4Aza. Mientras, el alcalde de Constanza, Francisco Antonio Marte Hern\u00e1ndez&nbsp;valor\u00f3 esta iniciativa que dignifica la vida de los residentes, destacando el trabajo que realizan la Presidencia y la Liga Municipal Dominicana en apoyo al desarrollo en los municipios. En total, el programa de Apoyo a los Gobiernos Locales ha destinado RD$1,500,000,000.00 en asfaltado para completar proyectos de adecuaci\u00f3n de las v\u00edas que ya contaban con aceras y contenes construidas en la primera fase de desarrollo de este programa, interviniendo as\u00ed municipios de 22 provincias del pa\u00eds.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-137487","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/137487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=137487"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/137487\/revisions"}],"predecessor-version":[{"id":137489,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/137487\/revisions\/137489"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=137487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=137487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=137487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}