{"id":139215,"date":"2025-09-28T14:09:45","date_gmt":"2025-09-28T18:09:45","guid":{"rendered":"https:\/\/conexiondigital.com.do\/?p=139215"},"modified":"2025-09-28T14:09:46","modified_gmt":"2025-09-28T18:09:46","slug":"inabie-invita-a-conocer-su-stand-en-la-xxvii-feria-internacional-del-libro-2025","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2025\/09\/28\/inabie-invita-a-conocer-su-stand-en-la-xxvii-feria-internacional-del-libro-2025\/","title":{"rendered":"Inabie invita a conocer su stand en la XXVII Feria Internacional del Libro 2025"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"\" alt=\"\" class=\"wp-image-139216\" srcset=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/09\/6b435c2b-3893-49ad-95b8-267cf3dcc668-1024x682.jpg 1024w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/09\/6b435c2b-3893-49ad-95b8-267cf3dcc668-800x533.jpg 800w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/09\/6b435c2b-3893-49ad-95b8-267cf3dcc668-768x512.jpg 768w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/09\/6b435c2b-3893-49ad-95b8-267cf3dcc668-1536x1023.jpg 1536w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/09\/6b435c2b-3893-49ad-95b8-267cf3dcc668-300x200.jpg 300w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/09\/6b435c2b-3893-49ad-95b8-267cf3dcc668.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Santo Domingo.- El Instituto Nacional de Bienestar Estudiantil (INABIE) invita a las familias y al p\u00fablico en general a visitar su stand en la XXVII Feria Internacional del Libro 2025, un espacio donde podr\u00e1n conocer los programas que desarrolla la instituci\u00f3n en favor de los estudiantes del sistema p\u00fablico nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El stand incluye orientaciones a cargo de profesionales de las \u00e1reas de Nutrici\u00f3n, Salud Escolar y Gesti\u00f3n Alimentaria del Inabie, quienes explican c\u00f3mo cada iniciativa contribuye al bienestar y rendimiento acad\u00e9mico de los escolares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este punto de encuentro, ubicado en el parque detr\u00e1s de la Biblioteca Nacional Pedro Henr\u00edquez Ure\u00f1a, los visitantes observan muestras de los componentes del desayuno escolar y del almuerzo escolar. Adem\u00e1s, reciben kits odontol\u00f3gicos para fomentar el cuidado de la salud bucal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La experiencia se completa con juegos interactivos como arma tu plato nutritivo y din\u00e1micas de memoria, pensadas para que ni\u00f1os y adultos aprendan de manera entretenida sobre la importancia de la alimentaci\u00f3n balanceada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el eslogan \u201cLos libros suman bienestar\u201d, el Inabie se une a la XXVII Feria Internacional del Libro, inaugurada el 25 de septiembre y que se extender\u00e1 hasta el 5 de octubre, ofreciendo a la ciudadan\u00eda la oportunidad de descubrir una propuesta que combina educaci\u00f3n y recreaci\u00f3n para todos sus visitantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.- El Instituto Nacional de Bienestar Estudiantil (INABIE) invita a las familias y al p\u00fablico en general a visitar su stand en la XXVII Feria Internacional del Libro 2025, un espacio donde podr\u00e1n conocer los programas que desarrolla la instituci\u00f3n en favor de los estudiantes del sistema p\u00fablico nacional. El stand incluye orientaciones a cargo de profesionales de las \u00e1reas de Nutrici\u00f3n, Salud Escolar y Gesti\u00f3n Alimentaria del Inabie, quienes explican c\u00f3mo cada iniciativa contribuye al bienestar y rendimiento acad\u00e9mico de los escolares. En este punto de encuentro, ubicado en el parque detr\u00e1s de la Biblioteca Nacional Pedro Henr\u00edquez Ure\u00f1a, los visitantes observan muestras de los componentes del desayuno escolar y del almuerzo escolar. Adem\u00e1s, reciben kits odontol\u00f3gicos para fomentar el cuidado de la salud bucal. La experiencia se completa con juegos interactivos como arma tu plato nutritivo y din\u00e1micas de memoria, pensadas para que ni\u00f1os y adultos aprendan de manera entretenida sobre la importancia de la alimentaci\u00f3n balanceada. Con el eslogan \u201cLos libros suman bienestar\u201d, el Inabie se une a la XXVII Feria Internacional del Libro, inaugurada el 25 de septiembre y que se extender\u00e1 hasta el 5 de octubre, ofreciendo a la ciudadan\u00eda la oportunidad de descubrir una propuesta que combina educaci\u00f3n y recreaci\u00f3n para todos sus visitantes.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-139215","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/139215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=139215"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/139215\/revisions"}],"predecessor-version":[{"id":139217,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/139215\/revisions\/139217"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=139215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=139215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=139215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}