{"id":139638,"date":"2025-10-17T21:22:03","date_gmt":"2025-10-18T01:22:03","guid":{"rendered":"https:\/\/conexiondigital.com.do\/?p=139638"},"modified":"2025-10-17T21:22:51","modified_gmt":"2025-10-18T01:22:51","slug":"las-pandillas-de-motoristas-de-los-fines-de-semana","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2025\/10\/17\/las-pandillas-de-motoristas-de-los-fines-de-semana\/","title":{"rendered":"Las pandillas de motoristas de los fines de semana"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"853\" height=\"643\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/10\/marino-ramirez.jpg\" alt=\"\" class=\"wp-image-139639\" srcset=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/10\/marino-ramirez.jpg 853w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/10\/marino-ramirez-800x603.jpg 800w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/10\/marino-ramirez-768x579.jpg 768w\" sizes=\"auto, (max-width: 853px) 100vw, 853px\"><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Por Marino Ram\u00edrez Grull\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es evidente que el caos que se ve a cada d\u00eda en las calles del pa\u00eds en medio de tr\u00e1nsito vehicular s\u00f3lo tiene un culpable es la autoridad encargada de regular ese rengl\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Motoristas que violan todas las leyes, reglas y normas del tr\u00e1nsito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Guag\u00fceros que no respetan a nadie mucho menos a las autoridades de Digesett o Intrant con los cuales parece que existe un pacto de coexistencia pac\u00edfica de que no se no se respete nada y que no haya multas por esas violaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero mucho m\u00e1s que eso las paradas de motoristas se convierten cada d\u00eda en puntos de ejercicio de violencia y de grandes negocios entre los supuestos due\u00f1os de esos lugares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un permiso de motoconchar en una parada cuesta hasta un mill\u00f3n de pesos, aunque el dinero no se sabe quien lo recibe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agregar que Intrant ha prohibido paradas en avenidas como la Winston Churchill y como perros por sus casas los motoristas tienen cruces de montar pasajeros en medio de las mismas v\u00edas p\u00fablicas obstaculizando el tr\u00e1nsito como si nada pasara.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No vale la pena mencionar el gran negocio de las rutas de veh\u00edculos conchos o guaguas llamadas voladoras por la velocidad a que transitan por las v\u00edas de las ciudades llev\u00e1ndose a todo el que encuentran en el medio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero en medio de este caos y negocios econ\u00f3micos que deja el tr\u00e1nsito p\u00fablico, los sectores privados pagamos las consecuencias de la falta de autoridad en ese medio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Incluso existen ordenes desde arriba de que los motoristas no sean molestados aunque no lleven placas que de hecho son pocos los que tienen licencia, seguro o marbete.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es pura delincuencia lo que se ve en las calles de todo el territorio nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por dem\u00e1s ya los ciudadanos no respetan a polic\u00edas, guardias o Digesett porque cuando intentan imponer las leyes son agredidos por cualquiera que ande en las calles en motores o veh\u00edculos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los fines de semana, especialmente los domingos decenas de motoristas sin cascos protectores o alg\u00fan papel legal cruzan los peajes, ha porque adem\u00e1s no pagan ese impuesto, para irse a los r\u00edos o playas tomando cervezas o alg\u00fan licor y tienen paso libre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En las propias ciudades usted los ve en t\u00faneles, elevados, no respetan sem\u00e1foros o sencillamente son invisibles antes cualquier autoridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No ha habido un s\u00f3lo gobierno que intente poner el orden en el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es como si el desarrollo econ\u00f3mico y social s\u00f3lo se queda en plazas o bancos comerciales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las calles son para los perros dir\u00e1n los del gobierno porque al fin y al cabo un roce, choque o discusi\u00f3n se salda con muertos y heridos que no son los que est\u00e1n en el poder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entiendo que para aplicar la ley de tr\u00e1nsito no hay que abusar sino tener autoridad al respecto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras los agentes de Digesett o polic\u00eda est\u00e9n para cogerles golpes a los delincuentes este pedazo de isla no llegar\u00e1 a ning\u00fan lado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Candidatos tras candidatos esperan las elecciones para proponer cualquier cosa que se les ocurra menos aplicar las leyes de manera responsable e integra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras eso no suceda lo dem\u00e1s ser\u00e1 pura demagogia pol\u00edtica o electoral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8212;<br>Marino Ramirez<br>http:\/\/verticalrd.blogspot.com\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Marino Ram\u00edrez Grull\u00f3n Es evidente que el caos que se ve a cada d\u00eda en las calles del pa\u00eds en medio de tr\u00e1nsito vehicular s\u00f3lo tiene un culpable es la autoridad encargada de regular ese rengl\u00f3n. Motoristas que violan todas las leyes, reglas y normas del tr\u00e1nsito. Guag\u00fceros que no respetan a nadie mucho menos a las autoridades de Digesett o Intrant con los cuales parece que existe un pacto de coexistencia pac\u00edfica de que no se no se respete nada y que no haya multas por esas violaciones. Pero mucho m\u00e1s que eso las paradas de motoristas se convierten cada d\u00eda en puntos de ejercicio de violencia y de grandes negocios entre los supuestos due\u00f1os de esos lugares. Un permiso de motoconchar en una parada cuesta hasta un mill\u00f3n de pesos, aunque el dinero no se sabe quien lo recibe. Agregar que Intrant ha prohibido paradas en avenidas como la Winston Churchill y como perros por sus casas los motoristas tienen cruces de montar pasajeros en medio de las mismas v\u00edas p\u00fablicas obstaculizando el tr\u00e1nsito como si nada pasara. No vale la pena mencionar el gran negocio de las rutas de veh\u00edculos conchos o guaguas llamadas voladoras por la velocidad a que transitan por las v\u00edas de las ciudades llev\u00e1ndose a todo el que encuentran en el medio. Pero en medio de este caos y negocios econ\u00f3micos que deja el tr\u00e1nsito p\u00fablico, los sectores privados pagamos las consecuencias de la falta de autoridad en ese medio. Incluso existen ordenes desde arriba de que los motoristas no sean molestados aunque no lleven placas que de hecho son pocos los que tienen licencia, seguro o marbete. Es pura delincuencia lo que se ve en las calles de todo el territorio nacional. Por dem\u00e1s ya los ciudadanos no respetan a polic\u00edas, guardias o Digesett porque cuando intentan imponer las leyes son agredidos por cualquiera que ande en las calles en motores o veh\u00edculos. Los fines de semana, especialmente los domingos decenas de motoristas sin cascos protectores o alg\u00fan papel legal cruzan los peajes, ha porque adem\u00e1s no pagan ese impuesto, para irse a los r\u00edos o playas tomando cervezas o alg\u00fan licor y tienen paso libre. En las propias ciudades usted los ve en t\u00faneles, elevados, no respetan sem\u00e1foros o sencillamente son invisibles antes cualquier autoridad. No ha habido un s\u00f3lo gobierno que intente poner el orden en el pa\u00eds. Es como si el desarrollo econ\u00f3mico y social s\u00f3lo se queda en plazas o bancos comerciales. Las calles son para los perros dir\u00e1n los del gobierno porque al fin y al cabo un roce, choque o discusi\u00f3n se salda con muertos y heridos que no son los que est\u00e1n en el poder. Entiendo que para aplicar la ley de tr\u00e1nsito no hay que abusar sino tener autoridad al respecto. Mientras los agentes de Digesett o polic\u00eda est\u00e9n para cogerles golpes a los delincuentes este pedazo de isla no llegar\u00e1 a ning\u00fan lado. Candidatos tras candidatos esperan las elecciones para proponer cualquier cosa que se les ocurra menos aplicar las leyes de manera responsable e integra. Mientras eso no suceda lo dem\u00e1s ser\u00e1 pura demagogia pol\u00edtica o electoral. &#8212;Marino Ramirezhttp:\/\/verticalrd.blogspot.com\/<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15,52],"tags":[],"class_list":["post-139638","post","type-post","status-publish","format-standard","hentry","category-nacionales","category-opinion"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/139638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=139638"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/139638\/revisions"}],"predecessor-version":[{"id":139640,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/139638\/revisions\/139640"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=139638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=139638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=139638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}