{"id":139831,"date":"2025-10-23T16:46:03","date_gmt":"2025-10-23T20:46:03","guid":{"rendered":"https:\/\/conexiondigital.com.do\/?p=139831"},"modified":"2025-10-23T16:46:04","modified_gmt":"2025-10-23T20:46:04","slug":"juan-hubieres-desmiente-aumento-de-pasajes-en-transporte-publico-de-zona-norte-de-santo-domingo","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2025\/10\/23\/juan-hubieres-desmiente-aumento-de-pasajes-en-transporte-publico-de-zona-norte-de-santo-domingo\/","title":{"rendered":"Juan Hubieres desmiente aumento de pasajes en transporte p\u00fablico de zona norte de Santo Domingo"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"906\" height=\"904\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/10\/thumbnail_Juan-Hubieres.png\" alt=\"\" class=\"wp-image-139832\" srcset=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/10\/thumbnail_Juan-Hubieres.png 906w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/10\/thumbnail_Juan-Hubieres-800x798.png 800w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/10\/thumbnail_Juan-Hubieres-150x150.png 150w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/10\/thumbnail_Juan-Hubieres-768x766.png 768w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/10\/thumbnail_Juan-Hubieres-333x333.png 333w\" sizes=\"auto, (max-width: 906px) 100vw, 906px\"><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00a0Presidente de Fenatrano afirma que se trata de un chantaje anuncio de subir pasajes<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Santo Domingo. &#8211; El presidente de la Federaci\u00f3n Nacional de Transporte la Nueva Opci\u00f3n (Fenatrano), desminti\u00f3 que se haya dispuesto un aumento de pasaje en los sindicatos afiliados a esa organizaci\u00f3n en la zona norte de Santo Domingo.<br><br><br>El l\u00edder del sector transporte de pasajero aclar\u00f3 que no asumen las declaraciones realizadas por una federaci\u00f3n en ese sentido: \u201cLa mayor\u00eda de los transportistas de la zona norte como Sabana Perdida, Los Guaricanos y La Javilla no habr\u00e1 aumentos de los pasajes ni en ninguna parte de la capital ni donde nosotros existimos\u201d.<br><br>No obstante, Juan Hubieres aprovech\u00f3 para reiterarle al gobierno sobre los combustibles que se le otorgue el mismo trato a todos, al denunciar que desde el Ministerio de Hacienda se ha firmado un acuerdo con la Asociaci\u00f3n de Hoteles y Turismo de la Rep\u00fablica Dominicana (Asonahores) con el objetivo de que solo pague en 2 % del Itbis de los productos que importan.<br><br>En ese sentido, el presidente de Fenatrano precis\u00f3 que en la actualidad tienen 67 autobuses en el muelle de due\u00f1os dominicanos y posiblemente m\u00e1s que los due\u00f1os de muchos hoteles, pero, ellos merecen el mismo trato, es decir un 2 % igualitario para el corredor Independencia.<br><br>Hubieres dijo que no le est\u00e1n mendigando nada al gobierno, pero, as\u00ed como otros tienen exenciones fiscales multimillonarias de pasajeros y de cargas de todo el pa\u00eds, solo tienen 3000 mil millones, al indicar que solo se debe aplicar la equidad: \u201cPero siempre se quiere aplicar una narrativa en contra de los peque\u00f1os y de eso producirse habr\u00e1 lucha con la poblaci\u00f3n\u201d. &nbsp;<br><br>Igualmente, solicit\u00f3 al gobierno resolver el problema, por lo menos en el Gran Santo Domingo con los cuatro mil choferes de las rutas afiliadas a Fenatrano que no tienen Bonogas, debido a la cancelaci\u00f3n de las tarjetas.<br><br>\u201cQue el Gobierno destine esa partida, y que en un breve plazo de 15 a 20 d\u00edas puedan tener sus tarjetas de Bonogas, de cinco mil pesos como se acord\u00f3 hace dos a\u00f1os\u201d, expuso.<br><br>Juan Hubieres solicit\u00f3, adem\u00e1s, con est\u00e1s condiciones una mesa de di\u00e1logo que vea estos puntos: \u201cAs\u00ed como Asonahores que solo va a pagar un 2 % de Itbis y nada m\u00e1s en todo lo que adquieran y compren, as\u00ed tambi\u00e9n est\u00e1n la Asociaci\u00f3n de Concesionarios de Fabricantes de Veh\u00edculos (Acofave), que paga un porcentaje de Itbis y les desmontan un 28 % al igual que la zona franca que no pagan un peso de impuestos\u201d.<br><br>El l\u00edder de Fenatrano asever\u00f3 que el sector transporte genera m\u00e1s ingresos al gobierno que m\u00e1s de esas grandes capitales, as\u00ed como m\u00e1s empleos en todo el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Afirm\u00f3 que Fenatrano ni sus rutas afiliadas son firmantes de ning\u00fan documento para mendigar: \u201cSolo planteamos una mesa de di\u00e1logos para el pa\u00eds, y que el gobierno siga resolviendo con alternativas que establecieron otros gobiernos mediante la Refiner\u00eda\u201d.<br><br>No hay aumento de pasaje ni en Santo Domingo Este ni Santo Domingo Norte ni en Los Alcarrizos ni en ning\u00fan lao\u2026esos que andan inventando no tiene ni tres rutas ni guagua para subir pasajes y lo que est\u00e1n es chantajeando\u2026con nosotros nadie cuente para chantajear\u201d, concluy\u00f3 Juan Hubieres, presidente de Fenatrano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Presidente de Fenatrano afirma que se trata de un chantaje anuncio de subir pasajes Santo Domingo. &#8211; El presidente de la Federaci\u00f3n Nacional de Transporte la Nueva Opci\u00f3n (Fenatrano), desminti\u00f3 que se haya dispuesto un aumento de pasaje en los sindicatos afiliados a esa organizaci\u00f3n en la zona norte de Santo Domingo. El l\u00edder del sector transporte de pasajero aclar\u00f3 que no asumen las declaraciones realizadas por una federaci\u00f3n en ese sentido: \u201cLa mayor\u00eda de los transportistas de la zona norte como Sabana Perdida, Los Guaricanos y La Javilla no habr\u00e1 aumentos de los pasajes ni en ninguna parte de la capital ni donde nosotros existimos\u201d. No obstante, Juan Hubieres aprovech\u00f3 para reiterarle al gobierno sobre los combustibles que se le otorgue el mismo trato a todos, al denunciar que desde el Ministerio de Hacienda se ha firmado un acuerdo con la Asociaci\u00f3n de Hoteles y Turismo de la Rep\u00fablica Dominicana (Asonahores) con el objetivo de que solo pague en 2 % del Itbis de los productos que importan. En ese sentido, el presidente de Fenatrano precis\u00f3 que en la actualidad tienen 67 autobuses en el muelle de due\u00f1os dominicanos y posiblemente m\u00e1s que los due\u00f1os de muchos hoteles, pero, ellos merecen el mismo trato, es decir un 2 % igualitario para el corredor Independencia. Hubieres dijo que no le est\u00e1n mendigando nada al gobierno, pero, as\u00ed como otros tienen exenciones fiscales multimillonarias de pasajeros y de cargas de todo el pa\u00eds, solo tienen 3000 mil millones, al indicar que solo se debe aplicar la equidad: \u201cPero siempre se quiere aplicar una narrativa en contra de los peque\u00f1os y de eso producirse habr\u00e1 lucha con la poblaci\u00f3n\u201d. &nbsp; Igualmente, solicit\u00f3 al gobierno resolver el problema, por lo menos en el Gran Santo Domingo con los cuatro mil choferes de las rutas afiliadas a Fenatrano que no tienen Bonogas, debido a la cancelaci\u00f3n de las tarjetas. \u201cQue el Gobierno destine esa partida, y que en un breve plazo de 15 a 20 d\u00edas puedan tener sus tarjetas de Bonogas, de cinco mil pesos como se acord\u00f3 hace dos a\u00f1os\u201d, expuso. Juan Hubieres solicit\u00f3, adem\u00e1s, con est\u00e1s condiciones una mesa de di\u00e1logo que vea estos puntos: \u201cAs\u00ed como Asonahores que solo va a pagar un 2 % de Itbis y nada m\u00e1s en todo lo que adquieran y compren, as\u00ed tambi\u00e9n est\u00e1n la Asociaci\u00f3n de Concesionarios de Fabricantes de Veh\u00edculos (Acofave), que paga un porcentaje de Itbis y les desmontan un 28 % al igual que la zona franca que no pagan un peso de impuestos\u201d. El l\u00edder de Fenatrano asever\u00f3 que el sector transporte genera m\u00e1s ingresos al gobierno que m\u00e1s de esas grandes capitales, as\u00ed como m\u00e1s empleos en todo el pa\u00eds. Afirm\u00f3 que Fenatrano ni sus rutas afiliadas son firmantes de ning\u00fan documento para mendigar: \u201cSolo planteamos una mesa de di\u00e1logos para el pa\u00eds, y que el gobierno siga resolviendo con alternativas que establecieron otros gobiernos mediante la Refiner\u00eda\u201d. No hay aumento de pasaje ni en Santo Domingo Este ni Santo Domingo Norte ni en Los Alcarrizos ni en ning\u00fan lao\u2026esos que andan inventando no tiene ni tres rutas ni guagua para subir pasajes y lo que est\u00e1n es chantajeando\u2026con nosotros nadie cuente para chantajear\u201d, concluy\u00f3 Juan Hubieres, presidente de Fenatrano.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-139831","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/139831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=139831"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/139831\/revisions"}],"predecessor-version":[{"id":139833,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/139831\/revisions\/139833"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=139831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=139831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=139831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}