{"id":140565,"date":"2025-11-18T13:04:14","date_gmt":"2025-11-18T17:04:14","guid":{"rendered":"https:\/\/conexiondigital.com.do\/?p=140565"},"modified":"2025-11-18T13:04:14","modified_gmt":"2025-11-18T17:04:14","slug":"presidente-abinader-encabeza-la-tercera-sesion-de-vistas-publicas-del-consejo-nacional-de-la-magistratura-para-llenar-vacantes-en-la-scj-y-el-tse","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2025\/11\/18\/presidente-abinader-encabeza-la-tercera-sesion-de-vistas-publicas-del-consejo-nacional-de-la-magistratura-para-llenar-vacantes-en-la-scj-y-el-tse\/","title":{"rendered":"Presidente Abinader encabeza la tercera sesi\u00f3n de vistas p\u00fablicas del Consejo Nacional de la Magistratura para llenar vacantes en la SCJ y el TSE"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"\" alt=\"\" class=\"wp-image-140566\" srcset=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/11\/6aaabe51-8f62-4216-a838-54edf6b8cd91-1024x682.jpg 1024w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/11\/6aaabe51-8f62-4216-a838-54edf6b8cd91-800x533.jpg 800w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/11\/6aaabe51-8f62-4216-a838-54edf6b8cd91-768x512.jpg 768w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/11\/6aaabe51-8f62-4216-a838-54edf6b8cd91-1536x1023.jpg 1536w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/11\/6aaabe51-8f62-4216-a838-54edf6b8cd91-300x200.jpg 300w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/11\/6aaabe51-8f62-4216-a838-54edf6b8cd91.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Santo Domingo.\u2014 En estos momentos, el presidente Luis Abinader encabeza la tercera sesi\u00f3n de vistas p\u00fablicas del Consejo Nacional de la Magistratura (CNM) para la elecci\u00f3n de los nuevos jueces que integrar\u00e1n la Suprema Corte de Justicia (SCJ) y el Tribunal Superior Electoral (TSE).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La sesi\u00f3n, que inici\u00f3 a las 9:20 de la ma\u00f1ana en el Sal\u00f3n Las Cari\u00e1tides del Palacio Nacional, contempla la evaluaci\u00f3n de 21 de los 83 candidatos postulados para ocupar las vacantes en las altas cortes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pasado 11 de noviembre fueron evaluados 21 postulantes en la primera sesi\u00f3n, y en la segunda jornada, celebrada el d\u00eda 14, se evaluaron 20 aspirantes, para un total de 41.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la reuni\u00f3n participan los presidentes de la Suprema Corte de Justicia, Luis Henry Molina; del Tribunal Constitucional, Napole\u00f3n Est\u00e9vez Lavandier; del Senado, Ricardo de los Santos y de la C\u00e1mara de Diputados, Alfredo Pacheco, as\u00ed como la jueza de la Suprema Corte de Justicia, magistrada Nancy Salcedo Fern\u00e1ndez, el senador Omar Fern\u00e1ndez y el diputado Tob\u00edas Crespo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los postulantes en esta tercera sesi\u00f3n son:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1) Samuel Moquete de la Cruz TSE;<br>2) Yokaurys Morales Castillo SCJ o TSE;<br>3) Wilson Francisco Moreta Tremols SCJ;<br>4) Aldemaro Jos\u00e9 Mu\u00f1iz Mena SCJ o TSE;<br>5) Daniel Julio Nolasco Olivo SCJ;<br>6) Edison Joel Pe\u00f1a SCJ;<br>7) Stefany Mar\u00eda Pe\u00f1a Hern\u00e1ndez TSE;<br>8) C\u00e9sar Ren\u00e9 Pe\u00f1al\u00f3 Ozuna TSE;<br>9) Rafaelina Peralta Arias TSE;<br>10) Cristian Perdomo Hern\u00e1ndez TSE;<br>11) Sonia Milagros Perdomo Rodr\u00edguez SCJ;<br>12) Rosa Fior D&#8217;Aliza P\u00e9rez de Garc\u00eda TSE;<br>13) Amauri Antonio Pimentel Fabi\u00e1n SCJ;<br>14) Doris Josefina Pujols Ortiz SCJ o TSE;<br>15) Juan Jos\u00e9 Quezada Rodr\u00edguez TSE;<br>16) Roberto Carlos Quiroz Canela SCJ;<br>17) Alfredo Ram\u00edrez Peguero TSE;<br>18) Manuel Antonio Ram\u00edrez Suza\u00f1a SCJ;<br>19) Fermina Reynoso TSE;<br>20) Maritza Marizol Reynoso SCJ;<br>21) Arelis Socorro Ricourt G\u00f3mez SCJ.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.\u2014 En estos momentos, el presidente Luis Abinader encabeza la tercera sesi\u00f3n de vistas p\u00fablicas del Consejo Nacional de la Magistratura (CNM) para la elecci\u00f3n de los nuevos jueces que integrar\u00e1n la Suprema Corte de Justicia (SCJ) y el Tribunal Superior Electoral (TSE). La sesi\u00f3n, que inici\u00f3 a las 9:20 de la ma\u00f1ana en el Sal\u00f3n Las Cari\u00e1tides del Palacio Nacional, contempla la evaluaci\u00f3n de 21 de los 83 candidatos postulados para ocupar las vacantes en las altas cortes. El pasado 11 de noviembre fueron evaluados 21 postulantes en la primera sesi\u00f3n, y en la segunda jornada, celebrada el d\u00eda 14, se evaluaron 20 aspirantes, para un total de 41. En la reuni\u00f3n participan los presidentes de la Suprema Corte de Justicia, Luis Henry Molina; del Tribunal Constitucional, Napole\u00f3n Est\u00e9vez Lavandier; del Senado, Ricardo de los Santos y de la C\u00e1mara de Diputados, Alfredo Pacheco, as\u00ed como la jueza de la Suprema Corte de Justicia, magistrada Nancy Salcedo Fern\u00e1ndez, el senador Omar Fern\u00e1ndez y el diputado Tob\u00edas Crespo. Los postulantes en esta tercera sesi\u00f3n son: 1) Samuel Moquete de la Cruz TSE;2) Yokaurys Morales Castillo SCJ o TSE;3) Wilson Francisco Moreta Tremols SCJ;4) Aldemaro Jos\u00e9 Mu\u00f1iz Mena SCJ o TSE;5) Daniel Julio Nolasco Olivo SCJ;6) Edison Joel Pe\u00f1a SCJ;7) Stefany Mar\u00eda Pe\u00f1a Hern\u00e1ndez TSE;8) C\u00e9sar Ren\u00e9 Pe\u00f1al\u00f3 Ozuna TSE;9) Rafaelina Peralta Arias TSE;10) Cristian Perdomo Hern\u00e1ndez TSE;11) Sonia Milagros Perdomo Rodr\u00edguez SCJ;12) Rosa Fior D&#8217;Aliza P\u00e9rez de Garc\u00eda TSE;13) Amauri Antonio Pimentel Fabi\u00e1n SCJ;14) Doris Josefina Pujols Ortiz SCJ o TSE;15) Juan Jos\u00e9 Quezada Rodr\u00edguez TSE;16) Roberto Carlos Quiroz Canela SCJ;17) Alfredo Ram\u00edrez Peguero TSE;18) Manuel Antonio Ram\u00edrez Suza\u00f1a SCJ;19) Fermina Reynoso TSE;20) Maritza Marizol Reynoso SCJ;21) Arelis Socorro Ricourt G\u00f3mez SCJ.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-140565","post","type-post","status-publish","format-standard","hentry","category-politic"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/140565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=140565"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/140565\/revisions"}],"predecessor-version":[{"id":140567,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/140565\/revisions\/140567"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=140565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=140565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=140565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}