{"id":141355,"date":"2025-12-21T09:13:31","date_gmt":"2025-12-21T13:13:31","guid":{"rendered":"https:\/\/conexiondigital.com.do\/?p=141355"},"modified":"2025-12-21T09:13:32","modified_gmt":"2025-12-21T13:13:32","slug":"presidente-abinader-resalta-trabajo-de-periodistas-que-cubren-la-fuente-del-palacio-nacional","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2025\/12\/21\/presidente-abinader-resalta-trabajo-de-periodistas-que-cubren-la-fuente-del-palacio-nacional\/","title":{"rendered":"Presidente Abinader resalta trabajo de periodistas que cubren la fuente del Palacio Nacional"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"\" alt=\"\" class=\"wp-image-141356\" srcset=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/2892f5e2-5911-4127-abf0-de946c1c38af-1024x683.jpg 1024w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/2892f5e2-5911-4127-abf0-de946c1c38af-800x533.jpg 800w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/2892f5e2-5911-4127-abf0-de946c1c38af-768x512.jpg 768w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/2892f5e2-5911-4127-abf0-de946c1c38af-1536x1024.jpg 1536w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/2892f5e2-5911-4127-abf0-de946c1c38af-2048x1365.jpg 2048w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/2892f5e2-5911-4127-abf0-de946c1c38af-300x200.jpg 300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Reconoce que no es una labor \u00abf\u00e1cil\u00bb por las intensas agendas que cumple.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Santo Domingo.- El presidente Luis Abinader destac\u00f3 la labor que realizan los periodistas que cubren las incidencias del Palacio Nacional en un trabajo en el, que reconoce, es intenso por las actividades que involucra su agenda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abQuiero agradecer a ustedes, que nos acompa\u00f1an cada d\u00eda en un trabajo que no es f\u00e1cil, en un trabajo en el que, yo se que ustedes van muchas veces forzados con las diferentes actividades que tenemos\u00bb, manifest\u00f3 el jefe de Estado al compartir un almuerzo con los periodistas que cubren las incidencias del Palacio Nacional.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"\" alt=\"\" class=\"wp-image-141357\" srcset=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/5ee3871b-2c45-4133-a45f-7c0f0cbd5a08-1024x683.jpg 1024w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/5ee3871b-2c45-4133-a45f-7c0f0cbd5a08-800x533.jpg 800w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/5ee3871b-2c45-4133-a45f-7c0f0cbd5a08-768x512.jpg 768w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/5ee3871b-2c45-4133-a45f-7c0f0cbd5a08-1536x1024.jpg 1536w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/5ee3871b-2c45-4133-a45f-7c0f0cbd5a08-2048x1365.jpg 2048w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/5ee3871b-2c45-4133-a45f-7c0f0cbd5a08-300x200.jpg 300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Manifest\u00f3 su deseo de ser m\u00e1s cercano a ellos, pero -dijo- que sus obligaciones de Estado no le permiten dedicarle toda la atenci\u00f3n que merecen quienes se encargan de informar a la ciudadan\u00eda, la cual valora y respeta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al encabezar el almuerzo con periodistas, camar\u00f3grafos y fot\u00f3grafos que cubren fuente del Palacio Nacional, el jefe de Estado, quien estuvo acompa\u00f1ado del ministro de Defensa, teniente general Carlos Antonio Fern\u00e1ndez Onofre; de los titulares de la Direcci\u00f3n de Estrategia y Comunicaci\u00f3n Gubernamental (DIECOM), F\u00e9lix Reyna; de la Direcci\u00f3n de Prensa del Presidente, Carlos Alberto Caminero y del subdirector de DIECOM, Abel Guzm\u00e1n Then; agradeci\u00f3 el trato y apoyo a su gesti\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"\" alt=\"\" class=\"wp-image-141358\" srcset=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/e8cce767-7648-4b9b-8442-afbc5f80ffba-1024x683.jpg 1024w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/e8cce767-7648-4b9b-8442-afbc5f80ffba-800x533.jpg 800w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/e8cce767-7648-4b9b-8442-afbc5f80ffba-768x512.jpg 768w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/e8cce767-7648-4b9b-8442-afbc5f80ffba-1536x1024.jpg 1536w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/e8cce767-7648-4b9b-8442-afbc5f80ffba-2048x1365.jpg 2048w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/e8cce767-7648-4b9b-8442-afbc5f80ffba-300x200.jpg 300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abVamos a seguir trabajando juntos, con confianza, con respeto y que siempre entre nosotros y m\u00e1s all\u00e1 de presidente de la Rep\u00fablica nos sientan como un amigo\u00bb, expres\u00f3 el mandatario al tiempo de desearles una feliz Navidad, con mucha salud para el pr\u00f3ximo a\u00f1o, \u00e9xitos y que lo disfruten con sus seres queridos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Resaltan apertura con la prensa<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En las palabras a los periodistas, el director de Prensa del Presidente, Alberto Caminero, record\u00f3 que el encuentro es de confraternidad para hacer un aparte en la labor diaria y compartir como colegas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Caminero destac\u00f3 que desde que inici\u00f3 su acompa\u00f1amiento al presidente Luis Abinader ha mantenido la misma disciplina, el mismo entusiasmo y af\u00e1n de trabajo y honestidad cuyas acciones en el Gobierno han sido las mismas que lo han caracterizado en su vida pol\u00edtica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Subray\u00f3 que el dignatario es un hombre que no fue a servirse del Gobierno y que su proyecto pol\u00edtico lo financi\u00f3 con los recursos de familia porque es un hombre \u00absincero y sin dobleces que no tiene dos caras y que dice las cosas de frente\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"\" alt=\"\" class=\"wp-image-141359\" srcset=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/392e417e-c4b5-4df8-a9ee-c13f537247b4-1024x683.jpg 1024w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/392e417e-c4b5-4df8-a9ee-c13f537247b4-800x533.jpg 800w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/392e417e-c4b5-4df8-a9ee-c13f537247b4-768x512.jpg 768w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/392e417e-c4b5-4df8-a9ee-c13f537247b4-1536x1024.jpg 1536w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/392e417e-c4b5-4df8-a9ee-c13f537247b4-2048x1365.jpg 2048w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/392e417e-c4b5-4df8-a9ee-c13f537247b4-300x200.jpg 300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">De su lado, el director de Estrategia y Comunicaci\u00f3n Gubernamental, F\u00e9lix Reyna, resalt\u00f3 lo significativo de la presencia del mandatario que modific\u00f3 su agenda para compartir con los periodistas que cubren la fuente del Palacio Nacional, por la importancia que le confiere al trabajo que realizan los profesionales de la comunicaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reyna destac\u00f3 la cercan\u00eda, dedicaci\u00f3n y preocupaci\u00f3n permanente del mandatario por colocar a los representantes de los medios de comunicaci\u00f3n en el sitial que les corresponde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que por sus a\u00f1os en el ejercicio de la profesi\u00f3n puede asegurar que el actual es un momento estelar en el periodismo dominicano por la cercan\u00eda y preocupaci\u00f3n permanente y el contacto directo con los periodistas por la importancia que tienen para el presidente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEste es un presidente excepcional en cuanto al manejo de las Relaciones P\u00fablicas, la comunicaci\u00f3n y su relaci\u00f3n con los periodistas en sentido general\u00bb, apostill\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En las palabras de bienvenida, el subdirector de la DIECOM, Abel Guzm\u00e1n Then, resalt\u00f3 la labor comunicacional de quienes cubren las incidencias de la Casa de Gobierno de forma tan profesional \u00abque, la verdad, eleva el nombre de la comunicaci\u00f3n y el periodismo como lo hacen ustedes cada d\u00eda de manera denodada\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Expres\u00f3 la satisfacci\u00f3n que siente esta gesti\u00f3n, bajo la direcci\u00f3n de F\u00e9lix Reyna, en la DIECOM y de Alberto Caminero, en la Direcci\u00f3n de Prensa del Presidente, de compartir un espacio en \u00abla etapa de mayor apertura hacia los medios de comunicaci\u00f3n con el presidente, como lo es Luis Abinader, m\u00e1s abierto y que cree en la prensa libre y en la comunicaci\u00f3n\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEl presidente Luis Abinader entiende que el trabajo que ustedes hacen diariamente es de cara a la democracia y de cara al sol, para fortalecer la comunicaci\u00f3n gubernamental\u00bb, manifest\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Reconoce que no es una labor \u00abf\u00e1cil\u00bb por las intensas agendas que cumple. Santo Domingo.- El presidente Luis Abinader destac\u00f3 la labor que realizan los periodistas que cubren las incidencias del Palacio Nacional en un trabajo en el, que reconoce, es intenso por las actividades que involucra su agenda. \u00abQuiero agradecer a ustedes, que nos acompa\u00f1an cada d\u00eda en un trabajo que no es f\u00e1cil, en un trabajo en el que, yo se que ustedes van muchas veces forzados con las diferentes actividades que tenemos\u00bb, manifest\u00f3 el jefe de Estado al compartir un almuerzo con los periodistas que cubren las incidencias del Palacio Nacional. Manifest\u00f3 su deseo de ser m\u00e1s cercano a ellos, pero -dijo- que sus obligaciones de Estado no le permiten dedicarle toda la atenci\u00f3n que merecen quienes se encargan de informar a la ciudadan\u00eda, la cual valora y respeta. Al encabezar el almuerzo con periodistas, camar\u00f3grafos y fot\u00f3grafos que cubren fuente del Palacio Nacional, el jefe de Estado, quien estuvo acompa\u00f1ado del ministro de Defensa, teniente general Carlos Antonio Fern\u00e1ndez Onofre; de los titulares de la Direcci\u00f3n de Estrategia y Comunicaci\u00f3n Gubernamental (DIECOM), F\u00e9lix Reyna; de la Direcci\u00f3n de Prensa del Presidente, Carlos Alberto Caminero y del subdirector de DIECOM, Abel Guzm\u00e1n Then; agradeci\u00f3 el trato y apoyo a su gesti\u00f3n. \u00abVamos a seguir trabajando juntos, con confianza, con respeto y que siempre entre nosotros y m\u00e1s all\u00e1 de presidente de la Rep\u00fablica nos sientan como un amigo\u00bb, expres\u00f3 el mandatario al tiempo de desearles una feliz Navidad, con mucha salud para el pr\u00f3ximo a\u00f1o, \u00e9xitos y que lo disfruten con sus seres queridos. Resaltan apertura con la prensa En las palabras a los periodistas, el director de Prensa del Presidente, Alberto Caminero, record\u00f3 que el encuentro es de confraternidad para hacer un aparte en la labor diaria y compartir como colegas. Caminero destac\u00f3 que desde que inici\u00f3 su acompa\u00f1amiento al presidente Luis Abinader ha mantenido la misma disciplina, el mismo entusiasmo y af\u00e1n de trabajo y honestidad cuyas acciones en el Gobierno han sido las mismas que lo han caracterizado en su vida pol\u00edtica. Subray\u00f3 que el dignatario es un hombre que no fue a servirse del Gobierno y que su proyecto pol\u00edtico lo financi\u00f3 con los recursos de familia porque es un hombre \u00absincero y sin dobleces que no tiene dos caras y que dice las cosas de frente\u00bb. De su lado, el director de Estrategia y Comunicaci\u00f3n Gubernamental, F\u00e9lix Reyna, resalt\u00f3 lo significativo de la presencia del mandatario que modific\u00f3 su agenda para compartir con los periodistas que cubren la fuente del Palacio Nacional, por la importancia que le confiere al trabajo que realizan los profesionales de la comunicaci\u00f3n. Reyna destac\u00f3 la cercan\u00eda, dedicaci\u00f3n y preocupaci\u00f3n permanente del mandatario por colocar a los representantes de los medios de comunicaci\u00f3n en el sitial que les corresponde. Dijo que por sus a\u00f1os en el ejercicio de la profesi\u00f3n puede asegurar que el actual es un momento estelar en el periodismo dominicano por la cercan\u00eda y preocupaci\u00f3n permanente y el contacto directo con los periodistas por la importancia que tienen para el presidente. \u00abEste es un presidente excepcional en cuanto al manejo de las Relaciones P\u00fablicas, la comunicaci\u00f3n y su relaci\u00f3n con los periodistas en sentido general\u00bb, apostill\u00f3. En las palabras de bienvenida, el subdirector de la DIECOM, Abel Guzm\u00e1n Then, resalt\u00f3 la labor comunicacional de quienes cubren las incidencias de la Casa de Gobierno de forma tan profesional \u00abque, la verdad, eleva el nombre de la comunicaci\u00f3n y el periodismo como lo hacen ustedes cada d\u00eda de manera denodada\u00bb. Expres\u00f3 la satisfacci\u00f3n que siente esta gesti\u00f3n, bajo la direcci\u00f3n de F\u00e9lix Reyna, en la DIECOM y de Alberto Caminero, en la Direcci\u00f3n de Prensa del Presidente, de compartir un espacio en \u00abla etapa de mayor apertura hacia los medios de comunicaci\u00f3n con el presidente, como lo es Luis Abinader, m\u00e1s abierto y que cree en la prensa libre y en la comunicaci\u00f3n\u00bb. \u00abEl presidente Luis Abinader entiende que el trabajo que ustedes hacen diariamente es de cara a la democracia y de cara al sol, para fortalecer la comunicaci\u00f3n gubernamental\u00bb, manifest\u00f3.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-141355","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/141355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=141355"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/141355\/revisions"}],"predecessor-version":[{"id":141360,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/141355\/revisions\/141360"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=141355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=141355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=141355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}