{"id":141424,"date":"2025-12-25T09:22:00","date_gmt":"2025-12-25T13:22:00","guid":{"rendered":"https:\/\/conexiondigital.com.do\/?p=141424"},"modified":"2025-12-25T09:25:22","modified_gmt":"2025-12-25T13:25:22","slug":"presidente-abinader-llama-a-los-dominicanos-a-estar-unidos-al-amor-y-la-solidaridad-en-esta-navidad-y-ano-nuevo","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2025\/12\/25\/presidente-abinader-llama-a-los-dominicanos-a-estar-unidos-al-amor-y-la-solidaridad-en-esta-navidad-y-ano-nuevo\/","title":{"rendered":"Presidente Abinader llama a los dominicanos a estar unidos, al amor y la solidaridad en esta Navidad y A\u00f1o Nuevo"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"592\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/694c43b44cd6a.jpg\" alt=\"\" class=\"wp-image-141425\" srcset=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/694c43b44cd6a.jpg 1200w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/694c43b44cd6a-800x395.jpg 800w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/694c43b44cd6a-1024x505.jpg 1024w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2025\/12\/694c43b44cd6a-768x379.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\"><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exhorta a la poblaci\u00f3n a cuidarse de la ambici\u00f3n desmedida por la riqueza, durante mensaje de Navidad junto a su esposa, la primera dama Raquel Arbaje.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Santo Domingo, R.D.- El presidente de la Rep\u00fablica, Luis Abinader, y su esposa, la primera dama Raquel Arbaje, enviaron un emotivo Mensaje de Navidad a la Naci\u00f3n dominicana, destacando la importancia de la unidad, la solidaridad y los valores fundamentales que gu\u00edan al pa\u00eds, pero tambi\u00e9n los peligros de la ambici\u00f3n y el amor desmedido por las riquezas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un audiovisual, el mandatario reflexion\u00f3 sobre el real significado de la Navidad, enfatizando que \u00abes un tiempo para reafirmar los valores que aprendimos en nuestros hogares: el respeto, la honestidad y la humildad\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destac\u00f3, adem\u00e1s, que la Navidad debe ser \u00abcomo aquella noche sencilla y silenciosa en la que naci\u00f3 Jes\u00fas, sin ostentaci\u00f3n ni grandezas\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La primera dama, Raquel Arbaje, se uni\u00f3 al mensaje, expresando que \u00abestoy aqu\u00ed no solo como su compa\u00f1era de vida, sino como aliada en la causa de servir y transformar positivamente nuestra naci\u00f3n\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Llam\u00f3 a los dominicanos a mirarse de forma sincera, a aprender, a reivindicar y a reencontrarse con lo mejor de s\u00ed mismos como seres humanos y como pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El gobernante invit\u00f3 a los dominicanos a compartir \u00abel amor de sus familias, el abrazo de los verdaderos amigos y la fe que nos sostiene\u00bb, y destac\u00f3 que \u00abla felicidad no nace del tener, sino del amar; no del exceso, sino de la paz que habita en el coraz\u00f3n\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mensaje de la pareja presidencial continu\u00f3 con un llamado a la unidad y la esperanza, con la plegaria de que \u00abesta Navidad nos una en EL AMOR, que renueve la esperanza en cada familia dominicana y que el Ni\u00f1o Dios llene nuestros hogares de luz, de paz y de bendiciones\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con las frases \u00a1\u00bbDios bendiga a la Rep\u00fablica Dominicana! \u00a1\u00bbFeliz Navidad y un a\u00f1o nuevo cargado de esperanzas\u00bb!, concluye el mensaje de la pareja presidencial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Exhorta a la poblaci\u00f3n a cuidarse de la ambici\u00f3n desmedida por la riqueza, durante mensaje de Navidad junto a su esposa, la primera dama Raquel Arbaje. Santo Domingo, R.D.- El presidente de la Rep\u00fablica, Luis Abinader, y su esposa, la primera dama Raquel Arbaje, enviaron un emotivo Mensaje de Navidad a la Naci\u00f3n dominicana, destacando la importancia de la unidad, la solidaridad y los valores fundamentales que gu\u00edan al pa\u00eds, pero tambi\u00e9n los peligros de la ambici\u00f3n y el amor desmedido por las riquezas. En un audiovisual, el mandatario reflexion\u00f3 sobre el real significado de la Navidad, enfatizando que \u00abes un tiempo para reafirmar los valores que aprendimos en nuestros hogares: el respeto, la honestidad y la humildad\u00bb. Destac\u00f3, adem\u00e1s, que la Navidad debe ser \u00abcomo aquella noche sencilla y silenciosa en la que naci\u00f3 Jes\u00fas, sin ostentaci\u00f3n ni grandezas\u00bb. La primera dama, Raquel Arbaje, se uni\u00f3 al mensaje, expresando que \u00abestoy aqu\u00ed no solo como su compa\u00f1era de vida, sino como aliada en la causa de servir y transformar positivamente nuestra naci\u00f3n\u00bb. Llam\u00f3 a los dominicanos a mirarse de forma sincera, a aprender, a reivindicar y a reencontrarse con lo mejor de s\u00ed mismos como seres humanos y como pa\u00eds. El gobernante invit\u00f3 a los dominicanos a compartir \u00abel amor de sus familias, el abrazo de los verdaderos amigos y la fe que nos sostiene\u00bb, y destac\u00f3 que \u00abla felicidad no nace del tener, sino del amar; no del exceso, sino de la paz que habita en el coraz\u00f3n\u00bb. El mensaje de la pareja presidencial continu\u00f3 con un llamado a la unidad y la esperanza, con la plegaria de que \u00abesta Navidad nos una en EL AMOR, que renueve la esperanza en cada familia dominicana y que el Ni\u00f1o Dios llene nuestros hogares de luz, de paz y de bendiciones\u00bb. Con las frases \u00a1\u00bbDios bendiga a la Rep\u00fablica Dominicana! \u00a1\u00bbFeliz Navidad y un a\u00f1o nuevo cargado de esperanzas\u00bb!, concluye el mensaje de la pareja presidencial.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-141424","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/141424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=141424"}],"version-history":[{"count":2,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/141424\/revisions"}],"predecessor-version":[{"id":141427,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/141424\/revisions\/141427"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=141424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=141424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=141424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}