{"id":142126,"date":"2026-02-12T14:16:59","date_gmt":"2026-02-12T18:16:59","guid":{"rendered":"https:\/\/conexiondigital.com.do\/?p=142126"},"modified":"2026-02-12T14:17:00","modified_gmt":"2026-02-12T18:17:00","slug":"abinader-designa-a-maira-morla-pineda-como-nueva-directora-general-del-infotep","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2026\/02\/12\/abinader-designa-a-maira-morla-pineda-como-nueva-directora-general-del-infotep\/","title":{"rendered":"Abinader designa a Maira Morla Pineda como nueva directora general del INFOTEP"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"92\" height=\"92\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/02\/download-3.jpg\" alt=\"\" class=\"wp-image-142127\" style=\"width:840px;height:auto\"><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Morla Pineda tiene m\u00e1s de tres d\u00e9cadas de experiencia dentro de la instituci\u00f3n, se desempe\u00f1aba como subdirectora general desde 2014.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Santo Domingo. \u2013 El presidente de la Rep\u00fablica, Luis Abinader, design\u00f3 a Maira Margarita Morla Pineda como nueva directora general del Instituto Nacional de Formaci\u00f3n T\u00e9cnico Profesional (INFOTEP), mediante el Decreto n\u00fam. 95-26.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La designaci\u00f3n se produce en cumplimiento de lo establecido en la Ley n\u00fam. 116, que crea el INFOTEP, la cual dispone que su director general debe ser seleccionado por el Poder Ejecutivo a partir de una terna sometida por la Junta de Directores del Instituto. En este caso, la terna fue remitida el 10 de febrero de 2026 e inclu\u00eda adem\u00e1s a Luis Manuel Rodr\u00edguez Acosta y Luis Hernani Beltr\u00e9 Mesa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Morla Pineda cuenta con m\u00e1s de tres d\u00e9cadas de experiencia dentro del INFOTEP, donde ha ocupado posiciones directivas de alto nivel. Hasta la fecha de su designaci\u00f3n se desempe\u00f1aba como subdirectora general (2014-2026), luego de haber ejercido como gerente regional central, directora regional sur y suroeste, y responsable de distintas \u00e1reas estrat\u00e9gicas de apoyo a la competitividad empresarial y laboral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es licenciada en Contabilidad por la Universidad Dominicana O&amp;M y posee maestr\u00edas en Alta Gerencia y en Educaci\u00f3n por el INTEC, adem\u00e1s de un posgrado en Administraci\u00f3n de la Educaci\u00f3n T\u00e9cnica y de la Formaci\u00f3n Profesional. Su perfil combina formaci\u00f3n acad\u00e9mica especializada con amplia capacitaci\u00f3n en liderazgo, calidad, planificaci\u00f3n estrat\u00e9gica, TICs e industria 4.0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante su trayectoria ha impulsado proyectos de modernizaci\u00f3n tecnol\u00f3gica, energ\u00edas renovables, certificaciones internacionales de calidad bajo normas ISO 9001, as\u00ed como programas de articulaci\u00f3n con sectores productivos nacionales e internacionales. Tambi\u00e9n ha representado al pa\u00eds en escenarios como la Asamblea Mundial WorldSkills y congresos vinculados a econom\u00eda circular, turismo, zonas francas y formaci\u00f3n profesional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Morla Pineda tiene m\u00e1s de tres d\u00e9cadas de experiencia dentro de la instituci\u00f3n, se desempe\u00f1aba como subdirectora general desde 2014. Santo Domingo. \u2013 El presidente de la Rep\u00fablica, Luis Abinader, design\u00f3 a Maira Margarita Morla Pineda como nueva directora general del Instituto Nacional de Formaci\u00f3n T\u00e9cnico Profesional (INFOTEP), mediante el Decreto n\u00fam. 95-26. La designaci\u00f3n se produce en cumplimiento de lo establecido en la Ley n\u00fam. 116, que crea el INFOTEP, la cual dispone que su director general debe ser seleccionado por el Poder Ejecutivo a partir de una terna sometida por la Junta de Directores del Instituto. En este caso, la terna fue remitida el 10 de febrero de 2026 e inclu\u00eda adem\u00e1s a Luis Manuel Rodr\u00edguez Acosta y Luis Hernani Beltr\u00e9 Mesa. Morla Pineda cuenta con m\u00e1s de tres d\u00e9cadas de experiencia dentro del INFOTEP, donde ha ocupado posiciones directivas de alto nivel. Hasta la fecha de su designaci\u00f3n se desempe\u00f1aba como subdirectora general (2014-2026), luego de haber ejercido como gerente regional central, directora regional sur y suroeste, y responsable de distintas \u00e1reas estrat\u00e9gicas de apoyo a la competitividad empresarial y laboral. Es licenciada en Contabilidad por la Universidad Dominicana O&amp;M y posee maestr\u00edas en Alta Gerencia y en Educaci\u00f3n por el INTEC, adem\u00e1s de un posgrado en Administraci\u00f3n de la Educaci\u00f3n T\u00e9cnica y de la Formaci\u00f3n Profesional. Su perfil combina formaci\u00f3n acad\u00e9mica especializada con amplia capacitaci\u00f3n en liderazgo, calidad, planificaci\u00f3n estrat\u00e9gica, TICs e industria 4.0. Durante su trayectoria ha impulsado proyectos de modernizaci\u00f3n tecnol\u00f3gica, energ\u00edas renovables, certificaciones internacionales de calidad bajo normas ISO 9001, as\u00ed como programas de articulaci\u00f3n con sectores productivos nacionales e internacionales. Tambi\u00e9n ha representado al pa\u00eds en escenarios como la Asamblea Mundial WorldSkills y congresos vinculados a econom\u00eda circular, turismo, zonas francas y formaci\u00f3n profesional.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-142126","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/142126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=142126"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/142126\/revisions"}],"predecessor-version":[{"id":142128,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/142126\/revisions\/142128"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=142126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=142126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=142126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}