{"id":142495,"date":"2026-03-03T18:33:48","date_gmt":"2026-03-03T22:33:48","guid":{"rendered":"https:\/\/conexiondigital.com.do\/?p=142495"},"modified":"2026-03-03T18:33:48","modified_gmt":"2026-03-03T22:33:48","slug":"economia-dominicana-registra-crecimiento-interanual-de-3-5-en-enero-2026","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2026\/03\/03\/economia-dominicana-registra-crecimiento-interanual-de-3-5-en-enero-2026\/","title":{"rendered":"Econom\u00eda dominicana registra crecimiento interanual de 3.5\u00a0% en enero 2026"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/03\/69a648d64c0b7.jpg\" alt=\"\" class=\"wp-image-142498\" style=\"width:840px;height:auto\" srcset=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/03\/69a648d64c0b7.jpg 800w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/03\/69a648d64c0b7-768x432.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\"><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>La variaci\u00f3n interanual de 3.5\u00a0% en el referido per\u00edodo refleja el ritmo de expansi\u00f3n de la actividad econ\u00f3mica m\u00e1s alto de los \u00faltimos diez meses, luego de haber registrado un crecimiento promedio de 2.1\u00a0% en el a\u00f1o 2025.<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las cifras preliminares del Indicador Mensual de Actividad Econ\u00f3mica (IMAE) correspondientes al mes de enero de 2026 muestran una expansi\u00f3n interanual de 3.5&nbsp;%, resultado principalmente del desempe\u00f1o favorable del valor agregado real del sector construcci\u00f3n (7.6&nbsp;%), manufactura local (3.4&nbsp;%) y de las actividades del sector servicios en su conjunto (3.5&nbsp;%). Dentro de estas \u00faltimas se destacan hoteles, bares y restaurantes (3.8&nbsp;%), intermediaci\u00f3n financiera, seguros y actividades conexas (4.6&nbsp;%), ense\u00f1anza (7.8&nbsp;%), salud (5.8&nbsp;%), servicios profesionales (4.0&nbsp;%) y otras actividades de servicios (3.5&nbsp;%).<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"519\" height=\"459\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/03\/IME-3.png\" alt=\"\" class=\"wp-image-142496\"><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Este desempe\u00f1o se ha logrado pese al contexto internacional de incertidumbre caracterizado por tensiones geopol\u00edticas y cambios en la pol\u00edtica de comercio exterior, as\u00ed como en el \u00e1mbito migratorio y de programas sociales implementados por los Estados Unidos de Am\u00e9rica, que afectaron las expectativas de los agentes econ\u00f3micos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el \u00e1mbito dom\u00e9stico, al analizar el comportamiento de mes de enero 2026 por actividad econ\u00f3mica, se observa que la construcci\u00f3n ha iniciado el a\u00f1o con un crecimiento interanual de 7.6&nbsp;%, el cual se explica por una mayor ejecuci\u00f3n en el gasto de capital por parte del sector p\u00fablico que cerr\u00f3 el 2025 en 2.9&nbsp;% del PIB, 0.4 puntos porcentuales mayor al verificado en 2024 y por la inversi\u00f3n privada en proyectos residenciales, comerciales y tur\u00edsticos. La reactivaci\u00f3n del componente privado ha estado influenciada en gran medida por las condiciones financieras m\u00e1s flexibles que ha promovido la pol\u00edtica monetaria, reflej\u00e1ndose en tasas de inter\u00e9s activas m\u00e1s favorables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese tenor, en la medida en que contin\u00fae operando el mecanismo de transmisi\u00f3n de la pol\u00edtica monetaria y se despejen los factores de incertidumbre que han afectado la inversi\u00f3n privada, unido a una mayor inversi\u00f3n p\u00fablica, la econom\u00eda estar\u00e1 en condiciones de cerrar el 2026 con un crecimiento en torno a 4.0&nbsp;% recuperando gradualmente su ritmo de crecimiento potencial en el mediano plazo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con relaci\u00f3n al valor agregado de hoteles, bares y restaurantes, el mismo exhibi\u00f3 una variaci\u00f3n interanual de 3.8&nbsp;%, lo que responde en gran medida al incremento en la llegada de pasajeros no residentes v\u00eda a\u00e9rea, la cual alcanz\u00f3 un total de 825,847 turistas recibidos por los distintos aeropuertos del pa\u00eds en enero 2026, significando un crecimiento de 8.7&nbsp;%, respecto al mismo mes del a\u00f1o 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En otro orden, en enero de 2026 la manufactura local creci\u00f3 3.4&nbsp;% en t\u00e9rminos interanuales, explicado fundamentalmente por el comportamiento registrado en la fabricaci\u00f3n de productos met\u00e1licos y de minerales no met\u00e1licos. En cambio, la manufactura de zonas francas exhibi\u00f3 una variaci\u00f3n interanual de -3.9&nbsp;% y sus exportaciones totalizaron US$541.5 millones en el referido mes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La actividad de intermediaci\u00f3n financiera, seguros y actividades conexas experiment\u00f3 un crecimiento interanual de 4.6&nbsp;% reflejando principalmente la expansi\u00f3n de 9.1&nbsp;% del cr\u00e9dito dirigido al sector privado en moneda nacional y extranjera, equivalente a RD$211 mil millones adicionales con respecto a enero del a\u00f1o 2025, as\u00ed como al desempe\u00f1o favorable de los ingresos por primas y comisiones del conglomerado de empresas representado en esta actividad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, es importante destacar que el Banco Central de la Rep\u00fablica Dominicana continuar\u00e1 monitoreando el comportamiento de la econom\u00eda, adoptando las acciones necesarias para contribuir a retomar gradualmente la senda de crecimiento en torno al potencial, en la medida que se cuente con los espacios suficientes para hacerlo sin comprometer la estabilidad de precios, que constituye la misi\u00f3n primigenia y compromiso constitucional de la instituci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"670\" height=\"366\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/03\/IME-4.png\" alt=\"\" class=\"wp-image-142497\"><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La variaci\u00f3n interanual de 3.5\u00a0% en el referido per\u00edodo refleja el ritmo de expansi\u00f3n de la actividad econ\u00f3mica m\u00e1s alto de los \u00faltimos diez meses, luego de haber registrado un crecimiento promedio de 2.1\u00a0% en el a\u00f1o 2025. Las cifras preliminares del Indicador Mensual de Actividad Econ\u00f3mica (IMAE) correspondientes al mes de enero de 2026 muestran una expansi\u00f3n interanual de 3.5&nbsp;%, resultado principalmente del desempe\u00f1o favorable del valor agregado real del sector construcci\u00f3n (7.6&nbsp;%), manufactura local (3.4&nbsp;%) y de las actividades del sector servicios en su conjunto (3.5&nbsp;%). Dentro de estas \u00faltimas se destacan hoteles, bares y restaurantes (3.8&nbsp;%), intermediaci\u00f3n financiera, seguros y actividades conexas (4.6&nbsp;%), ense\u00f1anza (7.8&nbsp;%), salud (5.8&nbsp;%), servicios profesionales (4.0&nbsp;%) y otras actividades de servicios (3.5&nbsp;%). Este desempe\u00f1o se ha logrado pese al contexto internacional de incertidumbre caracterizado por tensiones geopol\u00edticas y cambios en la pol\u00edtica de comercio exterior, as\u00ed como en el \u00e1mbito migratorio y de programas sociales implementados por los Estados Unidos de Am\u00e9rica, que afectaron las expectativas de los agentes econ\u00f3micos. En el \u00e1mbito dom\u00e9stico, al analizar el comportamiento de mes de enero 2026 por actividad econ\u00f3mica, se observa que la construcci\u00f3n ha iniciado el a\u00f1o con un crecimiento interanual de 7.6&nbsp;%, el cual se explica por una mayor ejecuci\u00f3n en el gasto de capital por parte del sector p\u00fablico que cerr\u00f3 el 2025 en 2.9&nbsp;% del PIB, 0.4 puntos porcentuales mayor al verificado en 2024 y por la inversi\u00f3n privada en proyectos residenciales, comerciales y tur\u00edsticos. La reactivaci\u00f3n del componente privado ha estado influenciada en gran medida por las condiciones financieras m\u00e1s flexibles que ha promovido la pol\u00edtica monetaria, reflej\u00e1ndose en tasas de inter\u00e9s activas m\u00e1s favorables. En ese tenor, en la medida en que contin\u00fae operando el mecanismo de transmisi\u00f3n de la pol\u00edtica monetaria y se despejen los factores de incertidumbre que han afectado la inversi\u00f3n privada, unido a una mayor inversi\u00f3n p\u00fablica, la econom\u00eda estar\u00e1 en condiciones de cerrar el 2026 con un crecimiento en torno a 4.0&nbsp;% recuperando gradualmente su ritmo de crecimiento potencial en el mediano plazo. Con relaci\u00f3n al valor agregado de hoteles, bares y restaurantes, el mismo exhibi\u00f3 una variaci\u00f3n interanual de 3.8&nbsp;%, lo que responde en gran medida al incremento en la llegada de pasajeros no residentes v\u00eda a\u00e9rea, la cual alcanz\u00f3 un total de 825,847 turistas recibidos por los distintos aeropuertos del pa\u00eds en enero 2026, significando un crecimiento de 8.7&nbsp;%, respecto al mismo mes del a\u00f1o 2025. En otro orden, en enero de 2026 la manufactura local creci\u00f3 3.4&nbsp;% en t\u00e9rminos interanuales, explicado fundamentalmente por el comportamiento registrado en la fabricaci\u00f3n de productos met\u00e1licos y de minerales no met\u00e1licos. En cambio, la manufactura de zonas francas exhibi\u00f3 una variaci\u00f3n interanual de -3.9&nbsp;% y sus exportaciones totalizaron US$541.5 millones en el referido mes. La actividad de intermediaci\u00f3n financiera, seguros y actividades conexas experiment\u00f3 un crecimiento interanual de 4.6&nbsp;% reflejando principalmente la expansi\u00f3n de 9.1&nbsp;% del cr\u00e9dito dirigido al sector privado en moneda nacional y extranjera, equivalente a RD$211 mil millones adicionales con respecto a enero del a\u00f1o 2025, as\u00ed como al desempe\u00f1o favorable de los ingresos por primas y comisiones del conglomerado de empresas representado en esta actividad. Finalmente, es importante destacar que el Banco Central de la Rep\u00fablica Dominicana continuar\u00e1 monitoreando el comportamiento de la econom\u00eda, adoptando las acciones necesarias para contribuir a retomar gradualmente la senda de crecimiento en torno al potencial, en la medida que se cuente con los espacios suficientes para hacerlo sin comprometer la estabilidad de precios, que constituye la misi\u00f3n primigenia y compromiso constitucional de la instituci\u00f3n.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-142495","post","type-post","status-publish","format-standard","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/142495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=142495"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/142495\/revisions"}],"predecessor-version":[{"id":142499,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/142495\/revisions\/142499"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=142495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=142495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=142495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}