{"id":143222,"date":"2026-04-14T15:36:03","date_gmt":"2026-04-14T19:36:03","guid":{"rendered":"https:\/\/conexiondigital.com.do\/?p=143222"},"modified":"2026-04-14T15:36:43","modified_gmt":"2026-04-14T19:36:43","slug":"ejercito-detiene-a-28-haitianos-indocumentados-detectados-con-drones-en-dajabon","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2026\/04\/14\/ejercito-detiene-a-28-haitianos-indocumentados-detectados-con-drones-en-dajabon\/","title":{"rendered":"Ej\u00e9rcito detiene a 28 haitianos indocumentados detectados con drones en Dajab\u00f3n"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/04\/e07074be-ac98-4e12-a972-40a48c5732a8-1024x576.jpg\" alt=\"\" class=\"wp-image-143223\" srcset=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/04\/e07074be-ac98-4e12-a972-40a48c5732a8-1024x576.jpg 1024w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/04\/e07074be-ac98-4e12-a972-40a48c5732a8-800x450.jpg 800w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/04\/e07074be-ac98-4e12-a972-40a48c5732a8-768x432.jpg 768w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/04\/e07074be-ac98-4e12-a972-40a48c5732a8-1536x864.jpg 1536w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/04\/e07074be-ac98-4e12-a972-40a48c5732a8.jpg 1599w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Los extranjeros en fueron interceptados por una patrulla del ERD en la zona conocida como Nene Checo.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dajab\u00f3n, R.D. \u2013 Durante una intervenci\u00f3n realizada por el Ej\u00e9rcito de Rep\u00fablica Dominicana (ERD) con el apoyo de unidades de drones y de una patrulla terrestre, fueron detenidos veintiocho (28) nacionales haitianos indocumentados en una operaci\u00f3n realizada en la provincia fronteriza de Dajab\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los miembros del 10mo. Batall\u00f3n de Infanter\u00eda interceptaron a los extranjeros indocumentados en la zona conocida como la finca de Nene Checo; durante una primera intervenci\u00f3n, fueron detenidos diecinueve (19) nacionales haitianos, compuesto por dieciocho (18) hombres y una (1) mujer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Posteriormente, fue interceptado un segundo grupo donde fueron detenidos nueve (9) extranjeros, entre ellos seis (6) hombres, dos (2) mujeres y un (1) menor de edad.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"779\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/04\/bab06438-00c1-4d39-8605-899e6e7a7364-1024x779.jpg\" alt=\"\" class=\"wp-image-143224\" srcset=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/04\/bab06438-00c1-4d39-8605-899e6e7a7364-1024x779.jpg 1024w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/04\/bab06438-00c1-4d39-8605-899e6e7a7364-800x609.jpg 800w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/04\/bab06438-00c1-4d39-8605-899e6e7a7364-768x584.jpg 768w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/04\/bab06438-00c1-4d39-8605-899e6e7a7364-1536x1168.jpg 1536w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/04\/bab06438-00c1-4d39-8605-899e6e7a7364.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Los detenidos fueron trasladados bajo custodia militar y entregados a la Direcci\u00f3n General de Migraci\u00f3n (DGM), para los procesos legales correspondientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Ej\u00e9rcito de Rep\u00fablica Dominicana continuar\u00e1 fortaleciendo las labores de vigilancia y control en la zona fronteriza, en cumplimiento de las leyes y en protecci\u00f3n del territorio nacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los extranjeros en fueron interceptados por una patrulla del ERD en la zona conocida como Nene Checo. Dajab\u00f3n, R.D. \u2013 Durante una intervenci\u00f3n realizada por el Ej\u00e9rcito de Rep\u00fablica Dominicana (ERD) con el apoyo de unidades de drones y de una patrulla terrestre, fueron detenidos veintiocho (28) nacionales haitianos indocumentados en una operaci\u00f3n realizada en la provincia fronteriza de Dajab\u00f3n. Los miembros del 10mo. Batall\u00f3n de Infanter\u00eda interceptaron a los extranjeros indocumentados en la zona conocida como la finca de Nene Checo; durante una primera intervenci\u00f3n, fueron detenidos diecinueve (19) nacionales haitianos, compuesto por dieciocho (18) hombres y una (1) mujer. Posteriormente, fue interceptado un segundo grupo donde fueron detenidos nueve (9) extranjeros, entre ellos seis (6) hombres, dos (2) mujeres y un (1) menor de edad. Los detenidos fueron trasladados bajo custodia militar y entregados a la Direcci\u00f3n General de Migraci\u00f3n (DGM), para los procesos legales correspondientes. El Ej\u00e9rcito de Rep\u00fablica Dominicana continuar\u00e1 fortaleciendo las labores de vigilancia y control en la zona fronteriza, en cumplimiento de las leyes y en protecci\u00f3n del territorio nacional.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-143222","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/143222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=143222"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/143222\/revisions"}],"predecessor-version":[{"id":143225,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/143222\/revisions\/143225"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=143222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=143222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=143222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}